{"id":166350,"date":"2025-11-26T22:16:22","date_gmt":"2025-11-26T22:16:22","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/166350\/"},"modified":"2025-11-26T22:16:22","modified_gmt":"2025-11-26T22:16:22","slug":"comissao-contra-fraude-no-sns-vai-ser-liderada-pelo-juiz-carlos-alexandre","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/166350\/","title":{"rendered":"Comiss\u00e3o contra fraude no SNS vai ser liderada pelo juiz Carlos Alexandre"},"content":{"rendered":"<p>                Segundo o Jornal de Not\u00edcias,<b> Carlos Alexandre vai liderar a nova comiss\u00e3o<\/b>, durante os pr\u00f3ximos tr\u00eas anos, <b>para cortar desperd\u00edcios das despesas em sa\u00fade, peneirar as fraudes e, no fim, garantir uma poupan\u00e7a de at\u00e9 800 milh\u00f5es de euros<\/b>.<br \/>\n          <img decoding=\"async\" itemprop=\"image\" class=\"img-fluid\"   src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2025\/11\/1764195381_985_bg_playeraudio_5.jpg\"\/><\/p>\n<p>Rosa Azevedo &#8211; Antena 1&#13;<\/p>\n<p>&#13;<br \/>\nEsta comiss\u00e3o vai tamb\u00e9m ter <b>elementos da Pol\u00edcia Judici\u00e1ria, da Inspe\u00e7\u00e3o-Geral das Finan\u00e7as e da Inspe\u00e7\u00e3o-Geral das Atividades em Sa\u00fade<\/b>.Caso surjam suspeitas de fraude, desperd\u00edcio de verbas ou falta de efici\u00eancia, estas situa\u00e7\u00f5es podem ser participadas \u00e0 Justi\u00e7a para investiga\u00e7\u00e3o.&#13;<br \/>\n&#13;\n<\/p>\n<p>O  juiz desembargador Carlos Alexandre, neste mandato de tr\u00eas anos, vai ter o vencimento  do presidente do Mecanismo Nacional Anti-corrup\u00e7\u00e3o, <b>correspondente ao sal\u00e1rio bruto de 6.100 euros por m\u00eas<\/b>.<br \/>\nResolu\u00e7\u00e3o entra em vigor na quinta-feira<br \/>&#13;<br \/>\n<br \/>\nNos termos da resolu\u00e7\u00e3o publicada esta quarta-feira, a Comiss\u00e3o de Combate a Fraude no Servi\u00e7o Nacional de Sa\u00fade ser\u00e1 ent\u00e3o presidida por um magistrado e ter\u00e1 elementos permanentes da Pol\u00edcia Judici\u00e1ria, da Inspe\u00e7\u00e3o Geral da Sa\u00fade e das Finan\u00e7as e do Infarmed.<\/p>\n<p><b>A estrutura dever\u00e1 centralizar, coordenar e executar a estrat\u00e9gia de preven\u00e7\u00e3o e dete\u00e7\u00e3o da fraude no \u00e2mbito do SNS, em articula\u00e7\u00e3o e coopera\u00e7\u00e3o com as entidades competentes para apuramento das responsabilidades disciplinar, financeira e criminal<\/b>.Na esfera de compet\u00eancias est\u00e3o a preven\u00e7\u00e3o, dete\u00e7\u00e3o e investiga\u00e7\u00e3o de fraudes relacionadas com atos m\u00e9dicos, receitas, compras, contratos e procedimentos hospitalares.<\/p>\n<p>A CCF-SNS vai tamb\u00e9m <b>estabelecer, a cada ano, as \u00e1reas priorit\u00e1rias de atua\u00e7\u00e3o e o plano de atividades ser\u00e1 aprovado na primeira quinzena de janeiro e levado ao conhecimento dos membros do Governo respons\u00e1veis pelas \u00e1reas da Justi\u00e7a e da Sa\u00fade<\/b>.<\/p>\n<p>O apoio t\u00e9cnico, log\u00edstico, administrativo e or\u00e7amental ser\u00e1 assegurado pela Secretaria-Geral do Minist\u00e9rio da Sa\u00fade, por quem correm igualmente as despesas associadas ao seu funcionamento, incluindo a remunera\u00e7\u00e3o do presidente.<br \/>&#13;\n<\/p>\n<p>&#13;<br \/>\nc\/ Lusa<br \/>&#13;<\/p>\n","protected":false},"excerpt":{"rendered":"Segundo o Jornal de Not\u00edcias, Carlos Alexandre vai liderar a nova comiss\u00e3o, durante os pr\u00f3ximos tr\u00eas anos, para&hellip;\n","protected":false},"author":2,"featured_media":166351,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[27,28,35104,5726,35102,15,16,35103,14,25,26,21,22,12,13,19,20,32,23,24,33,2649,17,18,29,30,31],"class_list":{"0":"post-166350","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-portugal","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-carlos-alexandre","11":"tag-combate","12":"tag-comissao","13":"tag-featured-news","14":"tag-featurednews","15":"tag-fraudes","16":"tag-headlines","17":"tag-latest-news","18":"tag-latestnews","19":"tag-main-news","20":"tag-mainnews","21":"tag-news","22":"tag-noticias","23":"tag-noticias-principais","24":"tag-noticiasprincipais","25":"tag-portugal","26":"tag-principais-noticias","27":"tag-principaisnoticias","28":"tag-pt","29":"tag-sns","30":"tag-top-stories","31":"tag-topstories","32":"tag-ultimas","33":"tag-ultimas-noticias","34":"tag-ultimasnoticias"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/115618315494030125","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/166350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=166350"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/166350\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/166351"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=166350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=166350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=166350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}