{"id":237627,"date":"2026-01-21T03:33:12","date_gmt":"2026-01-21T03:33:12","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/237627\/"},"modified":"2026-01-21T03:33:12","modified_gmt":"2026-01-21T03:33:12","slug":"ana-castela-capota-jetski-durante-passeio-radical-em-balneario-camboriu","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/237627\/","title":{"rendered":"Ana Castela capota jetski durante passeio radical em Balne\u00e1rio Cambori\u00fa"},"content":{"rendered":"\n<p class=\"resumo_item_amdb\">Ana Castela aproveitou um dia de lazer em Balne\u00e1rio Cambori\u00fa, onde fez um passeio de lancha e jetski, mas acabou capotando o ve\u00edculo aqu\u00e1tico durante uma curva, resultando em um mergulho inesperado na \u00e1gua.<\/p>\n<p class=\"resumo_item_amdb\">O incidente foi registrado em um v\u00eddeo compartilhado nas redes sociais, onde Ana se divertiu com a situa\u00e7\u00e3o, enquanto seu amigo expressava frustra\u00e7\u00e3o pela queda, destacando o tom leve da experi\u00eancia.<\/p>\n<p class=\"resumo_item_amdb\">Apesar do susto, a artista e seu amigo mantiveram o bom humor, fazendo piadas sobre a situa\u00e7\u00e3o e prometendo mais aventuras, evidenciando a descontra\u00e7\u00e3o t\u00edpica de suas intera\u00e7\u00f5es p\u00fablicas.<\/p>\n","protected":false},"excerpt":{"rendered":"Ana Castela aproveitou um dia de lazer em Balne\u00e1rio Cambori\u00fa, onde fez um passeio de lancha e jetski,&hellip;\n","protected":false},"author":2,"featured_media":237628,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[145],"tags":[1467,13762,528,37104,8603,45067,211,210,45065,114,115,45070,1015,45068,29848,45066,32,33,5891,3801,45069,578,6498],"class_list":{"0":"post-237627","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-celebridades","8":"tag-agua","9":"tag-ana-castela","10":"tag-artista","11":"tag-balneario-camboriu","12":"tag-brincadeira","13":"tag-capotou","14":"tag-celebridades","15":"tag-celebrities","16":"tag-curva","17":"tag-entertainment","18":"tag-entretenimento","19":"tag-gargalhava","20":"tag-instagram","21":"tag-jetski","22":"tag-lancha","23":"tag-moto-aquatica","24":"tag-portugal","25":"tag-pt","26":"tag-raiva","27":"tag-santa-catarina","28":"tag-veiculo","29":"tag-video","30":"tag-volta"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/115930988725348438","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/237627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=237627"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/237627\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/237628"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=237627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=237627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=237627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}