{"id":240237,"date":"2026-01-22T21:57:17","date_gmt":"2026-01-22T21:57:17","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/240237\/"},"modified":"2026-01-22T21:57:17","modified_gmt":"2026-01-22T21:57:17","slug":"conheca-as-outras-opcoes-em-portugal","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/240237\/","title":{"rendered":"conhe\u00e7a as outras op\u00e7\u00f5es em Portugal"},"content":{"rendered":"<p>Ao DN e Dinheiro Vivo, R\u00faben Germano, Branch Manager da Revolut em Portugal explica que a campanha em quest\u00e3o <strong>permite que a conta poupan\u00e7a seja criada at\u00e9 20 de mar\u00e7o <\/strong>e o pagamento de juros<strong> manter-se-\u00e1 at\u00e9 20 julho<\/strong> (perfazendo seis meses). &#8220;Quanto mais cedo, melhor; come\u00e7a logo a ganhar&#8221;, sublinha.<\/p>\n<p>Por outro lado, <strong>o cliente &#8220;pode, a qualquer momento, retirar o dinheiro&#8221;<\/strong> e, se o fizer durante o per\u00edodo de pagamento de juros, n\u00e3o perde qualquer valor. &#8220;N\u00e3o \u00e9 como uma conta dep\u00f3sito, em que o cliente perde os juros&#8221; caso o fa\u00e7a.<\/p>\n<p>Relativamente aos <strong>juros pagos ao dia<\/strong>, a Revolut j\u00e1 o fazia (com taxas entre 1,50% e 2,25%). Entre os competidores, assinala o respons\u00e1vel, <strong>&#8220;ningu\u00e9m no mercado tem esta componente&#8221;<\/strong>.<\/p>\n<p>Um dos objetivos passa por chegar ao m\u00e1ximo de clientes, pelo que, &#8220;a n\u00edvel de elegibilidade, n\u00e3o pomos quase restri\u00e7\u00f5es nenhumas&#8221;, al\u00e9m de evitar &#8220;letras pequeninas de condi\u00e7\u00f5es e restri\u00e7\u00f5es&#8221;, garante R\u00faben Germano.<\/p>\n","protected":false},"excerpt":{"rendered":"Ao DN e Dinheiro Vivo, R\u00faben Germano, Branch Manager da Revolut em Portugal explica que a campanha em&hellip;\n","protected":false},"author":2,"featured_media":240238,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[475,88,45474,89,90,26711,32,33,1362],"class_list":{"0":"post-240237","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-empresas","8":"tag-banca","9":"tag-business","10":"tag-conta-poupanca","11":"tag-economy","12":"tag-empresas","13":"tag-financas-pessoais","14":"tag-portugal","15":"tag-pt","16":"tag-revolut"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/115940992222773978","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/240237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=240237"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/240237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/240238"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=240237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=240237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=240237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}