{"id":244367,"date":"2026-01-26T00:43:06","date_gmt":"2026-01-26T00:43:06","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/244367\/"},"modified":"2026-01-26T00:43:06","modified_gmt":"2026-01-26T00:43:06","slug":"benedict-wong-diz-que-nao-sabe-onde-esta-wong-no-mcu","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/244367\/","title":{"rendered":"Benedict Wong diz que n\u00e3o sabe onde est\u00e1 Wong no MCU"},"content":{"rendered":"<p class=\"wp-block-yoast-seo-estimated-reading-time yoast-reading-time__wrapper\">Estimated reading time: 2 minutos<\/p>\n<p>Em entrevista com \u00e0 Variety, o ator\u00a0<strong>Benedict Wong<\/strong>\u00a0admitiu que n\u00e3o sabe por onde anda seu personagem,\u00a0<strong>Wong<\/strong>,\u00a0que atua como o Mago Supremo da Terra desde os eventos de Vingadores: Guerra Infinita.<\/p>\n<p>Em resposta ao jornalista, ele disse o seguinte: \u201c<strong>Ele est\u00e1 tirando uma soneca qu\u00e2ntica. Eu realmente n\u00e3o sei o que ele est\u00e1 fazendo\u2026 Mas se eles chamarem&#8230;\u201d<\/strong><\/p>\n<p>Ou seja, apesar de ser o Mago Supremo, tudo indica que Wong n\u00e3o participar\u00e1 do filme <strong>Vingadores: Doutor Destino<\/strong> e isso tamb\u00e9m coloca em d\u00favida sua participa\u00e7\u00e3o em <strong>Vingadores: Guerras Secretas.<\/strong> De todo modo, ficamos no aguardo de novidades.<\/p>\n<p>Leia mais sobre Vingadores:<\/p>\n<p><strong>Vingadores: Doutor Destino<\/strong>\u00a0estreia nos cinemas em\u00a0<strong>17 de dezembro<\/strong>.<\/p>\n<p>Doutor Destino chegou oficialmente ao Universo Cinematogr\u00e1fico Marvel. O vil\u00e3o, um mestre da ci\u00eancia de ponta e da magia poderosa, desencadear\u00e1 uma crise em cascata por todo o multiverso<\/p>\n<p>Fonte: <a href=\"https:\/\/x.com\/cosmic_marvel\/status\/2015519080694919437?s=20\" rel=\"nofollow\">Cosmic Marvel<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Estimated reading time: 2 minutos Em entrevista com \u00e0 Variety, o ator\u00a0Benedict Wong\u00a0admitiu que n\u00e3o sabe por onde&hellip;\n","protected":false},"author":2,"featured_media":244368,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[140],"tags":[21362,114,115,147,148,792,146,32,33,38893,46044],"class_list":{"0":"post-244367","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-filmes","8":"tag-benedict-wong","9":"tag-entertainment","10":"tag-entretenimento","11":"tag-film","12":"tag-filmes","13":"tag-marvel","14":"tag-movies","15":"tag-portugal","16":"tag-pt","17":"tag-vingadores-doutor-destino","18":"tag-wong"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/115958631912248795","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/244367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=244367"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/244367\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/244368"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=244367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=244367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=244367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}