{"id":253439,"date":"2026-02-02T04:24:23","date_gmt":"2026-02-02T04:24:23","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/253439\/"},"modified":"2026-02-02T04:24:23","modified_gmt":"2026-02-02T04:24:23","slug":"f1-porpoising-deixou-de-ser-problema","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/253439\/","title":{"rendered":"F1: Porpoising deixou de ser problema"},"content":{"rendered":"<p>Os dados t\u00e9cnicos, as declara\u00e7\u00f5es oficiais e os primeiros testes em pista apontam para que o fen\u00f3meno do porpoising \u2014 que marcou negativamente a F\u00f3rmula 1 em 2022 \u2014 n\u00e3o volte a ser um problema na gera\u00e7\u00e3o de carros de 2026. A FIA, pilotos e engenheiros concordam que as altera\u00e7\u00f5es estruturais na aerodin\u00e2mica e no piso foram desenhadas precisamente para eliminar a instabilidade vertical que afetou v\u00e1rias equipas no in\u00edcio da atual era regulamentar.<\/p>\n<p>A confian\u00e7a da federa\u00e7\u00e3o baseia-se sobretudo na mudan\u00e7a radical do conceito aerodin\u00e2mico. Entre 2022 e 2025, os carros recorriam a t\u00faneis Venturi profundos no piso para gerar grande parte da carga aerodin\u00e2mica, tornando-os extremamente sens\u00edveis \u00e0 altura ao solo. Em 2026, essa filosofia \u00e9 abandonada: o fundo passa a ser maioritariamente plano entre a dianteira e o difusor, este \u00faltimo significativamente ampliado, com a maior parte da carga a ser produzida pelas superf\u00edcies superiores, o que elimina a necessidade de rodar com uma altura ao solo muito reduzida. <\/p>\n<p>Esta altera\u00e7\u00e3o diminui drasticamente o ciclo que originava o porpoising: aproxima\u00e7\u00e3o ao solo, aumento s\u00fabito de carga, colapso do fluxo aerodin\u00e2mico, perda abrupta de apoio aerodin\u00e2mico e novo ressalto. A FIA reconheceu publicamente que a descida excessiva da altura ideal dos carros em 2022 foi um erro coletivo e afirma ter aprendido com essa experi\u00eancia ao conceber os regulamentos atuais.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"753\" data-lazy-type=\"image\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/02\/hadjar-red-bull-barcelona-1024x753.jpg\" alt=\"\" class=\"lazy lazy-hidden wp-image-741957\"  \/><\/p>\n<p>O diretor de monolugares da FIA, <strong>Nikolas Tombazis<\/strong>, afirmou:<\/p>\n<p>\u201cAcreditamos que \u00e9 muito improv\u00e1vel que existam caracter\u00edsticas semelhantes por causa de um piso muito mais plano. A carga aerodin\u00e2mica j\u00e1 n\u00e3o aumenta de forma t\u00e3o pronunciada quando o carro baixa, o que dever\u00e1 reduzir a probabilidade de porpoising.\u201d<\/p>\n<p>Sobre os erros de 2022, acrescentou:<\/p>\n<p>\u201cO facto de a altura ideal dos carros ter descido tanto foi uma falha nos regulamentos. Foi algo que se tornou \u00f3bvio demasiado perto do in\u00edcio do campeonato. Gostaria de ter feito melhor.\u201d<\/p>\n<p>Os testes em Barcelona refor\u00e7aram essa leitura. Ap\u00f3s mais de tr\u00eas mil voltas acumuladas por todas as equipas, nenhuma relatou epis\u00f3dios de ressalto aerodin\u00e2mico. A Mercedes, uma das mais afetadas no passado, completou mais de 500 voltas com o seu novo monolugar sem sinais do problema, um indicador forte de que a quest\u00e3o foi resolvida de forma estrutural. George Russell destacou isso mesmo:<\/p>\n<p>\u201cAs sensa\u00e7\u00f5es do carro s\u00e3o boas, sem grandes problemas, sem porpoising. \u00c9 uma \u00f3tima not\u00edcia para todos n\u00f3s.\u201d<\/p>\n<p>Apesar disso, a FIA mant\u00e9m prud\u00eancia, lembrando que novos regulamentos podem gerar efeitos secund\u00e1rios inesperados. O foco passa agora para outros desafios de 2026: sistemas de gest\u00e3o de energia muito mais exigentes, aerodin\u00e2mica ativa com asas m\u00f3veis, menor carga em curva e uma adapta\u00e7\u00e3o profunda ao novo equil\u00edbrio entre pot\u00eancia el\u00e9trica e t\u00e9rmica.<\/p>\n","protected":false},"excerpt":{"rendered":"Os dados t\u00e9cnicos, as declara\u00e7\u00f5es oficiais e os primeiros testes em pista apontam para que o fen\u00f3meno do&hellip;\n","protected":false},"author":2,"featured_media":245674,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87],"tags":[135,970,971,47417,32,33,134],"class_list":{"0":"post-253439","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-desporto","8":"tag-desporto","9":"tag-f1","10":"tag-formula-1","11":"tag-porpoising","12":"tag-portugal","13":"tag-pt","14":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/115999136997114321","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/253439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=253439"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/253439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/245674"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=253439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=253439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=253439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}