{"id":259551,"date":"2026-02-06T23:12:07","date_gmt":"2026-02-06T23:12:07","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/259551\/"},"modified":"2026-02-06T23:12:07","modified_gmt":"2026-02-06T23:12:07","slug":"depressao-marta-lisboa-anuncia-encerramento-de-varios-espacos-publicos-durante-o-fim-de-semana","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/259551\/","title":{"rendered":"Depress\u00e3o Marta: Lisboa anuncia encerramento de v\u00e1rios espa\u00e7os p\u00fablicos durante o fim de semana"},"content":{"rendered":"<p>\t                Autarquia emite uma s\u00e9rie de recomenda\u00e7\u00f5es para garantir a prote\u00e7\u00e3o de toda a popula\u00e7\u00e3o<\/p>\n<p style=\"margin-bottom:11px\">A C\u00e2mara Municipal de Lisboa decidiu encerrar v\u00e1rios espa\u00e7os p\u00fablicos durante o fim de semana, antevendo o agravamento do estado do tempo com a chegada da depress\u00e3o Marta, a terceira num curto espa\u00e7o de tempo.<\/p>\n<p>De acordo com as recomenda\u00e7\u00f5es da autarquia liderada por Carlos Moedas, que seguiu as recomenda\u00e7\u00f5es da Prote\u00e7\u00e3o Civil, espa\u00e7os como o Castelo de S\u00e3o Jorge ou a Feira da Ladra v\u00e3o ser encerrados s\u00e1bado e domingo.<\/p>\n<p>S\u00e3o medidas que se juntam \u00e0s anteriormente anunciadas pelo presidente da C\u00e2mara Municipal de Lisboa, que j\u00e1 tinha decretado o encerramento dos jardins municipais.<\/p>\n<p>A autarquia recomenda ainda o cancelamento de todas as atividades desportivas, culturais e associativas, procurando precaver toda a popula\u00e7\u00e3o para um fim de semana que se espera complicado.<\/p>\n<p>&#8220;Para garantir a prote\u00e7\u00e3o de todos, a C\u00e2mara Municipal de Lisboa refor\u00e7a ainda a import\u00e2ncia do cumprimento das seguintes indica\u00e7\u00f5es: evitar desloca\u00e7\u00f5es desnecess\u00e1rias; n\u00e3o circular nem estacionar em zonas potencialmente sujeitas a inunda\u00e7\u00f5es; n\u00e3o circular em zonas ribeirinhas; evitar o estacionamento de ve\u00edculos junto a \u00e1rvores, encostas e declives, sujeitas a deslizes de terra; recolher todos os objetos soltos em varandas, quintais e telhados&#8221;, indica o munic\u00edpio.<\/p>\n<p>As autoridades pedem ainda que sejam seguidas todas as indica\u00e7\u00f5es das autoridades e agentes da Prote\u00e7\u00e3o Civil. Caso necessite de informa\u00e7\u00e3o adicional pode enviar um SMS com o texto &#8220;AvisosLX&#8221; para o n\u00famero 927 944 000.<\/p>\n","protected":false},"excerpt":{"rendered":"Autarquia emite uma s\u00e9rie de recomenda\u00e7\u00f5es para garantir a prote\u00e7\u00e3o de toda a popula\u00e7\u00e3o A C\u00e2mara Municipal de&hellip;\n","protected":false},"author":2,"featured_media":259552,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[609,836,611,27,28,2139,607,608,333,832,604,47984,135,610,476,15,16,301,830,14,603,25,26,797,570,21,22,831,833,8532,62,834,12,13,19,20,835,602,52,32,23,24,33,17,18,29,30,31],"class_list":{"0":"post-259551","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-portugal","8":"tag-alerta","9":"tag-analise","10":"tag-ao-minuto","11":"tag-breaking-news","12":"tag-breakingnews","13":"tag-chuva","14":"tag-cnn","15":"tag-cnn-portugal","16":"tag-comentadores","17":"tag-costa","18":"tag-crime","19":"tag-depressao-marta","20":"tag-desporto","21":"tag-direto","22":"tag-economia","23":"tag-featured-news","24":"tag-featurednews","25":"tag-governo","26":"tag-guerra","27":"tag-headlines","28":"tag-justica","29":"tag-latest-news","30":"tag-latestnews","31":"tag-lisboa","32":"tag-live","33":"tag-main-news","34":"tag-mainnews","35":"tag-mais-vistas","36":"tag-marcelo","37":"tag-mau-tempo","38":"tag-mundo","39":"tag-negocios","40":"tag-news","41":"tag-noticias","42":"tag-noticias-principais","43":"tag-noticiasprincipais","44":"tag-opiniao","45":"tag-pais","46":"tag-politica","47":"tag-portugal","48":"tag-principais-noticias","49":"tag-principaisnoticias","50":"tag-pt","51":"tag-top-stories","52":"tag-topstories","53":"tag-ultimas","54":"tag-ultimas-noticias","55":"tag-ultimasnoticias"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/259551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=259551"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/259551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/259552"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=259551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=259551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=259551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}