{"id":260534,"date":"2026-02-07T16:23:26","date_gmt":"2026-02-07T16:23:26","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/260534\/"},"modified":"2026-02-07T16:23:26","modified_gmt":"2026-02-07T16:23:26","slug":"f1-mercedes-em-apuros-apos-reunioes-com-construtores-de-unidades-motrizes","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/260534\/","title":{"rendered":"F1: Mercedes em apuros ap\u00f3s reuni\u00f5es com construtores de unidades motrizes?"},"content":{"rendered":"<p>O campeonato de 2026 ainda nem sequer come\u00e7ou e j\u00e1 h\u00e1 a primeira \u201cnovela\u201d desta nova era. A Mercedes ter\u00e1 encontrado um truque que lhe poder\u00e1 dar uma vantagem significativa em pista, algo que as restantes construtoras de unidades motrizes est\u00e3o a tentar contrariar. <\/p>\n<p>A lista de mudan\u00e7as, comparativamente \u00e0 era anterior que terminou em 2025, \u00e9 enorme, mas h\u00e1 pontos que t\u00eam despertado maior aten\u00e7\u00e3o. Um deles \u00e9 a redu\u00e7\u00e3o da taxa de compress\u00e3o de cerca de 18:1 para um limite m\u00e1ximo de 16:1. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-lazy-type=\"image\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/02\/honda-f1-motor-2026-1024x683.jpg\" alt=\"\" class=\"lazy lazy-hidden wp-image-741096\"  \/><br \/>\nPress\u00e3o e Taxas de Compress\u00e3o<\/p>\n<p>A taxa de compress\u00e3o \u00e9 a rela\u00e7\u00e3o entre o volume do cilindro quando o pist\u00e3o est\u00e1 no ponto morto inferior e o volume quando o pist\u00e3o est\u00e1 no ponto morto superior, geralmente expressa em forma de raz\u00e3o (por exemplo, 16:1 significa que a mistura ar\/combust\u00edvel \u00e9 comprimida a um volume 16 vezes menor). Quanto maior esta rela\u00e7\u00e3o, mais a mistura \u00e9 comprimida antes da igni\u00e7\u00e3o, o que tende a aumentar a efici\u00eancia t\u00e9rmica e a pot\u00eancia extra\u00edda, embora tamb\u00e9m eleve temperatura e press\u00e3o internas e, portanto, o risco de detona\u00e7\u00e3o e a exig\u00eancia sobre materiais e combust\u00edvel. <\/p>\n<p>A redu\u00e7\u00e3o do r\u00e1cio de compress\u00e3o m\u00e1ximo dos motores t\u00e9rmicos de F\u00f3rmula 1 para 16:1 em 2026 surge como uma op\u00e7\u00e3o deliberada para travar ganhos excessivos de pot\u00eancia no motor de combust\u00e3o e recentrar a performance na componente el\u00e9trica e na efici\u00eancia global do conjunto. Limitando picos de pot\u00eancia e a efici\u00eancia m\u00e1xima alcan\u00e7\u00e1vel por solu\u00e7\u00f5es muito agressivas, valoriza\u2011se ainda mais a gest\u00e3o de energia el\u00e9trica e a aerodin\u00e2mica (incluindo a ativa), j\u00e1 que o motor t\u00e9rmico passa a ter menor margem para ganhos significativos apenas pela combust\u00e3o.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">Shakedown: Debriefed \u2705 <\/p>\n<p>Bringing our Lauda Drive team together for the first time in 2026 to look back on Barcelona, and continue preparations for the season ahead \ud83d\udcaa <a href=\"https:\/\/t.co\/ZlXlqDFvh3\" rel=\"nofollow\">pic.twitter.com\/ZlXlqDFvh3<\/a><\/p>\n<p>\u2014 Mercedes-AMG PETRONAS F1 Team (@MercedesAMGF1) <a href=\"https:\/\/twitter.com\/MercedesAMGF1\/status\/2019015919314542817?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">February 4, 2026<\/a><\/p>\n<\/blockquote>\n<p>O truque que a Mercedes ter\u00e1 encontrado<\/p>\n<p>A pol\u00e9mica centra\u2011se no facto de os regulamentos determinarem que o r\u00e1cio de compress\u00e3o \u00e9 verificado \u00e0 temperatura ambiente, existindo suspeitas de que a Mercedes poder\u00e1 operar a valores efetivos superiores quando os motores est\u00e3o quentes. Os engenheiros de Brixworth ter\u00e3o encontrado uma solu\u00e7\u00e3o que permite estar conforme o exigido nos regulamentos \u00e0 temperatura de teste, mas aumentar a taxa de compress\u00e3o a temperaturas mais elevadas, provavelmente recorrendo a uma combina\u00e7\u00e3o espec\u00edfica de desenho de c\u00e2mara de combust\u00e3o e materiais que alteram ligeiramente o volume efetivo em funcionamento. <\/p>\n<p>Confrontadas com este cen\u00e1rio, as restantes construtoras de motores mostraram\u2011se contra, com alguns respons\u00e1veis a exigirem mudan\u00e7as, nomeadamente no m\u00e9todo de medi\u00e7\u00e3o da taxa de compress\u00e3o (as construtoras unidas pretende que a medi\u00e7\u00e3o seja feita com o motor quente). Reuni\u00f5es recentes com a FIA envolveram especialistas t\u00e9cnicos e grupos de trabalho dedicados \u00e0s unidades motrizes, mas, apesar dos rumores, n\u00e3o resultaram em altera\u00e7\u00f5es imediatas \u00e0s regras. Ainda assim, fabricantes como Ferrari, Audi e Honda, que j\u00e1 tinham manifestado preocupa\u00e7\u00f5es formais, ter\u00e3o conquistado tamb\u00e9m o apoio da Red Bull.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" data-lazy-type=\"image\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/02\/motor-mercedes.jpg\" alt=\"\" class=\"lazy lazy-hidden wp-image-742829\"\/><br \/>\nQuatro fabricantes unidos<\/p>\n<p>Aparentemente, a Red Bull ter\u00e1 tamb\u00e9m explorado a possibilidade de aumentar a taxa de compress\u00e3o usando um conceito semelhante ao suposto truque da Mercedes, mas, n\u00e3o encontrando um caminho suficientemente promissor, parece agora alinhar\u2011se com a Audi, a Honda e a Ferrari. Com quatro fabricantes potencialmente alinhados, existiria base para alcan\u00e7ar a maioria qualificada exigida para uma mudan\u00e7a imediata \u2014 desde que a FIA e a FOM concordem. Por\u00e9m, tudo indica que a FIA continua a defender a interpreta\u00e7\u00e3o atual. Al\u00e9m disso, o calend\u00e1rio joga contra uma revis\u00e3o r\u00e1pida: com a homologa\u00e7\u00e3o final das unidades motrizes prevista para o in\u00edcio de mar\u00e7o, seria extremamente dif\u00edcil alterar projetos de raiz antes da primeira corrida. Assim, mesmo que haja consenso pol\u00edtico, uma eventual revis\u00e3o s\u00f3 dever\u00e1 entrar em vigor mais tarde, possivelmente em 2027.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">The new F1 season is calling \ud83d\udcde<a href=\"https:\/\/twitter.com\/hashtag\/F1?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#F1<\/a> || <a href=\"https:\/\/twitter.com\/hashtag\/RedBullRacing?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#RedBullRacing<\/a> <a href=\"https:\/\/t.co\/vNGjA9ogvO\" rel=\"nofollow\">pic.twitter.com\/vNGjA9ogvO<\/a><\/p>\n<p>\u2014 Oracle Red Bull Racing (@redbullracing) <a href=\"https:\/\/twitter.com\/redbullracing\/status\/2016866624519680464?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">January 29, 2026<\/a><\/p>\n<\/blockquote>\n<p>Mercedes defende-se <\/p>\n<p><a href=\"https:\/\/www.autosport.pt\/formula1\/f1\/f1-toto-wolff-a-nossa-unidade-motriz-e-legal\/\" rel=\"nofollow noopener\" target=\"_blank\">A Mercedes tem defendido a sua posi\u00e7\u00e3o veementemente, com Toto Wolff a assumir o papel de principal porta\u2011voz da equipa, acusando as outras estruturas de se reunirem em segredo para tentar condicionar a legalidade da sua unidade motriz. <\/a>O respons\u00e1vel da equipa alem\u00e3 sublinha que todo o processo de desenvolvimento foi feito \u00e0 luz dos regulamentos da FIA e que a Mercedes entrou em contacto com o \u00f3rg\u00e3o federativo para esclarecer antecipadamente a legalidade da sua filosofia de unidade motriz, recebendo garantias de conformidade. Ola K\u00e4llenius,  presidente do Conselho de Administra\u00e7\u00e3o da Daimler AG e chefe da Mercedes-Benz, j\u00e1 admitiu que a Mercedes poder\u00e1 levar o caso at\u00e9 \u00e0s \u00faltimas consequ\u00eancias, com a amea\u00e7a de processo judiciais a pairar. <\/p>\n<p>Assim, de um lado est\u00e1 a Mercedes a tentar defender\u2011se praticamente sozinha de um ataque que agora conta com as restantes quatro fabricantes de unidades motrizes; do outro, uma FIA que, em conjunto com a FOM, ter\u00e1 de decidir se mant\u00e9m a interpreta\u00e7\u00e3o atual ou se avan\u00e7a para altera\u00e7\u00f5es de curto prazo \u2014 algo pouco plaus\u00edvel, dada a proximidade da data final de homologa\u00e7\u00e3o dos motores.<\/p>\n<p>Fotos: Mercedes e Honda<\/p>\n<p>\t\t\t<script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"O campeonato de 2026 ainda nem sequer come\u00e7ou e j\u00e1 h\u00e1 a primeira \u201cnovela\u201d desta nova era. A&hellip;\n","protected":false},"author":2,"featured_media":260535,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87],"tags":[135,1162,970,971,4459,718,1163,32,33,134,48275],"class_list":{"0":"post-260534","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-desporto","8":"tag-desporto","9":"tag-destaque-homepage","10":"tag-f1","11":"tag-formula-1","12":"tag-mercedes","13":"tag-newsletter","14":"tag-newsletter-destaque","15":"tag-portugal","16":"tag-pt","17":"tag-sports","18":"tag-unidades-motrizes"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116030275938652180","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/260534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=260534"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/260534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/260535"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=260534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=260534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=260534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}