{"id":268502,"date":"2026-02-13T16:41:05","date_gmt":"2026-02-13T16:41:05","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/268502\/"},"modified":"2026-02-13T16:41:05","modified_gmt":"2026-02-13T16:41:05","slug":"marcelo-escolheu-vhils-para-fazer-o-seu-retrato-oficial-como-presidente-da-republica-museu-da-presidencia-da-republica","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/268502\/","title":{"rendered":"Marcelo escolheu Vhils para fazer o seu retrato oficial como Presidente da Rep\u00fablica | Museu da Presid\u00eancia da Rep\u00fablica"},"content":{"rendered":"<p><a href=\"https:\/\/www.publico.pt\/marcelo-rebelo-de-sousa\" rel=\"nofollow noopener\" target=\"_blank\">Marcelo Rebelo de Sousa<\/a> escolheu o artista Vhils, conhecido pelos rostos esculpidos em paredes, para fazer o seu retrato oficial como Presidente da Rep\u00fablica, noticiou o Expresso e confirmou esta sexta-feira o pr\u00f3prio \u00e0 Lusa.<\/p>\n<p>O retrato da autoria de Alexandre Farto, que assina como <a href=\"https:\/\/www.publico.pt\/autor\/vhils\" rel=\"nofollow noopener\" target=\"_blank\">Vhils<\/a>, ser\u00e1 apresentado em Mar\u00e7o, na \u00faltima semana do mandato do chefe de Estado, que termina no dia 9 desse m\u00eas.<\/p>\n<p>O Presidente da Rep\u00fablica referiu \u00e0 Lusa que &#8220;a raz\u00e3o principal&#8221; para esta op\u00e7\u00e3o foi, al\u00e9m de gostar das obras de Vhils, &#8220;o considerar um expoente, um s\u00edmbolo de uma \u00e9poca, como foram outros retratistas de outros presidentes noutras \u00e9pocas&#8221;.<\/p>\n<p>        &#13;<\/p>\n<p>&#13;<br \/>\n                &#13;\n            <\/p>\n<p>&#13;<\/p>\n<p>O retrato de Marcelo Rebelo de Sousa feito por Vhils ficar\u00e1 no Museu da Presid\u00eancia da Rep\u00fablica na galeria onde est\u00e3o os retratos oficiais dos seus antecessores.<\/p>\n<p>O retrato de Ant\u00f3nio Ramalho Eanes \u00e9 da autoria de Lu\u00eds Pinto Coelho, o de M\u00e1rio Soares foi feito por J\u00falio Pomar, o de Jorge Sampaio foi pintado por Paula Rego e o de An\u00edbal Cavaco Silva \u00e9 de <a href=\"https:\/\/www.publico.pt\/2016\/03\/05\/culturaipsilon\/noticia\/barahona-possolo-do-erotismo-na-antiguidade-ao-retrato-de-cavaco-1725316\" rel=\"nofollow noopener\" target=\"_blank\">Carlos Barahona Possolo<\/a>.<\/p>\n<p>        &#13;<\/p>\n<p>&#13;<br \/>\n                &#13;\n            <\/p>\n<p>&#13;<\/p>\n<p>Logo no in\u00edcio do seu primeiro mandato, Marcelo Rebelo de Sousa viu <a href=\"https:\/\/www.publico.pt\/2017\/06\/17\/culturaipsilon\/noticia\/o-artista-anonimo-que-pintou-o-retrato-oficial-de-marcelo-em-troca-de-um-abraco-1775907\" rel=\"nofollow noopener\" target=\"_blank\">um retrato pintado pelo mestre Bessa<\/a>, no Porto, que chegou a pensar escolher para seu retrato oficial.<\/p>\n<p>Tornou-se tradi\u00e7\u00e3o os presidentes da Rep\u00fablica apresentarem os seus retratos oficiais apenas no fim do segundo mandato. O de Cavaco Silva foi divulgado em 4 de Mar\u00e7o de 2016, cinco dias antes de cessar fun\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"Marcelo Rebelo de Sousa escolheu o artista Vhils, conhecido pelos rostos esculpidos em paredes, para fazer o seu&hellip;\n","protected":false},"author":2,"featured_media":268503,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[1753,1413,114,115,588,49532,32,14937,1963,33,49533],"class_list":{"0":"post-268502","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-entretenimento","8":"tag-artes","9":"tag-cultura-ipsilon","10":"tag-entertainment","11":"tag-entretenimento","12":"tag-marcelo-rebelo-de-sousa","13":"tag-museu-da-presidencia-da-republica","14":"tag-portugal","15":"tag-presidencia-da-republica","16":"tag-presidente-da-republica","17":"tag-pt","18":"tag-vhils"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116064320485794398","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/268502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=268502"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/268502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/268503"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=268502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=268502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=268502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}