{"id":269101,"date":"2026-02-14T03:12:11","date_gmt":"2026-02-14T03:12:11","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/269101\/"},"modified":"2026-02-14T03:12:11","modified_gmt":"2026-02-14T03:12:11","slug":"a-reflexao-de-josh-freese-sobre-sua-passagem-pelo-foo-fighters","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/269101\/","title":{"rendered":"A reflex\u00e3o de Josh Freese sobre sua passagem pelo Foo Fighters"},"content":{"rendered":"\n<p>Desde que foi demitido do <strong>Foo Fighters<\/strong> em maio do ano passado, <strong>Josh Freese<\/strong> n\u00e3o comentou os motivos da sa\u00edda. Na ocasi\u00e3o, o baterista limitou-se a publicar nas redes sociais que recebeu a not\u00edcia por telefone e que \u201cnenhuma raz\u00e3o foi dada\u201d.<\/p>\n<p>Por\u00e9m, agora, o m\u00fasico resolveu refletir a respeito da situa\u00e7\u00e3o. E confessou que tem teorias quanto \u00e0 decis\u00e3o tomada por <strong>Dave Grohl<\/strong> e companhia.\u00a0<\/p>\n<p>&#8211; Advertisement &#8211;<\/p>\n<p>Durante entrevista \u00e0 revista Modern Drummer, o integrante do Nine Inch Nails, primeiramente, deixou claro que tomaria cuidado com as palavras devido \u00e0 prov\u00e1vel repercuss\u00e3o. Conforme transcri\u00e7\u00e3o da <a href=\"https:\/\/blabbermouth.net\/news\/josh-freese-reflects-on-his-time-with-foo-fighters-they-were-good-to-me-until-they-werent\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Blabbermouth<\/a>, o baterista pontuou:<\/p>\n<p>\u201cO Foo Fighters \u00e9 uma banda t\u00e3o grande e mainstream que tudo o que eu digo acaba sendo tirado de contexto, republicado e exagerado. Criaram manchetes a partir de um coment\u00e1rio r\u00e1pido e simples que fiz em um podcast n\u00e3o muito tempo atr\u00e1s. \u00c9 loucura. Preciso ter cuidado com o que falo sobre isso.\u201d<\/p>\n<p>Em seguida, Freese revelou que n\u00e3o pode entrar em detalhes, mas que est\u00e1 \u201ctentando entender como e quando articular tudo de forma adequada\u201d. Ainda, que tinha uma \u00f3tima conviv\u00eancia com os integrantes do FF, at\u00e9 que tudo pareceu desandar:\u00a0<\/p>\n<p>\u201cMas tenho muito a dizer e estou apenas tentando entender como e quando articular tudo de forma adequada. Tenho algumas pequenas teorias [sobre o motivo de ter sido demitido], mas n\u00e3o posso realmente entrar em detalhes agora. Ainda assim, gostei muito dos dois anos que passei com aqueles caras, e eles foram bons comigo\u2026 at\u00e9 deixarem de ser [\u2026]. Eu gostava de estar com aqueles caras, eles eram generosos comigo e \u00e9 isso que torna tudo ainda mais um mist\u00e9rio. Acho que tenho uma boa leitura das pessoas, mas n\u00e3o vi esse movimento acontecendo. Num dia era s\u00f3 risada, est\u00e1vamos no palco e o Dave olhava para mim todas as noites como quem diz \u2018voc\u00ea est\u00e1 mandando muito bem, cara\u2019 e ent\u00e3o simplesmente acabou.\u201d<\/p>\n<p> Elogios a Dave Grohl <\/p>\n<p>O m\u00fasico tamb\u00e9m aproveitou a oportunidade para exaltar o l\u00edder do Foo Fighters. Pelo fato do vocalista e guitarrista tamb\u00e9m ser um baterista, Fresse acredita que os dois conseguiram estabelecer uma conex\u00e3o:<\/p>\n<p>\u201cAdorei ter o Dave Grohl como l\u00edder da banda. Eu o respeito profundamente, como baterista. Para mim, ele \u00e9 baterista em primeiro lugar e todo o resto vem depois. J\u00e1 o ouvi em todos os grandes discos nos quais tocou bateria muito mais do que ouvi material do Foo Fighters. Foi realmente incr\u00edvel estar em uma banda cujo l\u00edder \u00e9 um baterista fenomenal que voc\u00ea respeita. Isso \u00e9 muito divertido. N\u00f3s basicamente viemos da mesma \u00e9poca tamb\u00e9m, ent\u00e3o consegu\u00edamos nos identificar um com o outro.\u201d<\/p>\n<p>Por fim, o instrumentista ressaltou que, apesar de todo cen\u00e1rio relatado, est\u00e1 em um \u00f3timo momento profissional:<\/p>\n<p>\u201cO fato \u00e9 que voltei a fazer turn\u00ea com o Nine Inch Nails e o A Perfect Circle, toquei em alguns shows com o Weezer e trabalhei em est\u00fadio com gente que vai de Danny Elfman a Billy Idol. Sinto que estou de volta ao meu lugar. Acredite, ningu\u00e9m deveria sentir pena de mim.\u201d<\/p>\n<p> Josh Freese e Foo Fighters <\/p>\n<p>Nos \u00faltimos meses, Josh Freese vem trazendo mais declara\u00e7\u00f5es sobre a demiss\u00e3o do Foo Fighters. Primeiro, em agosto, numa entrevista ao <a href=\"https:\/\/www.nytimes.com\/2025\/08\/27\/arts\/music\/josh-freese-drummer.html\" rel=\"nofollow noopener\" target=\"_blank\">New York Times<\/a>, o m\u00fasico admitiu que n\u00e3o era um grande f\u00e3 da m\u00fasica tocada por Dave Grohl e companhia, afirmando:\u00a0<\/p>\n<p>\u201cEntrei para a banda como o baterista do Dave Grohl e como o cara que supostamente salvaria o dia depois da morte do querido Taylor Hawkins. [Assumir o lugar do Taylor] Foi como se tivesse que estar funcionando a todo vapor o tempo todo. Olhando para tr\u00e1s, provavelmente [a demiss\u00e3o] era mais uma quest\u00e3o da gest\u00e3o da banda. N\u00e3o era uma m\u00fasica com a qual eu realmente me identificasse.\u201d<\/p>\n<p>Ent\u00e3o, em dezembro, ao programa Trunk Nation With Eddie Trunk, o m\u00fasico mencionou o fato de quem tem teorias a respeito do desligamento. Por\u00e9m, como transcrito pela <a href=\"https:\/\/blabbermouth.net\/news\/josh-freese-has-a-couple-of-theories-as-to-why-he-was-fired-from-foo-fighters\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Blabbermouth<\/a>, n\u00e3o quis entrar no assunto pelo seguinte motivo:\u00a0<\/p>\n<p>\u201cTenho algumas teorias, mas sinto que as pessoas est\u00e3o t\u00e3o interessadas nisso, por se tratar de uma banda t\u00e3o gigantesca, que fico meio hesitante em comentar qualquer coisa por enquanto, porque tudo o que eu disser vai ser usado, distorcido, republicado e repostado. Mas, sim, eu adorei o tempo que passei com eles. Tive dois anos incr\u00edveis ao lado daqueles caras.\u201d<\/p>\n<p><strong>Clique<\/strong> para seguir IgorMiranda.com.br no: <a href=\"https:\/\/instagram.com\/igormirandasite\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Instagram<\/a> | <a href=\"https:\/\/bsky.app\/profile\/igormirandasite.bsky.social\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Bluesky<\/a> | <a href=\"https:\/\/twitter.com\/igormirandasite\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Twitter<\/a> | <a href=\"https:\/\/tiktok.com\/@igormirandasite\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">TikTok<\/a> | <a href=\"https:\/\/facebook.com\/igormirandasite\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Facebook<\/a> | <a href=\"https:\/\/www.youtube.com\/igormirandasite\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">YouTube<\/a> | <a href=\"https:\/\/www.threads.net\/@igormirandasite\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Threads<\/a>.<\/p>\n<p> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><script async src=\"\/\/www.tiktok.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"Desde que foi demitido do Foo Fighters em maio do ano passado, Josh Freese n\u00e3o comentou os motivos&hellip;\n","protected":false},"author":2,"featured_media":269102,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[141],"tags":[114,115,14484,14485,149,150,32,33],"class_list":{"0":"post-269101","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-musica","8":"tag-entertainment","9":"tag-entretenimento","10":"tag-foo-fighters","11":"tag-josh-freese","12":"tag-music","13":"tag-musica","14":"tag-portugal","15":"tag-pt"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116066801573356015","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/269101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=269101"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/269101\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/269102"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=269101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=269101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=269101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}