{"id":284249,"date":"2026-02-26T02:53:11","date_gmt":"2026-02-26T02:53:11","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/284249\/"},"modified":"2026-02-26T02:53:11","modified_gmt":"2026-02-26T02:53:11","slug":"influenciadora-revela-detalhes-da-mansao-de-r-50-milhoes-que-vive-com-jogador","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/284249\/","title":{"rendered":"Influenciadora revela detalhes da mans\u00e3o de R$ 50 milh\u00f5es que vive com jogador"},"content":{"rendered":"<p>A influenciadora digital <a href=\"https:\/\/caras.com.br\/tags\/bruna-biancardi\" rel=\"nofollow noopener\" target=\"_blank\"><strong>Bruna Biancardi<\/strong><\/a> surpreendeu seus seguidores nesta semana. A esposa de <strong><a href=\"https:\/\/caras.com.br\/tags\/neymar\" rel=\"nofollow noopener\" target=\"_blank\">Neymar<\/a><\/strong> revelou detalhes da casa milion\u00e1ria em que vive ao lado do companheiro. O assunto surgiu por acaso, ao compartilhar um vlog com os melhores momentos da fam\u00edlia no m\u00eas de fevereiro.<\/p>\n<p>Um dos registros compartilhados exibia a festa surpresa que Bruna preparou ao atleta, a fim de comemorar a chegada de seus 34 anos. A aten\u00e7\u00e3o dos f\u00e3s foi voltada \u00e0 enorme garagem na casa do casal, localizada em Santos. Outros c\u00f4modos, como closet e piscina, tamb\u00e9m viralizaram nas redes.<\/p>\n<p> Os detalhes da mans\u00e3o milion\u00e1ria <\/p>\n<p>A resid\u00eancia do casal fica localizada em um condom\u00ednio de luxo no morro Santa Terezinha, no topo de um planalto em Santos, litoral de S\u00e3o Paulo. O terreno mede cerca de 2500 a 3000 metros quadrados e uma garagem enorme, com capacidade para mais de 20 carros.<\/p>\n<p>Em 2021, o atleta revelou ao Gshow que comprou duas casas do empres\u00e1rio do ramo imobili\u00e1rio <strong>Luiz Moura,<\/strong> em um dos melhores condom\u00ednios da Baixada Santista. O im\u00f3vel foi vendido por mais de R$ 50 milh\u00f5es, \u00e0 vista.<\/p>\n<p>De acordo com o antigo propriet\u00e1rio, as duas casas juntas possuem tr\u00eas andares, com subsolo e terra\u00e7o, al\u00e9m de 10 quartos com su\u00edte e tr\u00eas lavabos. A mans\u00e3o tamb\u00e9m conta com brinquedoteca, piscina de borda infinita, uma adega gigante, sala de cinema para oito pessoas, uma academia bem equipada e spa, al\u00e9m de escrit\u00f3rios e uma cozinha integrada com a sala de cinema.<\/p>\n<p>Vale ressaltar que, al\u00e9m do casal de famosos, as pequenas <strong>Mavie<\/strong> (2) e <strong>Mel<\/strong>, de 7 meses, tamb\u00e9m residem no im\u00f3vel de luxo.<\/p>\n<p> Confira <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1079100 img-fluid lazy\" alt=\"Mans\u00e3o de Neymar e Bruna Biancardi - Foto: Reprodu\u00e7\u00e3o\/YouTube \" width=\"1920\" height=\"1080\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/02\/casa-bruna-biancardi-neymar.jpg\"  \/>Mans\u00e3o de Neymar e Bruna Biancardi \u2013 Foto: Reprodu\u00e7\u00e3o\/YouTube <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1079102 img-fluid lazy\" alt=\"Mans\u00e3o de Neymar e Bruna Biancardi - Foto: Reprodu\u00e7\u00e3o\/YouTube \" width=\"1920\" height=\"1080\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/02\/casa-bruna-biancardi-neymar1.jpg\"  \/>Mans\u00e3o de Neymar e Bruna Biancardi \u2013 Foto: Reprodu\u00e7\u00e3o\/YouTube <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1079105 img-fluid lazy\" alt=\"Mans\u00e3o de Neymar e Bruna Biancardi - Foto: Reprodu\u00e7\u00e3o\/YouTube \" width=\"1920\" height=\"1080\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/02\/casa-bruna-biancardi-neymar3.jpg\"  \/>Mans\u00e3o de Neymar e Bruna Biancardi \u2013 Foto: Reprodu\u00e7\u00e3o\/YouTube  <\/p>\n<p><strong>Leia tamb\u00e9m:\u00a0<\/strong><a href=\"https:\/\/caras.com.br\/kids\/bruna-biancardi-encanta-ao-mostrar-mavie-orando-ela-agradeceu.phtml\" rel=\"nofollow noopener\" target=\"_blank\">Bruna Biancardi encanta ao mostrar Mavie orando: \u2018Ela agradeceu\u2019<\/a><\/p>\n<p>        <a href=\"https:\/\/caras.com.br\/autor\/giovanna-f-campos\" rel=\"nofollow noopener\" target=\"_blank\">&#13;<br \/>\n          <img loading=\"lazy\" decoding=\"async\" alt=\"Giovanna F Campos\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2025\/09\/525986578_1657136028311574_5510063872310493577_n-150x150.jpg\" class=\"avatar avatar-115 photo rounded-circle\" height=\"115\" width=\"115\"\/>        <\/a><\/p>\n<p>Giovanna F Campos \u00e9 estudante de jornalismo pela Faculdade C\u00e1sper L\u00edbero, apaixonada por entretenimento e literatura.<\/p>\n","protected":false},"excerpt":{"rendered":"A influenciadora digital Bruna Biancardi surpreendeu seus seguidores nesta semana. A esposa de Neymar revelou detalhes da casa&hellip;\n","protected":false},"author":2,"featured_media":284250,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[145],"tags":[4290,211,210,114,115,1874,38123,1996,32,33],"class_list":{"0":"post-284249","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-celebridades","8":"tag-bruna-biancardi","9":"tag-celebridades","10":"tag-celebrities","11":"tag-entertainment","12":"tag-entretenimento","13":"tag-mansao","14":"tag-milionario","15":"tag-neymar","16":"tag-portugal","17":"tag-pt"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116134674662183717","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/284249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=284249"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/284249\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/284250"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=284249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=284249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=284249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}