{"id":293814,"date":"2026-03-06T11:55:10","date_gmt":"2026-03-06T11:55:10","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/293814\/"},"modified":"2026-03-06T11:55:10","modified_gmt":"2026-03-06T11:55:10","slug":"ja-fazem-planos-a-sos-soraia-sousa-lanca-convite-a-instrutor-joaquim-data-hora-secret-story","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/293814\/","title":{"rendered":"J\u00e1 fazem planos a s\u00f3s? Soraia Sousa lan\u00e7a convite a instrutor Joaquim \u00abData, hora!\u00bb &#8211; Secret Story"},"content":{"rendered":"<p data-end=\"290\" data-start=\"0\">A atriz <strong data-end=\"24\" data-start=\"8\">Soraia Sousa<\/strong> recordou nas redes sociais um momento marcante que viveu recentemente e que descreveu como uma verdadeira supera\u00e7\u00e3o pessoal. Esta quarta-feira, 4 de setembro, partilhou no Instagram v\u00e1rias imagens dessa experi\u00eancia, que incluiu a sua primeira tentativa de escalada.<\/p>\n<p data-end=\"509\" data-start=\"292\">Na legenda da publica\u00e7\u00e3o, a participante da\u00a0<strong data-end=\"355\" data-start=\"336\">1.\u00aa Companhia<\/strong>, reality show da TVI, falou do orgulho em ter conseguido ultrapassar o medo das alturas e deixou um agradecimento especial aos instrutores do programa.<\/p>\n<p data-end=\"759\" data-start=\"511\">\u00abA felicidade de quem j\u00e1 controla o medo de alturas e experimentou escalada pela primeira vez\u00bb, escreveu, dirigindo-se diretamente a <strong data-end=\"709\" data-start=\"644\">Rodrigo Joaquim, Paulo Andrade, Bruno Marques e Jo\u00e3o Moutinho<\/strong>, a quem agradeceu pelo apoio ao longo do desafio.<\/p>\n<p data-end=\"981\" data-start=\"761\">A publica\u00e7\u00e3o n\u00e3o passou despercebida a <strong data-end=\"819\" data-start=\"800\">Rodrigo Joaquim<\/strong>, instrutor do formato, que reagiu nos coment\u00e1rios com uma mensagem bem-humorada: \u201cTudo se paga! Pr\u00f3ximo n\u00edvel: o c\u00e9u n\u00e3o \u00e9 o limite, \u00e9 o ponto de partida\u201d.<\/p>\n<p data-end=\"1210\" data-start=\"983\">Soraia Sousa entrou na brincadeira e respondeu de imediato, lan\u00e7ando um novo desafio: \u201cJ\u00e1 disse que quero o salto! Data, hora!\u201d. A resposta de Rodrigo Joaquim tamb\u00e9m n\u00e3o tardou: \u201cCalma! Antes, tens de passar nos psicot\u00e9cnicos\u201d.<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/DVec3kFDJ7B\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<\/blockquote>\n<p data-end=\"1497\" data-start=\"1212\">Tamb\u00e9m <strong data-end=\"1236\" data-start=\"1219\">Bruno Marques<\/strong> deixou palavras de reconhecimento \u00e0 atriz, elogiando a forma como encarou a experi\u00eancia: \u201cCamarada, amiga Soraia\u2026 J\u00e1 n\u00e3o me deves nada. Tudo j\u00e1 foi pago, sem tu saberes, com toda a tua entrega, o esp\u00edrito de corpo e a dedica\u00e7\u00e3o com que te lan\u00e7aste ao desafio\u201d.<\/p>\n<p data-end=\"1682\" data-is-last-node=\"\" data-is-only-node=\"\" data-start=\"1499\">J\u00e1 <strong data-end=\"1519\" data-start=\"1502\">Paulo Andrade<\/strong> optou por uma rea\u00e7\u00e3o mais descontra\u00edda, brincando com a destreza demonstrada por Soraia Sousa na escalada: \u201cUma aut\u00eantica osga\u2026 E a sorrir, de certeza\u2026 Beijinho\u201d.<\/p>\n<p>                        <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"A atriz Soraia Sousa recordou nas redes sociais um momento marcante que viveu recentemente e que descreveu como&hellip;\n","protected":false},"author":2,"featured_media":284053,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142],"tags":[18706,114,115,18705,17411,32,33,14291,151,18704],"class_list":{"0":"post-293814","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-bastidores-secret-story","9":"tag-entertainment","10":"tag-entretenimento","11":"tag-entrevistas-concorrentes-tvi","12":"tag-joaquim","13":"tag-portugal","14":"tag-pt","15":"tag-soraia-sousa","16":"tag-tv","17":"tag-vida-fora-da-casa"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116182104770668577","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/293814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=293814"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/293814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/284053"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=293814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=293814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=293814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}