{"id":296782,"date":"2026-03-08T18:24:22","date_gmt":"2026-03-08T18:24:22","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/296782\/"},"modified":"2026-03-08T18:24:22","modified_gmt":"2026-03-08T18:24:22","slug":"penso-que-o-arbitro-tem-de-ajudar-e-nao-complicar","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/296782\/","title":{"rendered":"\u00abPenso que o \u00e1rbitro tem de ajudar e n\u00e3o complicar\u00bb"},"content":{"rendered":"<p>&#8211; Advertisement &#8211;<\/p>\n<p><strong>Na passada sexta-feira, o Al Ittihad foi derrotado por 3-1 na visita ao Al Ahli. S\u00e9rgio Concei\u00e7\u00e3o criticou a arbitragem e refletiu sobre o nervosismo num d\u00e9rbi.<\/strong><\/p>\n<p>O Al Ittihad n\u00e3o foi capaz de bater o Al Ahly na passada sexta-feira, acabando por ser <a href=\"https:\/\/bolanarede.pt\/especial-bola-na-rede\/atualidade\/al-ahli-derrota-al-ittihad-de-sergio-conceicao-e-assume-lideranca-provisoria-da-liga-saudita\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">derrotado por 3-1 no d\u00e9rbi da 25.\u00aa jornada da Liga Saudita<\/a>. Ap\u00f3s a partida, S\u00e9rgio Concei\u00e7\u00e3o reagiu ao resultado, come\u00e7ando por resumir o jogo com uma cr\u00edtica \u00e0 arbitragem:<\/p>\n<p>\u00abFoi um jogo competitivo entre duas boas equipas, que foi decidido por situa\u00e7\u00f5es individuais. Na primeira parte, quando foram \u00e0 baliza fizeram o golo, n\u00f3s tivemos uma bola no poste, um jogo dividido. Na segunda parte conseguimos empatar, houve ali mais alguns momentos em que o Ahli levou o jogo para a bola mais direta, muitas quez\u00edlias, muitas faltas, e penso que o \u00e1rbitro tem de ajudar e n\u00e3o complicar. Sinceramente, sofremos o segundo golo quando est\u00e1vamos melhor no jogo, depois do 2-1 a equipa advers\u00e1ria andava a queimar tempo porque percebeu a nossa supremacia no jogo. O 3-1 \u00e9 um erro individual e acabou o jogo a\u00ed, praticamente\u00bb.<\/p>\n<p>De seguida, o t\u00e9cnico portugu\u00eas destacou alguma arestas por limar na sua equipa:<\/p>\n<p>\u00abO advers\u00e1rio estica constantemente o jogo, faz direto e aposta nas segundas bolas, t\u00eam jogadores na frente que s\u00e3o r\u00e1pidos e fortes fisicamente, e n\u00f3s se fossemos buscar o advers\u00e1rio muito altos ir\u00edamos sofrer depois na segunda bola. Eu acho que nesse sentido houve momentos em que estivemos bem e outros em que n\u00e3o estivemos t\u00e3o bem, e j\u00e1 houve jogos em que estivemos melhor\u00bb<\/p>\n<p>Por fim, abordou o poss\u00edvel nervosismo de alguns jogadores por se tratar de um d\u00e9rbi, mencionando que os advers\u00e1rios souberam estabelecer o tipo de jogo que queriam:<\/p>\n<p>\u00abIsto \u00e9 um derby, \u00e9 normal. Eu joguei muitos, como jogador e como treinador. Eu acho que o Ahli levou o jogo para onde queria, e levou o jogo para um ambiente com mais frenesim, com mais duelos f\u00edsicos e \u00e0s vezes com mais provoca\u00e7\u00f5es aos nossos jogadores, e n\u00f3s entr\u00e1mos nisso por vezes, o que n\u00e3o \u00e9 bom porque retira discernimento \u00e0 equipa. Temos \u00e9 de pensar no que temos de fazer quando n\u00e3o temos bola, e principalmente com a bola porque havia espa\u00e7o para jogar e para criar dificuldades ao advers\u00e1rio. Mas se calhar vamos encontrar-nos outra vez, vamos ver\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"&#8211; Advertisement &#8211; Na passada sexta-feira, o Al Ittihad foi derrotado por 3-1 na visita ao Al Ahli.&hellip;\n","protected":false},"author":2,"featured_media":296783,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87],"tags":[2120,24483,260,135,1965,32,33,5540,134],"class_list":{"0":"post-296782","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-desporto","8":"tag-al-ittihad","9":"tag-al-ahly","10":"tag-atualidade","11":"tag-desporto","12":"tag-liga-saudita","13":"tag-portugal","14":"tag-pt","15":"tag-sergio-conceicao","16":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116194958717282865","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/296782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=296782"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/296782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/296783"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=296782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=296782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=296782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}