{"id":304660,"date":"2026-03-14T16:43:29","date_gmt":"2026-03-14T16:43:29","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/304660\/"},"modified":"2026-03-14T16:43:29","modified_gmt":"2026-03-14T16:43:29","slug":"ja-esta-uma-adolescente-claudia-vieira-faz-partilha-rara-sobre-filha-com-pedro-teixeira-nem-de-perfil","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/304660\/","title":{"rendered":"J\u00e1 est\u00e1 uma adolescente! Cl\u00e1udia Vieira faz partilha rara sobre filha com Pedro Teixeira: &#8220;Nem de perfil&#8230;&#8221;"},"content":{"rendered":"<p>O Instagram de <a href=\"https:\/\/selfie.iol.pt\/famosos\/claudia-vieira\/claudia-vieira-em-partilha-rara-eu-e-a-minha-irma-nao-estavamos-de-acordo-com-receio-que-desse-para-o-torto\/20260217\/6994ae13d34e28842c80baca\" target=\"_blank\" rel=\"nofollow noopener\">Cl\u00e1udia Vieira<\/a> ficou, recentemente, repleto de elogios, depois de a atriz ter partilhado uma s\u00e9rie de fotografias da filha mais nova, Caetana, de seis anos, fruto do atual relacionamento com Jo\u00e3o Alves.<\/p>\n<p>&#8220;Vou s\u00f3 ali e j\u00e1 volto, mas entretanto deixo esta del\u00edcia irresist\u00edvel agarradinha ao seu urso de peluche&#8221;, assinalou a m\u00e3e babada na legenda das imagens ternurentas.<\/p>\n<p>Nessa partilha, Cl\u00e1udia Vieira ainda deixou uma confiss\u00e3o sobre a filha mais velha, Maria: &#8220;A mais crescida&#8230; nem de perfil a apanho em fotografias!&#8221; E, na caixa de coment\u00e1rios da publica\u00e7\u00e3o, uma seguidora assinalou, com um emoji a piscar o olho: &#8220;A mais crescida est\u00e1 na adolesc\u00eancia.&#8221;<\/p>\n<p>Recorde-se que Maria j\u00e1 tem 15 anos e \u00e9 fruto da rela\u00e7\u00e3o, entretanto terminada, de Cl\u00e1udia Vieira com <a href=\"https:\/\/selfie.iol.pt\/famosos\/a-madrasta\/de-pedro-teixeira-a-matilde-reymao-tvi-anuncia-novos-nomes-do-elenco-de-a-madrasta\/20260218\/69960c3ed34e28842c80c736\" target=\"_blank\" rel=\"nofollow noopener\">Pedro Teixeira<\/a>.<\/p>\n<p>Veja, agora, as imagens partilhadas por Cl\u00e1udia Vieira na galeria de fotografias que prepar\u00e1mos para si.<\/p>\n","protected":false},"excerpt":{"rendered":"O Instagram de Cl\u00e1udia Vieira ficou, recentemente, repleto de elogios, depois de a atriz ter partilhado uma s\u00e9rie&hellip;\n","protected":false},"author":2,"featured_media":304661,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[145],"tags":[1244,813,211,210,1082,114,115,980,1015,619,159,32,33,1012,1751],"class_list":{"0":"post-304660","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-celebridades","8":"tag-ator","9":"tag-atriz","10":"tag-celebridades","11":"tag-celebrities","12":"tag-claudia-vieira","13":"tag-entertainment","14":"tag-entretenimento","15":"tag-famosos","16":"tag-instagram","17":"tag-nacional","18":"tag-pedro-teixeira","19":"tag-portugal","20":"tag-pt","21":"tag-selfie","22":"tag-sic"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116228535433179511","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/304660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=304660"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/304660\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/304661"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=304660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=304660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=304660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}