{"id":305607,"date":"2026-03-15T13:05:10","date_gmt":"2026-03-15T13:05:10","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/305607\/"},"modified":"2026-03-15T13:05:10","modified_gmt":"2026-03-15T13:05:10","slug":"neymar-jr-chama-a-atencao-ao-mostrar-para-quem-esta-torcendo-do-bbb-26","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/305607\/","title":{"rendered":"Neymar Jr. chama a aten\u00e7\u00e3o ao mostrar para quem est\u00e1 torcendo do BBB 26"},"content":{"rendered":"<p>Parece que <strong>Neymar Jr.<\/strong> \u00e9 um dos famosos que gosta de acompanhar BBB e deixou escapar para quem est\u00e1 torcendo nesta edi\u00e7\u00e3o. Na rede social, o jogador de futebol fez um coment\u00e1rio em um post de um dos participantes confinados e chamou a aten\u00e7\u00e3o.<\/p>\n<p>O esposo de <strong>Bruna Biancardi<\/strong> colocou um emoji de medalha de ouro com o n\u00famero um em uma publica\u00e7\u00e3o de <strong>Jonas Sulzabach<\/strong>. O Veterano estava chorando ap\u00f3s brigas no v\u00eddeo que recebeu um coment\u00e1rio do atleta.<\/p>\n<p>\u201cInfernizam o cara, falaram do filho dele, da m\u00e3e e at\u00e9 da idade, como se isso fosse um dem\u00e9rito. \u00c9 impressionante a resili\u00eancia do Jonas, porque ele vem sendo atacado das formas mais baixas dentro do programa\u201d, escreveu a equipe na legenda do post comentado por Neymar.<\/p>\n<p>A rea\u00e7\u00e3o deixada pelo jogador de futebol gerou mais de mil coment\u00e1rios e mais de 25 mil curtidas. Os f\u00e3s do influenciador digital adoraram a intera\u00e7\u00e3o. \u201cNeymar, nunca te pedir nada, faz o cara ser campe\u00e3o!\u201d, disseram.<\/p>\n<p>\t Neymar declara torcida para Jonas: <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1087303 img-fluid lazy\" alt=\"Neymar mostra torcida para Jonas\" width=\"1080\" height=\"358\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/03\/neymar-declara-torcida-jonas-bbb.jpg\"  \/>Neymar mostra torcida para Jonas \u2013 Foto: Reprodu\u00e7\u00e3o\/Instagram <\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DV3Z3MhAGCT\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\"><\/blockquote>\n<p> Jonas est\u00e1 no pared\u00e3o <\/p>\n<p>Por enquanto, Jonas est\u00e1 no pared\u00e3o com <strong>Ana Paula Renault<\/strong> e <strong>Leandro Boneco<\/strong>. <a href=\"https:\/\/caras.com.br\/big-brother\/bbb-26-saiba-quem-esta-no-paredao-apos-dinamica-surpresa.phtml\" rel=\"nofollow noopener\" target=\"_blank\">Durante uma din\u00e2mica neste s\u00e1bado, 14, o influencer e os outros dois participantes foram os escolhidos para a berlinda<\/a>.<\/p>\n<p> O Pared\u00e3o dessa semana <\/p>\n<p>A forma\u00e7\u00e3o do pared\u00e3o essa semana ter\u00e1 algumas novidades, al\u00e9m do hor\u00e1rio. O programa ser\u00e1 dividido em duas partes e a primeira vai ao ar \u00e0s 13h50, com vota\u00e7\u00e3o da casa e indica\u00e7\u00e3o do l\u00edder.<\/p>\n<p>Ap\u00f3s essa primeira etapa do programa, a segunda ir\u00e1 ao ar \u00e0s 19h20. Dessa vez, os brothers emparedados far\u00e3o a prova Bate-Volta. Menos o indicado pelo l\u00edder e o salvo pelo poder n\u00e3o participar\u00e3o dela.<\/p>\n<p> Um da din\u00e2mica poder\u00e1 ser salvo <\/p>\n<p>Essa semana a caixa misteriosa dar\u00e1 o poder de salvar algu\u00e9m da din\u00e2mica do pared\u00e3o.<\/p>\n<p>\u00a0<\/p>\n<p>        <a href=\"https:\/\/caras.com.br\/autor\/nataly-paschoal\" rel=\"nofollow noopener\" target=\"_blank\">&#13;<br \/>\n          <img loading=\"lazy\" decoding=\"async\" alt=\"Nataly Paschoal\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/03\/nataly-paschoal_sqmd.jpg\" class=\"avatar avatar-115 photo rounded-circle\" height=\"115\" width=\"115\"\/>        <\/a><\/p>\n<p><b>Nataly Paschoal <\/b>\u00e9 rep\u00f3rter de conte\u00fado do site CARAS. Formada em jornalismo pela Faculdade C\u00e1sper L\u00edbero, ela j\u00e1 passou por sites como Todateen, Sportlife e espnW. Escreve sobre celebridades, TV, reality show e novelas.<\/p>\n<p>\t                                            <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"Parece que Neymar Jr. \u00e9 um dos famosos que gosta de acompanhar BBB e deixou escapar para quem&hellip;\n","protected":false},"author":2,"featured_media":305608,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142],"tags":[15986,114,115,44675,1996,6039,32,33,151],"class_list":{"0":"post-305607","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-bbb-26","9":"tag-entertainment","10":"tag-entretenimento","11":"tag-jonas-sulzabach","12":"tag-neymar","13":"tag-neymar-jr","14":"tag-portugal","15":"tag-pt","16":"tag-tv"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116233340574887694","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/305607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=305607"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/305607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/305608"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=305607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=305607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=305607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}