{"id":311700,"date":"2026-03-20T07:19:10","date_gmt":"2026-03-20T07:19:10","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/311700\/"},"modified":"2026-03-20T07:19:10","modified_gmt":"2026-03-20T07:19:10","slug":"ranking-uefa-portugal-alcanca-a-melhor-pontuacao-de-sempre","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/311700\/","title":{"rendered":"Ranking UEFA: Portugal alcan\u00e7a a melhor pontua\u00e7\u00e3o de sempre"},"content":{"rendered":"<p>As vit\u00f3rias e consequentes apuramentos de Sporting, Sp. Braga e FC Porto permitiram a Portugal n\u00e3o s\u00f3 ter uma jornada perfeita, como bater o recorde de pontos somados pelo pa\u00eds numa temporada, com 18.900 pontos. At\u00e9 agora, o registo m\u00e1ximo dos representantes lusos nas competi\u00e7\u00f5es europeias (18.800) datava da \u00e9poca 2010\/11, quando FC Porto e Sp. Braga chegaram \u00e0 final da Liga Europa (os drag\u00f5es, ent\u00e3o treinados por Andr\u00e9 Villas-Boas, venceram a prova) e o Benfica despediu-se nas meias-finais.<\/p>\n<p>Uma \u00f3tima not\u00edcias que, no entanto, n\u00e3o vem s\u00f3. \u00c9 que a elimina\u00e7\u00e3o do Genk, \u00faltimo representante belga nas provas europeias, deixou Portugal mais confort\u00e1vel na defesa do sexto lugar conquistado e que as equipas lusas v\u00e3o tentar defender na pr\u00f3xima \u00e9poca.<\/p>\n<p>A B\u00e9lgica, atual oitava classificada no ranking, vai iniciar a pr\u00f3xima temporada no s\u00e9timo posto, imediatamente atr\u00e1s de Portugal e \u00e0 frente dos Pa\u00edses Baixos. Se o pa\u00eds das tulipas ver\u00e1 eliminados os pontos da melhor das \u00faltimas cinco temporadas (2021\/22), os belgas ficam sem os pontos daquele que foi o pior dos \u00faltimos anos.<\/p>\n<p>Isso tamb\u00e9m poderia representar uma amea\u00e7a para Portugal, mas a excelente campanha internacional dos representantes nacionais em 2025\/26 permitiu que a B\u00e9lgica n\u00e3o s\u00f3 n\u00e3o inicie a pr\u00f3xima temporada no sexto posto, como abre perspetivas de que a dist\u00e2ncia possa ser consider\u00e1vel.<\/p>\n<p>Mesmo se os representantes lusos n\u00e3o somassem mais pontos nas provas europeias nesta temporada, Portugal iniciaria 2026\/27 com 58.650 pontos face aos 55.650 da B\u00e9lgica. Acontece que Sporting, FC Porto e Sp. Braga podem contribuir ainda mais para dilatar a vantagem sobre aquele que ser\u00e1 na pr\u00f3xima \u00e9poca o mais direto concorrente na luta pelo tal terceiro lugar &#8211; j\u00e1 garantido por Portugal em 2027\/28 &#8211; que pode dar acesso a um lugar na fase de liga da Champions.<\/p>\n<p><strong>O TOP-10 DO RANKING A CINCO ANOS DA UEFA:<\/strong><\/p>\n<p>1.\u00ba &#8211; Inglaterra: 115.630 (5 de 9 clubes)<\/p>\n<p>2.\u00ba &#8211; It\u00e1lia: 99.660 (2 de 7 clubes)<\/p>\n<p>3.\u00ba &#8211; Espanha: 95.234 (6 de 8 clubes)<\/p>\n<p>4.\u00ba &#8211; Alemanha: 90.545 (3 de 7 clubes)<\/p>\n<p>5.\u00ba &#8211; Fran\u00e7a: 81.569 (2 de 7 clubes)<\/p>\n<p>6.\u00ba &#8211; Portugal: 71.566 (3 de 7 clubes)<\/p>\n<p>7.\u00ba &#8211; Pa\u00edses Baixos: 67.762 (1 de 6 clubes)<\/p>\n<p>8.\u00ba &#8211; B\u00e9lgica: 62.250 (0 de 5 clubes)<\/p>\n<p>9.\u00ba &#8211; Turquia: 51.875 (0 de 5 clubes)<\/p>\n<p>10.\u00ba &#8211; Ch\u00e9quia: 48.525 (0 de 5 clubes)<\/p>\n<p> <strong>A outra luta de Portugal<\/strong> <\/p>\n<p>Mas se Portugal j\u00e1 acautelou 2027\/28, ainda pode tirar proveito do que resta jogar daquela que j\u00e1 est\u00e1 a ser, por uma boa margem, a melhor das representa\u00e7\u00f5es nacionais nas competi\u00e7\u00f5es europeias: no ranking anual, que confere aos dois melhores pa\u00edses uma vaga extra na Champions da pr\u00f3xima \u00e9poca para cada um.<\/p>\n<p>Neste bra\u00e7o de ferro, o nosso pa\u00eds est\u00e1 nesta altura no quarto lugar com 18.900 pontos, menos 0.528 pontos do que a Alemanha (3.\u00ba) e a 1.381 de Espanha (2.\u00ba), o que confere ainda mais import\u00e2ncia \u00e0 eliminat\u00f3ria entre Sp. Braga e Betis.<\/p>\n<p>No entanto, as hip\u00f3teses, embora reais, s\u00e3o t\u00e9nues, j\u00e1 que se Portugal tem tr\u00eas na Europa tr\u00eas de cinco equipas com que iniciou as competi\u00e7\u00f5es da UEFA, Espanha conserva ainda seis de oito, sendo que j\u00e1 garantiu que ter\u00e1 pelo menos um clube nas meias-finais de uma das tr\u00eas provas, uma vez que o Barcelona e o Atl\u00e9tico Madrid v\u00e3o defrontar-se nos quartos de final da Champions.<\/p>\n<p>Na lideran\u00e7a do ranking anual est\u00e1 Inglaterra (cinco equipas ainda em a\u00e7\u00e3o na Europa), a quem basta um empate para garantir que o quinto classificado da Premier League vai \u00e0 Liga dos Campe\u00f5es em 2026\/27.<\/p>\n<p><strong>O TOP-10 DO RANKING DE \u00c9POCA:<\/strong><\/p>\n<p>1.\u00ba: Inglaterra, 24.791 (5 de 9 clubes)<\/p>\n<p>2.\u00ba: Espanha, 20.281 (6 de 8 clubes)<\/p>\n<p>3.\u00ba: Alemanha, 19.428 (4 de 7 clubes)<\/p>\n<p>4.\u00ba: PORTUGAL, 18.900 (3 de 5 clubes)<\/p>\n<p>5.\u00ba: It\u00e1lia, 18.714 (2 de 7 clubes)<\/p>\n<p>6.\u00ba: Fran\u00e7a, 16.392 (2 de 7 clubes)<\/p>\n<p>7.\u00ba: Pol\u00f3nia, 15.750 (0 de 4 clubes)<\/p>\n<p>8.\u00ba: Gr\u00e9cia, 13.800 (1 de 5 clubes)<\/p>\n<p>9.\u00ba: Dinamarca, 12.250 (0 de 4 clubes)<\/p>\n<p>10.\u00ba: Chipre, 12.156 (0 de 4 clubes)<\/p>\n","protected":false},"excerpt":{"rendered":"As vit\u00f3rias e consequentes apuramentos de Sporting, Sp. Braga e FC Porto permitiram a Portugal n\u00e3o s\u00f3 ter&hellip;\n","protected":false},"author":2,"featured_media":311701,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87],"tags":[51,135,282,7706,4237,137,46,32,33,47,9453,1233,34,134],"class_list":{"0":"post-311700","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-desporto","8":"tag-benfica","9":"tag-desporto","10":"tag-fc-porto","11":"tag-liga-campeoes","12":"tag-liga-conferencia","13":"tag-liga-europa","14":"tag-maisfutebol","15":"tag-portugal","16":"tag-pt","17":"tag-pura-paixao","18":"tag-ranking-uefa","19":"tag-sp-braga","20":"tag-sporting","21":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116260291506691316","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/311700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=311700"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/311700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/311701"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=311700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=311700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=311700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}