{"id":357322,"date":"2026-04-25T19:11:25","date_gmt":"2026-04-25T19:11:25","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/357322\/"},"modified":"2026-04-25T19:11:25","modified_gmt":"2026-04-25T19:11:25","slug":"rosto-de-soares-da-autoria-de-vhils-inaugurado-na-amadora-observador","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/357322\/","title":{"rendered":"Rosto de Soares da autoria de Vhils inaugurado na Amadora \u2013 Observador"},"content":{"rendered":"<p>Uma escultura em bet\u00e3o do rosto M\u00e1rio Soares, assinada por Vhils, foi este s\u00e1bado inaugurada na Amadora, tendo a filha do antigo Presidente da Rep\u00fablica pedido que se lute para que a \u201cliberdade continue\u201d e a mem\u00f3ria n\u00e3o se apague.<\/p>\n<p>A cerim\u00f3nia de inaugura\u00e7\u00e3o desta obra pedida pela C\u00e2mara da Amadora, distrito de Lisboa, decorreu este s\u00e1bado, no dia em que se comemora o 25 de Abril, no Parque da Liberdade, contando com a presen\u00e7a, entre outras figuras, do secret\u00e1rio-geral do PS, Jos\u00e9 Lu\u00eds Carneiro, e fam\u00edlia de M\u00e1rio Soares, entre eles os filhos Jo\u00e3o Soares e Isabel Soares.<\/p>\n<p>Isabel Soares, presidente da Funda\u00e7\u00e3o M\u00e1rio Soares e Maria Barroso, pediu que se continue \u201ca lutar para que a liberdade continue,\u00a0para que a democracia continue\u201d.<\/p>\n<p>\u201cE para que n\u00e3o apague a mem\u00f3ria. \u00c9 fundamental que\u00a0n\u00e3o se apague a mem\u00f3ria e que se passe isso aos nossos jovens, \u00e9 importante que\u00a0eles saibam o que \u00e9 que se viveu antes do 25 de Abril para que n\u00e3o voltemos ao passado\u201d, pediu.<\/p>\n<p>A filha de M\u00e1rio Soares elogiou a obra de Vhils, uma escultura em bet\u00e3o que \u201cassume a forma de um diorama de grande escala\u201d e que tem cerca de cinco metros de comprimento, 2,5 metros de altura e um peso aproximado de sete toneladas.<\/p>\n<p>\u201c\u00c9 uma pe\u00e7a lind\u00edssima que retrata o nosso pai com o seu sorriso luminoso e\u00a0o seu olhar sempre confiante, sempre otimista. Era ele que nos dava \u00e2nimo e coragem quando \u00edamos visitar as cadeias\u00a0do Aljube e de Caxias, nunca o vimos abatido, nunca o vimos triste\u201d, recordou Isabel Soares.<\/p>\n<p>A presidente da Funda\u00e7\u00e3o M\u00e1rio Soares e Maria Barroso recordou o lema\u00a0do seu pai de que \u201cs\u00f3 \u00e9 vencido quem desiste de lutar\u201d.<\/p>\n<p>A primeira pessoa a discursar foi o artista, Alexandre Farto, que \u00e9 conhecido por Vhils, que destacou M\u00e1rio Soares e todo o seu percurso.<\/p>\n<p>\u201cConseguiu\u00a0criar pontes onde ningu\u00e9m as conseguia ver e uma democracia que tamb\u00e9m ningu\u00e9m conseguia\u00a0ver porque era tudo do zero\u201d, elogiou.<\/p>\n<p>Apesar dos problemas e dos desafios do in\u00edcio da democracia, a esperan\u00e7a do artista \u00e9 que a pr\u00f3xima gera\u00e7\u00e3o consiga \u201cfazer 20 ou 30%\u201d do que fez a gera\u00e7\u00e3o dos seus pais, dos seus av\u00f3s e de M\u00e1rio Soares.<\/p>\n<p>\u201cJ\u00e1 consegu\u00edamos\u00a0uma grande vit\u00f3ria.\u00a0E \u00e9 s\u00f3 isso que eu quero, \u00e9 que a pr\u00f3xima gera\u00e7\u00e3o consiga fazer os 20% do que j\u00e1 foi\u00a0feito antes\u201d, pediu, recordando o seu percurso, a sua liga\u00e7\u00e3o \u00e0 sa\u00fade e \u00e0s escolas p\u00fablicas e a forma como M\u00e1rio Soares marcou a sua pr\u00f3pria vida.<\/p>\n<p>A fechar os discursos esteve o presidente da C\u00e2mara da Amadora, V\u00edtor Ferreira, que considerou que, atrav\u00e9s da \u201ct\u00e9cnica \u00fanica\u201d de Vhils, \u201cM\u00e1rio Soares fica agora gravado na paisagem da Amadora tal como ficou gravado na hist\u00f3ria de Portugal\u201d.<\/p>\n<p>\u201cEvocar M\u00e1rio Soares \u00e9, por isso, celebrar n\u00e3o apenas um homem, mas a pr\u00f3pria conquista\u00a0da dignidade democr\u00e1tica e a afirma\u00e7\u00e3o de um pa\u00eds livre, plural e voltado para o futuro\u201d, elogiou, apelidando-o como um dos \u201cprincipais obreiros do Portugal democr\u00e1tico\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"Uma escultura em bet\u00e3o do rosto M\u00e1rio Soares, assinada por Vhils, foi este s\u00e1bado inaugurada na Amadora, tendo&hellip;\n","protected":false},"author":2,"featured_media":357323,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[2534,207,6594,27,28,315,15,16,14,25,26,21,22,60883,12,13,19,20,57,32,23,24,33,58,17,18,29,30,31,49533],"class_list":{"0":"post-357322","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-portugal","8":"tag-25-de-abril","9":"tag-arte","10":"tag-arte-urbana","11":"tag-breaking-news","12":"tag-breakingnews","13":"tag-cultura","14":"tag-featured-news","15":"tag-featurednews","16":"tag-headlines","17":"tag-latest-news","18":"tag-latestnews","19":"tag-main-news","20":"tag-mainnews","21":"tag-mu00e1rio-soares","22":"tag-news","23":"tag-noticias","24":"tag-noticias-principais","25":"tag-noticiasprincipais","26":"tag-pau00eds","27":"tag-portugal","28":"tag-principais-noticias","29":"tag-principaisnoticias","30":"tag-pt","31":"tag-sociedade","32":"tag-top-stories","33":"tag-topstories","34":"tag-ultimas","35":"tag-ultimas-noticias","36":"tag-ultimasnoticias","37":"tag-vhils"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116466934485602495","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/357322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=357322"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/357322\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/357323"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=357322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=357322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=357322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}