{"id":362509,"date":"2026-04-29T17:50:13","date_gmt":"2026-04-29T17:50:13","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/362509\/"},"modified":"2026-04-29T17:50:13","modified_gmt":"2026-04-29T17:50:13","slug":"venda-da-indaqua-atrai-propostas-acima-de-mil-milhoes-de-euros-empresas","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/362509\/","title":{"rendered":"Venda da Indaqua atrai propostas acima de mil milh\u00f5es de euros &#8211; Empresas"},"content":{"rendered":"<p class=\"\">&#13;<br \/>\n        A <b>venda da Indaqua, um grupo portugu\u00eas que gere o abastecimento de \u00e1gua em seis munic\u00edpios no norte de Portugal, est\u00e1 a atrair a aten\u00e7\u00e3o de pelo menos quatro fundos e empresas internacionais, com v\u00e1rias propostas a avaliarem a empresa em mais de mil milh\u00f5es de euros<\/b>. A informa\u00e7\u00e3o est\u00e1 a ser avan\u00e7ada esta quarta-feira pela Bloomberg, que cita fontes com conhecimento sobre o tema.&#13;\n    <\/p>\n","protected":false},"excerpt":{"rendered":"&#13; A venda da Indaqua, um grupo portugu\u00eas que gere o abastecimento de \u00e1gua em seis munic\u00edpios no&hellip;\n","protected":false},"author":2,"featured_media":362510,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[61706,88,89,90,49793,445,59487,16648,42283,32,33],"class_list":{"0":"post-362509","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-empresas","8":"tag-antin-infrastructure-partners","9":"tag-business","10":"tag-economy","11":"tag-empresas","12":"tag-equity-partners","13":"tag-europa","14":"tag-mil-milhoes-de-euros","15":"tag-milhoes","16":"tag-morgan-stanley","17":"tag-portugal","18":"tag-pt"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116489265264549485","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/362509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=362509"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/362509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/362510"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=362509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=362509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=362509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}