{"id":367142,"date":"2026-05-03T14:09:12","date_gmt":"2026-05-03T14:09:12","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/367142\/"},"modified":"2026-05-03T14:09:12","modified_gmt":"2026-05-03T14:09:12","slug":"eu-dirigi-o-carro-dele-coluna-chico-lelis","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/367142\/","title":{"rendered":"Eu dirigi o carro dele &#8211; Coluna Chico Lelis"},"content":{"rendered":"<p>Muitos de voc\u00eas v\u00e3o identificar este meu amigo. E\u00a0 tamb\u00e9m lamentar que ele deixou poucos andarem no seu carro, atr\u00e1s do volante. Da\u00ed, o meu t\u00edtulo para essa coluna.<\/p>\n<p>Para que se tenha uma ideia do tanto que o meu amigo ama o seu M5, um BMW 95, resultado do projeto E34 (denomina\u00e7\u00e3o que as f\u00e1bricas usam para seus projetos, como a GM, por exemplo, usou Blue Macaw \u2013 Arara Azul \u2013 para o Celta) ele n\u00e3o sai na chuva com sua m\u00e1quina de 340 CV, amortecedores el\u00e9tricos, c\u00e2mbio manual de seis marchas\u200b, tra\u00e7\u00e3o traseira,\u00a0que fazia 0 a 100 em 5,7s, incr\u00edveis para a \u00e9poca do seu lan\u00e7amento. Sua m\u00e1xima, limitada eletronicamente, alcan\u00e7a 250 km\/h.<\/p>\n<p><img data-portal-copyright=\"Motociclismo Online\" data-has-syndication-rights=\"1\" decoding=\"async\" fetchpriority=\"high\" class=\"aligncenter size-full wp-image-105154\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/05\/M5-DO-MEU-AMIGO-1-1.jpeg\" alt=\"\" width=\"1280\" height=\"960\"  \/><\/p>\n<p>S\u00e3o muitas as hist\u00f3rias sobre o ci\u00fame que meu amigo tem do seu carro, comprado, Zero km, em 1996 quando chegou ao Brasil. E foi uma das \u00faltimas unidades fabricadas pela BMW na Alemanha.<\/p>\n<p>Ele confessa que n\u00e3o anda com seu carro na chuva, n\u00e3o por molhar a lataria, mas pela sujeira que se acumula sob o carro. E aproveita para contar a hist\u00f3ria do dia em que deixou seu M5 protegido de uma chuva que n\u00e3o existiu.<\/p>\n<p>\u2013 J\u00e1 faz alguns anos \u2013 conta ele \u2013 eu estava fazendo um trabalho de treinamento e meu parceiro saiu antes do local, indo para S\u00e3o Paulo e eu fiquei alguns minutos mais. Ent\u00e3o, ele manda um recado dizendo que chovia muito na metade do caminho. \u00a0Eu voltei para S\u00e3o Paulo em outro\u00a0\u200bcarro\u00a0e deixei o meu l\u00e1. E era mentira. Deu o maior trabalho voltar l\u00e1 no dia seguinte para trocar\u00a0\u200bp\u200belo meu.<\/p>\n<p><img loading=\"lazy\" data-portal-copyright=\"Motociclismo Online\" data-has-syndication-rights=\"1\" decoding=\"async\" class=\"aligncenter size-full wp-image-105155\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/05\/Campanha-de-abril-Citroen_Thiaguinho_.png\" alt=\"\" width=\"728\" height=\"90\"  \/><\/p>\n<p>M5 iguais aos do meu amigo, foram fabricadas\u00a0404 unidades, os famosos Six Speed Models, mas ele n\u00e3o sabe quantos exatamente vieram para o Brasil. O modelo M5 E34, come\u00e7ou a ser produzido em 1988, com mo\u200btores 6 cilindros em linha 3.6. Sendo a do meu amigo a \u00faltima vers\u00e3o, 3.8L, que prefere ficar no seu canto, sem mostrar-se, embora muita gente do meio saiba de quem estou falando, \u201cn\u00e9\u201d?.<\/p>\n<p>A BMW tamb\u00e9m produziu uma vers\u00e3o, em 1992 a SW, at\u00e9 1995. A tra\u00e7\u00e3o traseira\u200b, que\u00a0\u00a0\u00e9 o forte do carro, hoje por ser vendido com a possibilidade de ter tra\u00e7\u00e3o total.<\/p>\n<p><strong>Como enganar a eletr\u00f4nica na velocidade<\/strong><\/p>\n<p>Um acordo, na\u00a0Europa, entre v\u00e1rios fabricantes, limitava, eletronicamente, a velocidade dos seus modelos em 250 km\/h (os superesportivos nunca entraram nesse acordo, nem a Opel).<\/p>\n<p>Meu amigo queria saber qual o limite real do seu carro e conseguiu de um engenheiro da BMW, na Alemanha, a dica para passar dessa limita\u00e7\u00e3o.<\/p>\n<p>Uma coisa muito simples para conseguir:\u00a0n\u00e3o mudar para a sexta marcha, indo ao limite das rota\u00e7\u00f5es na quinta. E o M5 dele alcan\u00e7ou 275 km\/h, em uma pista fechada, j\u00e1 que o engenheiro alem\u00e3o n\u00e3o queria ensinar o segredo, pois sabia que no Brasil a velocidade m\u00e1quina nas estradas era de 120 km\/h.<\/p>\n<p><strong>Por que essa hist\u00f3ria?<\/strong><\/p>\n<p>Acontece que, recentemente, conversando com esse meu amigo, lembrei o dia em que me deixou dirigir a sua \u201cm\u00e1quina\u201d. Para minha grata surpresa, ele revelou que pode contar nos dedos, de uma s\u00f3 m\u00e3o, as pessoas a quem ele permitiu est\u200be\u00a0\u200bprivil\u00e9gio.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Muitos de voc\u00eas v\u00e3o identificar este meu amigo. E\u00a0 tamb\u00e9m lamentar que ele deixou poucos andarem no seu&hellip;\n","protected":false},"author":2,"featured_media":367143,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[12051,62197,109,107,108,62198,32,33,105,103,104,106,110],"class_list":{"0":"post-367142","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ciencia-e-tecnologia","8":"tag-bmw-m5","9":"tag-chico-lelis","10":"tag-ciencia","11":"tag-ciencia-e-tecnologia","12":"tag-cienciaetecnologia","13":"tag-coluna-chico-lelis","14":"tag-portugal","15":"tag-pt","16":"tag-science","17":"tag-science-and-technology","18":"tag-scienceandtechnology","19":"tag-technology","20":"tag-tecnologia"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116511045883393779","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/367142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=367142"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/367142\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/367143"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=367142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=367142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=367142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}