{"id":369894,"date":"2026-05-05T14:46:20","date_gmt":"2026-05-05T14:46:20","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/369894\/"},"modified":"2026-05-05T14:46:20","modified_gmt":"2026-05-05T14:46:20","slug":"fc-porto-noticias-bernardo-lima-renova-ate-2031","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/369894\/","title":{"rendered":"FC Porto &#8211; Not\u00edcias &#8211; Bernardo Lima renova at\u00e9 2031"},"content":{"rendered":"<p>Bernardo Lima renovou contrato e vai continuar a defender as cores do clube que representa desde 2016. O FC Porto e o m\u00e9dio de 18 anos chegaram a acordo para prolongar o v\u00ednculo para os pr\u00f3ximos cinco anos, at\u00e9 2031.<\/p>\n<p>Natural de S\u00e3o Jo\u00e3o da Madeira, o centrocampista de 1,82 metros deu os primeiros toques na AD Sanjoanense e, com apenas oito anos, trocou a cidade natal pela Invicta para dar in\u00edcio ao percurso no FC Porto.<\/p>\n<p>O bom desempenho nos escal\u00f5es jovens fez com que queimasse etapas e subisse na hierarquia da forma\u00e7\u00e3o: ainda com idade de juvenil, Bernardo Lima marcou oito golos e fez uma assist\u00eancia em 30 jogos pelos juniores, n\u00fameros que lhe valeram a assinatura do primeiro contrato profissional em 2024\/25.<\/p>\n<p>Nessa mesma temporada, a 9 de mar\u00e7o, estreou-se nas competi\u00e7\u00f5es profissionais com apenas 16 anos, quando Jo\u00e3o Brand\u00e3o o lan\u00e7ou para o lugar ocupado por Trafim Melnichenka em Mafra.<\/p>\n<p>Conclu\u00edda uma \u00e9poca de sonho, Bernardo Lima integrou a convocat\u00f3ria da sele\u00e7\u00e3o nacional de sub-17 para o Campeonato da Europa e foi um dos principais rostos da vit\u00f3ria lusa, ap\u00f3s assinar duas assist\u00eancias no jogo decisivo. Ao Europeu seguiu-se o Mundial, participando em todos os jogos e ajudando Portugal a alcan\u00e7ar um t\u00edtulo in\u00e9dito.<\/p>\n<p>Com o estatuto de Campe\u00e3o da Europa e do Mundo, o capit\u00e3o dos juniores foi distinguido com um Drag\u00e3o de Ouro no passado m\u00eas de dezembro e afirmou-se como um dos nomes a ter em conta no futuro do futebol portugu\u00eas.<\/p>\n<p>Al\u00e9m do pr\u00e9mio Revela\u00e7\u00e3o e de um registo prof\u00edcuo de 10 remates certeiros e duas assist\u00eancias em 17 jogos ao servi\u00e7o dos sub-19, a presente campanha trouxe mais minutos (438) e os primeiros golos enquanto s\u00e9nior.<\/p>\n<p>Sa\u00eddo do banco na 22.\u00aa jornada da Segunda Liga, o camisola 66 marcou nos descontos e resgatou o empate em casa da UD Leiria. H\u00e1 menos de 24 horas, Bernardo Lima estreou-se como titular pelo FC Porto B e assinou o \u00fanico golo na rece\u00e7\u00e3o ao FC Felgueiras.<\/p>\n<p>As boas exibi\u00e7\u00f5es ao servi\u00e7o da equipa B valeram-lhe a chamada aos treinos do plantel principal e Francesco Farioli convocou-o para o est\u00e1gio realizado no Algarve no in\u00edcio deste ano. Questionado sobre a integra\u00e7\u00e3o dos talentos jovens na equipa, o t\u00e9cnico italiano n\u00e3o deixou de mencionar Bernardo Lima e revelou que \u201cas oportunidades chegar\u00e3o muito em breve\u201d.<\/p>\n<p>No ep\u00edlogo de \u201cuma \u00e9poca desafiante, cansativa e exigente\u201d, o m\u00e9dio renova contrato com \u201co clube do cora\u00e7\u00e3o\u201d de olhos postos na \u201cestreia pela equipa A\u201d e com muita vontade de \u201cconquistar t\u00edtulos no FC Porto\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"Bernardo Lima renovou contrato e vai continuar a defender as cores do clube que representa desde 2016. O&hellip;\n","protected":false},"author":2,"featured_media":369895,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[27,28,57201,15,16,14,25,26,21,22,12,13,19,20,462,32,23,24,33,17,18,29,30,31],"class_list":{"0":"post-369894","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-principais-noticias","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-fcporto","11":"tag-featured-news","12":"tag-featurednews","13":"tag-headlines","14":"tag-latest-news","15":"tag-latestnews","16":"tag-main-news","17":"tag-mainnews","18":"tag-news","19":"tag-noticias","20":"tag-noticias-principais","21":"tag-noticiasprincipais","22":"tag-porto","23":"tag-portugal","24":"tag-principais-noticias","25":"tag-principaisnoticias","26":"tag-pt","27":"tag-top-stories","28":"tag-topstories","29":"tag-ultimas","30":"tag-ultimas-noticias","31":"tag-ultimasnoticias"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116522515979692292","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/369894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=369894"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/369894\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/369895"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=369894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=369894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=369894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}