{"id":370956,"date":"2026-05-06T12:24:23","date_gmt":"2026-05-06T12:24:23","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/370956\/"},"modified":"2026-05-06T12:24:23","modified_gmt":"2026-05-06T12:24:23","slug":"militares-feridos-em-salto-de-paraquedas-em-situacao-estavel-observador","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/370956\/","title":{"rendered":"Militares feridos em salto de paraquedas em situa\u00e7\u00e3o est\u00e1vel \u2013 Observador"},"content":{"rendered":"<p>Os dois militares do 3.\u00ba Curso de Paraquedismo de 2025 que ficaram feridos na ter\u00e7a-feira num acidente com paraquedas em Tancos encontram-se em situa\u00e7\u00e3o est\u00e1vel, adiantou esta quarta-feira o Ex\u00e9rcito.<\/p>\n<p>Na atualiza\u00e7\u00e3o divulgada sobre o estado de sa\u00fade dos dois militares, o Ex\u00e9rcito revelou que ambos \u201cpermanecem em observa\u00e7\u00e3o hospitalar, no Hospital de Leiria e no Hospital de S\u00e3o Jos\u00e9, onde est\u00e3o a realizar exames complementares de diagn\u00f3stico para avalia\u00e7\u00e3o de eventuais fraturas ou outras les\u00f5es\u201d.<\/p>\n<p>\u201cO Ex\u00e9rcito continua a acompanhar a situa\u00e7\u00e3o, garantindo o apoio necess\u00e1rio aos militares e \u00e0s respetivas fam\u00edlias, e prestar\u00e1 nova atualiza\u00e7\u00e3o sempre que se justifique\u201d, acrescenta o comunicado do Ex\u00e9rcito, que j\u00e1 na v\u00e9spera tinha revelado a abertura de um processo de averigua\u00e7\u00f5es relativamente a este incidente.<\/p>\n<p>Ao Observador, fonte do Ex\u00e9rcito explicou que os paraquedas dos dois militares ficaram \u201cenganchados\u201d durante o salto, num exerc\u00edcio que se realizava no \u00faltimo dia do curso, o que levou a que se \u201cacelerasse a velocidade da queda\u201d.<\/p>\n<p>De acordo a nota que o Ex\u00e9rcito enviou \u00e0 comunica\u00e7\u00e3o social, durante a manh\u00e3 desta ter\u00e7a-feira, em Tancos, distrito de Santar\u00e9m, \u201cocorreu um<strong> incidente no \u00e2mbito do Curso de Paraquedismo<\/strong>, envolvendo dois militares, durante a <strong>execu\u00e7\u00e3o de um salto de paraquedas<\/strong>\u201c. Segundo o ramo, foram acionados de imediato os meios de emerg\u00eancia m\u00e9dica, tendo os militares sido assistidos no local por equipas do Ex\u00e9rcito e do INEM, e posteriormente encaminhados para uma unidade hospitalar.<\/p>\n<p>Ao Observador, a mesma fonte do Ex\u00e9rcito disse que os militares foram assistidos, num primeiro momento, pela equipa m\u00e9dica da for\u00e7a especial de paraquedistas. O INEM foi depois acionado, os militares foram \u201cestabilizados\u201d no local e transportados para o hospital.<\/p>\n<p>A unidade de sa\u00fade mais pr\u00f3xima de Tancos \u00e9 o Hospital de Abrantes. No entanto, devido aos ferimentos sofridos, os militares ter\u00e3o sido transportados para outra unidade. A mesma fonte n\u00e3o soube detalhar a extens\u00e3o e a gravidade dos ferimentos sofridos. Os militares ser\u00e3o, segundo o gabinete de rela\u00e7\u00f5es p\u00fablicas do Ex\u00e9rcito, ambos sargentos.<\/p>\n<p>Foi determinada a abertura de um processo de averigua\u00e7\u00f5es \u201ccom vista ao apuramento das circunst\u00e2ncias do incidente\u201d e <strong>acionado o apoio psicol\u00f3gico<\/strong>, \u201cassegurando acompanhamento aos militares envolvidos e respetivos familiares\u201d.<\/p>\n<p>O porta-voz do Ex\u00e9rcito acrescenta que o 3.\u00ba Curso de Paraquedismo de 2025, de que os dois militares faziam parte, teve in\u00edcio em 27 de outubro de 2025 e terminou esta ter\u00e7a-feira. O grupo contava com 48 formandos. Helder Parcelas sublinha que \u201co curso tem como objetivo formar paraquedistas militares, capacitando-os para o desempenho de fun\u00e7\u00f5es nas unidades paraquedistas e desenvolvendo as compet\u00eancias f\u00edsicas, t\u00e9cnicas, t\u00e1ticas e psicol\u00f3gicas essenciais ao cumprimento de miss\u00f5es aeroterrestres de elevada exig\u00eancia\u201d.<\/p>\n<p>(Not\u00edcia atualizada \u00e0s 11h25 de quarta-feira com novas informa\u00e7\u00f5es sobre o estado de sa\u00fade dos dois militares)<\/p>\n<p><strong>[Ao d\u00e9cimo dia em Nova Iorque d\u00e1-se o homic\u00eddio brutal. As \u00faltimas horas, o que aconteceu no quarto 3416 e a confiss\u00e3o de Renato sobre como matou Carlos Castro.\u00a0O acesso aos ficheiros da investiga\u00e7\u00e3o permite reconstituir toda a investiga\u00e7\u00e3o ao crime. Ou\u00e7a o\u00a0<a href=\"https:\/\/observador.pt\/programas\/os-ficheiros-do-caso-carlos-castro\/episodio-5-cinquenta-e-duas-chamadas-nao-atendidas\/\" rel=\"nofollow noopener\" target=\"_blank\">quinto epis\u00f3dio<\/a>\u00a0de\u00a0<a href=\"https:\/\/observador.pt\/programas\/os-ficheiros-do-caso-carlos-castro\/\" rel=\"nofollow noopener\" target=\"_blank\">\u201cOs ficheiros do caso Carlos Castro\u201d<\/a>, o novo Podcast Plus do Observador, narrado pela atriz Joana Santos, com banda sonora original de J\u00falio Resende. Pode ouvir\u00a0<a href=\"https:\/\/observador.pt\/programas\/os-ficheiros-do-caso-carlos-castro\/episodio-5-cinquenta-e-duas-chamadas-nao-atendidas\/\" rel=\"nofollow noopener\" target=\"_blank\">aqui<\/a>, no site do Observador,\u00a0e tamb\u00e9m na\u00a0<a href=\"https:\/\/podcasts.apple.com\/pt\/podcast\/epis%C3%B3dio-5-cinquenta-e-duas-chamadas-n%C3%A3o-atendidas\/id1889212549?i=1000766106610\" rel=\"nofollow noopener\" target=\"_blank\">Apple Podcasts<\/a>, no\u00a0<a href=\"https:\/\/open.spotify.com\/episode\/0OKb8LsJBK3pGtJI3vLyLg\" rel=\"nofollow noopener\" target=\"_blank\">Spotify<\/a>\u00a0e no\u00a0<a href=\"https:\/\/music.youtube.com\/watch?v=kl54SuGXPjw&amp;list=RDPEVM9JCdgklQvXQ\" rel=\"nofollow noopener\" target=\"_blank\">Youtube Music<\/a>. E pode ouvir tamb\u00e9m\u00a0<a href=\"https:\/\/observador.pt\/programas\/os-ficheiros-do-caso-carlos-castro\/episodio-1-onde-esta-o-assassino-do-quarto-3416\/\" rel=\"nofollow noopener\" target=\"_blank\">aqui<\/a>\u00a0o primeiro epis\u00f3dio,\u00a0<a href=\"https:\/\/observador.pt\/programas\/os-ficheiros-do-caso-carlos-castro\/episodio-2-o-meu-nome-e-jesus-cristo\/\" rel=\"nofollow noopener\" target=\"_blank\">aqui<\/a>\u00a0o segundo,\u00a0<a href=\"https:\/\/observador.pt\/programas\/os-ficheiros-do-caso-carlos-castro\/episodio-3-desta-vez-e-amor\/\" rel=\"nofollow noopener\" target=\"_blank\">aqui<\/a>\u00a0o terceiro epis\u00f3dio e\u00a0<a href=\"https:\/\/observador.pt\/programas\/os-ficheiros-do-caso-carlos-castro\/episodio-4-alguem-nao-esta-a-cumprir-o-acordo\/\" rel=\"nofollow noopener\" target=\"_blank\">aqui<\/a>\u00a0o quarto epis\u00f3dio]<\/strong><\/p>\n<p><a href=\"https:\/\/observador.pt\/programas\/os-ficheiros-do-caso-carlos-castro\/episodio-5-cinquenta-e-duas-chamadas-nao-atendidas\/\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>        <img src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/04\/1776253829_645_ficheiros-ccc-1920x1080-play.jpg\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone\" onload=\"this.parentElement.classList.remove('spinner')\" onerror=\"this.parentElement.classList.remove('spinner')\" width=\"1440\" height=\"810\"\/><br \/>\n    Miguel Feraso Cabral<\/p>\n<p><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Os dois militares do 3.\u00ba Curso de Paraquedismo de 2025 que ficaram feridos na ter\u00e7a-feira num acidente com&hellip;\n","protected":false},"author":2,"featured_media":370957,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[27,28,2537,15,16,14,25,26,21,22,8498,12,13,19,20,32,23,24,33,58,17,18,29,30,31],"class_list":{"0":"post-370956","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-portugal","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-defesa","11":"tag-featured-news","12":"tag-featurednews","13":"tag-headlines","14":"tag-latest-news","15":"tag-latestnews","16":"tag-main-news","17":"tag-mainnews","18":"tag-militares","19":"tag-news","20":"tag-noticias","21":"tag-noticias-principais","22":"tag-noticiasprincipais","23":"tag-portugal","24":"tag-principais-noticias","25":"tag-principaisnoticias","26":"tag-pt","27":"tag-sociedade","28":"tag-top-stories","29":"tag-topstories","30":"tag-ultimas","31":"tag-ultimas-noticias","32":"tag-ultimasnoticias"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116527619859774917","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/370956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=370956"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/370956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/370957"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=370956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=370956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=370956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}