{"id":371379,"date":"2026-05-06T18:32:11","date_gmt":"2026-05-06T18:32:11","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/371379\/"},"modified":"2026-05-06T18:32:11","modified_gmt":"2026-05-06T18:32:11","slug":"nacional-de-juniores-benfica-vence-e-adia-festa-do-fc-porto","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/371379\/","title":{"rendered":"Nacional de Juniores: Benfica vence e adia festa do FC Porto"},"content":{"rendered":"<p>O Benfica recebeu e venceu o Rio Ave (2-1), nesta quarta-feira, num encontro referente \u00e0 10.\u00aa jornada da fase de apuramento de campe\u00e3o do Nacional de Juniores (Sub-19). Os avan\u00e7ados Francisco Silva e Dilan Neves marcaram os golos das \u00e1guias, aos 14 e 70 minutos.<\/p>\n<p>Assim, o Benfica mant\u00e9m-se na luta pelo bicampeonato e adiou a festa do FC Porto, que lidera com quatro pontos de vantagem, a duas jornadas do t\u00e9rmino da prova. Os drag\u00f5es recebem o Famalic\u00e3o no s\u00e1bado (17h). \u00c0 mesma hora, o Benfica recebe a Uni\u00e3o de Leiria.<\/p>\n<p>O FC Porto n\u00e3o conquista o Nacional de Juniores desde 2019.<\/p>\n<p> Confira a classifica\u00e7\u00e3o do Nacional de Juniores <\/p>\n<p><strong>1.\u00ba &#8211; FC Porto, 27 pontos<br \/>2.\u00ba &#8211; Benfica, 23 pontos<br \/>3.\u00ba &#8211; Sporting, 21 pontos<\/strong><br \/>4.\u00ba &#8211; Rio Ave, 16 pontos<br \/>5.\u00ba &#8211; Santa Clara, 15 pontos<br \/>6.\u00ba &#8211; Leiria, 15 pontos<br \/>7.\u00ba &#8211; Famalic\u00e3o, 11 pontos<br \/>8.\u00ba &#8211; Gil Vicente, 5 pontos<\/p>\n","protected":false},"excerpt":{"rendered":"O Benfica recebeu e venceu o Rio Ave (2-1), nesta quarta-feira, num encontro referente \u00e0 10.\u00aa jornada da&hellip;\n","protected":false},"author":2,"featured_media":285000,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87],"tags":[51,135,282,8344,8339,46,32,33,47,527,5434,5920,134,8340],"class_list":{"0":"post-371379","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-desporto","8":"tag-benfica","9":"tag-desporto","10":"tag-fc-porto","11":"tag-formacao","12":"tag-juniores","13":"tag-maisfutebol","14":"tag-portugal","15":"tag-pt","16":"tag-pura-paixao","17":"tag-resultados","18":"tag-resultados-hoje","19":"tag-resultados-maisfutebol","20":"tag-sports","21":"tag-sub-19"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116529066565167572","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/371379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=371379"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/371379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/285000"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=371379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=371379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=371379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}