{"id":372959,"date":"2026-05-07T23:27:13","date_gmt":"2026-05-07T23:27:13","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/372959\/"},"modified":"2026-05-07T23:27:13","modified_gmt":"2026-05-07T23:27:13","slug":"eua-estao-comprometidos-em-promover-a-paz-e-a-dignidade-humana-diz-rubio-ao-papa-igreja-catolica","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/372959\/","title":{"rendered":"EUA est\u00e3o comprometidos em \u201cpromover a paz e a dignidade humana\u201d, diz Rubio ao Papa | Igreja Cat\u00f3lica"},"content":{"rendered":"<p>O Papa Le\u00e3o XIV e Marco Rubio debateram esta quinta-feira a situa\u00e7\u00e3o no M\u00e9dio Oriente num encontro no Vaticano onde, segundo um porta-voz do Departamento de Estado, o chefe da diplomacia norte-americana \u201csublinhou a forte rela\u00e7\u00e3o entre os Estados Unidos e a Santa S\u00e9\u201d.<\/p>\n<p>\u201cO secret\u00e1rio de Estado Marco Rubio reuniu-se hoje com Sua Santidade o Papa Le\u00e3o XIV para discutir a situa\u00e7\u00e3o no M\u00e9dio Oriente e temas de interesse m\u00fatuo no Hemisf\u00e9rio Ocidental&#8221;, indicou, num comunicado, Tommy Pigott.<\/p>\n<p>O porta-voz do Departamento de Estado sublinhou ainda o \u201ccompromisso partilhado\u201d entre os EUA e a Santa S\u00e9 para \u201cpromover a paz e a dignidade humana\u201d.<\/p>\n<p>Uma fonte do Departamento de Estado descreveu \u00e0 ag\u00eancia France-Presse (AFP) que a reuni\u00e3o, que decorreu ap\u00f3s duras cr\u00edticas de Donald Trump ao Papa, foi \u201camig\u00e1vel e construtiva\u201d.<\/p>\n<p>Incomodado com as cr\u00edticas do l\u00edder da Igreja Cat\u00f3lica \u2013 o norte-americano Robert Prevost \u2013 \u00e0 guerra lan\u00e7ada pelos Estados Unidos e Israel contra o Ir\u00e3o e aos respons\u00e1veis pol\u00edticos que \u201cabusam da mensagem crist\u00e3\u201d para justificar interven\u00e7\u00f5es militares, o Presidente republicano <a href=\"https:\/\/www.publico.pt\/2026\/04\/15\/mundo\/noticia\/vance-defende-trump-aconselha-papa-cuidado-fala-teologia-limitarse-questoes-moralidade-2171274\" target=\"_blank\" rel=\"nofollow noopener\">descreveu o Papa como \u201cterr\u00edvel\u201d<\/a>, amigo da \u201cesquerda radical\u201d, \u201cp\u00e9ssimo em pol\u00edtica externa\u201d e \u201cfraco em mat\u00e9ria de criminalidade\u201d.<\/p>\n<p>Pouco depois de ter criticado o Papa Le\u00e3o XIV, no m\u00eas passado, Trump publicou nas redes sociais uma imagem de intelig\u00eancia artificial, que depois apagou, em que <a href=\"https:\/\/www.publico.pt\/2026\/04\/13\/mundo\/noticia\/donald-trump-publicou-imagem-surge-retratado-jesus-verdadeiro-2171026\" target=\"_blank\" rel=\"nofollow noopener\">surgia retratado como Jesus Cristo<\/a>, com a luz numa m\u00e3o e a outra sobre a testa de um homem deitado.<\/p>\n<p>Esta visita de Rubio ao Vaticano foi, por isso, descrita pela imprensa italiana como uma tentativa do Governo dos EUA de \u201c<a href=\"https:\/\/www.publico.pt\/2026\/05\/06\/mundo\/noticia\/marco-rubio-recebido-papa-meloni-tentativa-apaziguar-relacoes-2173733\" target=\"_blank\" rel=\"nofollow noopener\">apaziguar as rela\u00e7\u00f5es<\/a>\u201d entre a Casa Branca e a Santa S\u00e9.<\/p>\n<p>No in\u00edcio desta semana, por\u00e9m, Trump voltou \u00e0 carga, afirmando que \u201co Papa est\u00e1 a p\u00f4r em perigo muitos cat\u00f3licos e muitas pessoas\u201d porque \u201cn\u00e3o se importa que o Ir\u00e3o tenha uma arma nuclear\u201d.<\/p>\n<p>Le\u00e3o XIV respondeu a Trump, como j\u00e1 fez noutras ocasi\u00f5es, ap\u00f3s ser questionado por jornalistas: \u201cA miss\u00e3o da Igreja \u00e9 proclamar o Evangelho, pregar a paz. Se algu\u00e9m quiser criticar-me por proclamar o Evangelho, que o fa\u00e7a com a verdade\u201d, disse.<\/p>\n<p>O Vaticano ainda n\u00e3o fez qualquer declara\u00e7\u00e3o ap\u00f3s a audi\u00eancia \u00e0 porta fechada, que durou cerca de 45 minutos.<\/p>\n<p>Depois do encontro com o Papa, Rubio reuniu-se com o secret\u00e1rio de Estado e \u201cn\u00famero dois\u201d da Santa S\u00e9, o cardeal Pietro Parolin.<\/p>\n<p>\u201cAnalisaram os esfor\u00e7os humanit\u00e1rios em curso no Hemisf\u00e9rio Ocidental e as iniciativas para alcan\u00e7ar uma paz duradoura no M\u00e9dio Oriente\u201d, afirmou o Departamento de Estado, num outro comunicado, explicando que a troca de ideias entre Rubio e o Papa \u201cforam um testemunho da forte e cont\u00ednua parceria entre os EUA e a Santa S\u00e9 em apoio \u00e0 liberdade religiosa\u201d.<\/p>\n<p>Marco Rubio encontra-se na sexta-feira com Giorgia Meloni, primeira-ministra de It\u00e1lia e aliada de Trump dentro do movimento internacional da direita radical, que, n\u00e3o obstante, <a href=\"https:\/\/www.publico.pt\/2026\/04\/19\/mundo\/noticia\/meloni-admoestar-trump-acabou-saco-lideres-europeus-2171624\" target=\"_blank\" rel=\"nofollow noopener\">condenou as cr\u00edticas<\/a> ao Papa, dizendo que os coment\u00e1rios do Presidente norte-americano sobre ele s\u00e3o \u201cinaceit\u00e1veis\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"O Papa Le\u00e3o XIV e Marco Rubio debateram esta quinta-feira a situa\u00e7\u00e3o no M\u00e9dio Oriente num encontro no&hellip;\n","protected":false},"author":2,"featured_media":372960,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[27,28,637,92,413,15,16,14,545,25,26,21,22,18507,62,12,13,19,20,811,542,23,24,17,18,29,30,31,5598,63,64,65],"class_list":{"0":"post-372959","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mundo","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-diplomacia","11":"tag-donald-trump","12":"tag-eua","13":"tag-featured-news","14":"tag-featurednews","15":"tag-headlines","16":"tag-igreja-catolica","17":"tag-latest-news","18":"tag-latestnews","19":"tag-main-news","20":"tag-mainnews","21":"tag-marco-rubio","22":"tag-mundo","23":"tag-news","24":"tag-noticias","25":"tag-noticias-principais","26":"tag-noticiasprincipais","27":"tag-papa-leao-xiv","28":"tag-para-redes","29":"tag-principais-noticias","30":"tag-principaisnoticias","31":"tag-top-stories","32":"tag-topstories","33":"tag-ultimas","34":"tag-ultimas-noticias","35":"tag-ultimasnoticias","36":"tag-vaticano","37":"tag-world","38":"tag-world-news","39":"tag-worldnews"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/372959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=372959"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/372959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/372960"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=372959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=372959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=372959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}