{"id":374542,"date":"2026-05-09T04:00:19","date_gmt":"2026-05-09T04:00:19","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/374542\/"},"modified":"2026-05-09T04:00:19","modified_gmt":"2026-05-09T04:00:19","slug":"billie-eilish-defende-que-comer-carne-e-errado-e-desafia-vao-ver-imagens-daquilo-que-acontece-aos-animais-que-dizem-que-amam","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/374542\/","title":{"rendered":"Billie Eilish defende que \u201ccomer carne \u00e9 errado\u201d e desafia: \u201cV\u00e3o ver imagens daquilo que acontece aos animais que dizem que amam\u201d"},"content":{"rendered":"<p class=\"MsoNormal\"><strong>Billie Eilish<\/strong> reagiu \u00e0s cr\u00edticas que lhe foram dirigidas depois de ter dito numa entrevista com a revista \u201cElle\u201d que <strong>\u201ccomer carne \u00e9 errado\u201d<\/strong>. A artista norte-americana, que \u00e9 <strong>vegetariana desde os 12 anos<\/strong>, partilhou imagens de animais em matadouros no Instagram e escreveu um texto no qual <strong>desafia as pessoas que dizem ser amantes de animais a ver document\u00e1rios<\/strong> sobre o assunto.<\/p>\n<p class=\"MsoNormal\">\u201cVejam imagens daquilo que acontece aos animais que dizem que amam e do que isso provoca no planeta que tamb\u00e9m fingem amar\u201d, come\u00e7ou por escrever Eilish, \u201cestou muito <strong>cansada de ser pol\u00e9mica por defender e ter empatia por seres vivos<\/strong>. Continuem a viver nesse estado de disson\u00e2ncia cognitiva e nega\u00e7\u00e3o e tentem convencer-se de que n\u00e3o est\u00e3o a viver uma mentira\u201d.<\/p>\n<p class=\"MsoNormal\">Na entrevista \u00e0 \u201cElle\u201d, a artista j\u00e1 tinha dito: \u201cH\u00e1 duas coisas que n\u00e3o podem coincidir: \u2018Adoro tanto os animais\u2019 e \u2018como carne\u2019. Desculpem\u2026 <strong>podem comer carne \u00e0 vontade e podem amar animais, mas n\u00e3o podem ter as duas coisas<\/strong>\u201d. <\/p>\n<p class=\"MsoNormal\">Estreou esta semana nas salas de cinemas o <strong>filme-concerto \u201cBillie Eilish \u2013 Hit Me Hard and Soft: The Tour (Live in 3D)\u201d<\/strong>, com realiza\u00e7\u00e3o conjunta da artista norte-americana e de <strong>James Cameron<\/strong>, cineasta de \u2018blockbusters\u2019 como \u201cTitanic\u201d ou \u201cAvatar\u201d. A BLITZ assistiu ao filme e encontrou um <a href=\"https:\/\/expresso.pt\/blitz\/historias\/2026-05-07-vimos-billie-eilish-em-3d-pela-lente-de-james-cameron-se-e-para-ir-a-um-concerto-no-cinema-entao-que-seja-sempre-assim-b93634eb\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">retrato \u00edntimo e pormenorizado de um espet\u00e1culo visualmente minimalista, mas emocionalmente maximizado<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Billie Eilish reagiu \u00e0s cr\u00edticas que lhe foram dirigidas depois de ter dito numa entrevista com a revista&hellip;\n","protected":false},"author":2,"featured_media":374543,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[145],"tags":[211,210,114,115,32,33],"class_list":{"0":"post-374542","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-celebridades","8":"tag-celebridades","9":"tag-celebrities","10":"tag-entertainment","11":"tag-entretenimento","12":"tag-portugal","13":"tag-pt"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116542624621564923","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/374542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=374542"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/374542\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/374543"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=374542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=374542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=374542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}