{"id":374623,"date":"2026-05-09T06:20:57","date_gmt":"2026-05-09T06:20:57","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/374623\/"},"modified":"2026-05-09T06:20:57","modified_gmt":"2026-05-09T06:20:57","slug":"homem-que-vendeu-droga-em-barcelos-e-esposende-durante-12-anos-nao-vai-preso","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/374623\/","title":{"rendered":"Homem que vendeu droga em Barcelos e Esposende durante 12 anos n\u00e3o vai preso"},"content":{"rendered":"<p>O Tribunal de Braga condenou, quarta-feira, um homem de 30 anos, de Barcelos a cinco anos de pris\u00e3o, suspensos na sua execu\u00e7\u00e3o, pela pr\u00e1tica dos crimes de tr\u00e1fico de estupefacientes, deten\u00e7\u00e3o de arma proibida e coa\u00e7\u00e3o e resist\u00eancia sobre funcion\u00e1rio, no caso um militar da GNR.<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n<p>O condenado ter\u00e1 de se sujeitar a um \u2018regime de prova\u2019 assente num plano de reinser\u00e7\u00e3o social que envolve a proibi\u00e7\u00e3o de consumir produtos estupefacientes e de frequentar locais conotados com esse consumo e\/ou tr\u00e1fico de subst\u00e2ncias estupefacientes, sujeitando-se a testes de despistagem sempre que assim for determinado pela Dire\u00e7\u00e3o Geral de Reinser\u00e7\u00e3o Social para efeitos de fiscaliza\u00e7\u00e3o.<\/p>\n<p>O coletivo de ju\u00edzes obriga-o, ainda, a iniciar o tratamento que lhe seja prescrito para a sua toxicodepend\u00eancia e para doen\u00e7a mental (tratamento psiqui\u00e1trico) \u2013 j\u00e1 consentido \u2013, comparecendo \u00e0s consultas agendadas e cumprindo os planos terap\u00eauticos institu\u00eddos, podendo tal tratamento implicar o seu internamento em institui\u00e7\u00e3o adequada para o efeito, caso se mostre necess\u00e1rio.<\/p>\n<p>Imp\u00f5e-lhe, ainda, a procura de uma ocupa\u00e7\u00e3o profissional a tempo inteiro e organiza\u00e7\u00e3o e estrutura\u00e7\u00e3o do tempo dispon\u00edvel.<\/p>\n<p>Vendeu entre 2013 e 2025<\/p>\n<p>O ac\u00f3rd\u00e3o judicial d\u00e1 como provado que, pelo menos desde 2013 at\u00e9 maio de 2025, o arguido dedicou-se \u00e0 venda de produtos estupefacientes a terceiros, designadamente coca\u00edna, can\u00e1bis e MDMA, fazendo-o mediante contrapartida monet\u00e1ria ou outra.<\/p>\n<p>Para o efeito, era contactado previamente pelos consumidores, principalmente atrav\u00e9s da rede social Facebook Messenger, onde lhe davam a conhecer da sua pretens\u00e3o.<\/p>\n<p>A\u00ed \u2013 diz a senten\u00e7a \u2013 uma vez estabelecido o tipo e quantidade de estupefaciente a serem transaccionados, eram ent\u00e3o encetados os necess\u00e1rios acertos de hora e local, para assim se ver consumada a transac\u00e7\u00e3o.<\/p>\n<p>Essas transa\u00e7\u00f5es \u201cocorriam nos mais variados locais da freguesia de Vila Seca, Barqueiros, Gilmonde, Cristelo ou Barcelinhos, todas do concelho de Barcelos, em v\u00e1rias freguesias do concelho de Esposende, nomeadamente, Esposende, Fonte Boa Rio Tinto, mas, maioritariamente, junto da resid\u00eancia do arguido, em Vila Seca, Barcelos\u201d. <\/p>\n<p>Nas suas desloca\u00e7\u00f5es fazia uso de um ve\u00edculo BMW, ou, mais raramente, de um da marca Renault, modelo Megane, de cor branca.<\/p>\n<p>No entanto, \u2013 anota o coletivo de ju\u00edzes \u2013 na grande maioria das situa\u00e7\u00f5es, eram os consumidores que se deslocavam at\u00e9 junto da resid\u00eancia do arguido para concretizarem as transa\u00e7\u00f5es.<\/p>\n<p>Uma vez nesse local, estacionavam o ve\u00edculo em que se faziam transportar junto, ou nas imedia\u00e7\u00f5es, da resid\u00eancia do arguido e aguardavam que este \u00faltimo fosse ao seu encontro para assim consumarem a compra do estupefaciente pretendido.<\/p>\n<p>Em outras ocasi\u00f5es, os compradores eram informados de antem\u00e3o pelo arguido de que o estupefaciente pretendido se encontrava depositado no interior da caixa de correio, ou em um vaso pr\u00f3ximo, pelo que bastava pegarem nesse estupefaciente, e deixar o dinheiro correspondente no interior da caixa de correio.<\/p>\n<p>Escondia a droga em locais ermos<\/p>\n<p>Para al\u00e9m disso, o arguido deslocava-se a locais ermos, a fim de depositar e esconder o produto estupefaciente, assim como outros objetos relacionados com essa atividade. <\/p>\n<p>Como aconteceu no dia 22 de outubro de 2024, em que o arguido se deslocou \u00e0 Rua de Pontizelas, Vila Seca, Barcelos, mais propriamente para um caminho em terra que d\u00e1 acesso a terrenos de cultivo e florestais, e ainda, noutras ocasi\u00f5es, num terreno cont\u00edguo \u00e0 sua resid\u00eancia, que fica situado nas traseiras da casa, indo busc\u00e1-lo durante o dia e escondendo-o durante a noite.<\/p>\n","protected":false},"excerpt":{"rendered":"O Tribunal de Braga condenou, quarta-feira, um homem de 30 anos, de Barcelos a cinco anos de pris\u00e3o,&hellip;\n","protected":false},"author":2,"featured_media":374624,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[27,28,15,16,14,25,26,21,22,12,13,19,20,32,23,24,33,17,18,29,30,31],"class_list":{"0":"post-374623","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-portugal","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-featured-news","11":"tag-featurednews","12":"tag-headlines","13":"tag-latest-news","14":"tag-latestnews","15":"tag-main-news","16":"tag-mainnews","17":"tag-news","18":"tag-noticias","19":"tag-noticias-principais","20":"tag-noticiasprincipais","21":"tag-portugal","22":"tag-principais-noticias","23":"tag-principaisnoticias","24":"tag-pt","25":"tag-top-stories","26":"tag-topstories","27":"tag-ultimas","28":"tag-ultimas-noticias","29":"tag-ultimasnoticias"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116543179031788007","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/374623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=374623"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/374623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/374624"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=374623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=374623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=374623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}