{"id":374637,"date":"2026-05-09T06:42:24","date_gmt":"2026-05-09T06:42:24","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/374637\/"},"modified":"2026-05-09T06:42:24","modified_gmt":"2026-05-09T06:42:24","slug":"o-chale-suico-de-1906-da-anne-hathaway-ja-foi-de-yves-saint-laurent-e-wes-anderson-com-fachada-de-pedra-e-bola-de-discoteca-do-inicio-do-seculo-xx-de-um-spa-turco-na-sala","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/374637\/","title":{"rendered":"O chal\u00e9 su\u00ed\u00e7o de 1906 da Anne Hathaway &#8216;j\u00e1 foi&#8217; de Yves Saint Laurent e Wes Anderson: com fachada de pedra e bola de discoteca do in\u00edcio do s\u00e9culo XX de um spa turco na sala"},"content":{"rendered":"<p>\n    De volta com &#8220;O Diabo Veste Prada 2&#8221;, Anne Hathaway define seu ref\u00fagio com Adam Shulman como &#8216;o equil\u00edbrio ideal entre romance e design&#8217;, segundo revista de arquitetura; confira\n<\/p>\n<p><a href=\"https:\/\/www.purepeople.com.br\/noticia\/a-mansao-milionaria-de-denzel-washington-em-beverly-hills-residencia-luxuosa-tem-15-banheiros-quadra-de-tenis-e-ja-sobreviveu-a-incendio_a412978\/1\" rel=\"nofollow noopener\" target=\"_blank\">Quem imagina a casa perfeita de uma estrela de Hollywood<\/a> pode at\u00e9 pensar em algo moderno e minimalista, mas <a href=\"https:\/\/www.purepeople.com.br\/famosos\/anne-hathaway_p1308\" rel=\"nofollow noopener\" target=\"_blank\"><strong>Anne Hathaway<\/strong> <\/a>prova exatamente o contr\u00e1rio. A atriz vencedora do Oscar, <a href=\"https:\/\/www.purepeople.com.br\/noticia\/anne-hathaway-idade-aos-43-anos-andrea-andy-de-o-diabo-veste-prada-2-e-o-segredo-da-beleza-e-longevidade-parei-de-me-interessar-por-viver-travada_a419408\/1\" rel=\"nofollow noopener\" target=\"_blank\">atualmente de volta ao papel de <strong>Andy Sachs<\/strong> em &#8220;O Diabo Veste Prada 2&#8221;<\/a>, e seu marido, o designer de joias <strong>Adam Shulman<\/strong>, vivem em um verdadeiro conto de fadas arquitet\u00f4nico na Calif\u00f3rnia, com direito a refer\u00eancias hist\u00f3ricas, toques fashion e uma boa dose de imagina\u00e7\u00e3o.<\/p>\n<p>As informa\u00e7\u00f5es foram reveladas pela revista <strong>Architectural Digest<\/strong>, em reportagem assinada por <strong>Mayer Rus<\/strong>, com fotos de <strong>Stephen Kent Johnson<\/strong> e styling de <strong>Michael Reynolds<\/strong>.<\/p>\n<p>Avaliadas em + de R$ 100 milh\u00f5es e com vista privilegiada para a Lagoa: como s\u00e3o as mans\u00f5es de Eike Batista e Luma de Oliveira, vizinhos em Jardim Pernambuco, condom\u00ednio de casas de alt\u00edssimo luxo no Leblon<\/p>\n<p>Uma casa com passado digno de cinema<\/p>\n<p>Constru\u00edda originalmente em 1906, a resid\u00eancia em estilo chal\u00e9 su\u00ed\u00e7o carrega uma hist\u00f3ria curiosa. Segundo a narrativa imaginada pelos pr\u00f3prios moradores, o im\u00f3vel teria passado pelas m\u00e3os de ningu\u00e9m menos que <strong>Yves Saint Laurent<\/strong> e, posteriormente, do cineasta <strong>Wes Anderson<\/strong>, conhecido por seu estilo visual \u00fanico.<\/p>\n<p>Como se n\u00e3o bastasse, ainda de acordo com a narrativa ficcional do casal, o local inclui hist\u00f3rias de festas de Ano Novo organizadas pelo pr\u00f3prio <strong>Wes<\/strong> e por <strong>David Bowie<\/strong>, criando uma aura quase cinematogr\u00e1fica em torno do im\u00f3vel. Mesmo sendo uma narrativa criativa, o casal abra\u00e7ou totalmente essa proposta durante a renova\u00e7\u00e3o.<\/p>\n<p>Reforma com assinatura e muita personalidade<\/p>\n<p>Para transformar o espa\u00e7o, <strong>Anne Hathaway<\/strong> e <strong>Adam Shulman<\/strong> contaram com a designer <strong>Pamela Shamshiri<\/strong>, do Studio Shamshiri. A proposta foi clara desde o in\u00edcio: preservar o charme original e adicionar camadas de cor, textura e hist\u00f3ria.<\/p>\n<blockquote>\n<p>&#8220;Esta casa inspirou discuss\u00f5es criativas malucas&#8221;, contou a atriz \u00e0 publica\u00e7\u00e3o.\u00a0<\/p>\n<\/blockquote>\n<p>J\u00e1 <strong>Adam Shulman<\/strong> destacou que o resultado trouxe \u00a0&#8220;sofistica\u00e7\u00e3o, magia e divers\u00e3o&#8221;.<\/p>\n<p>A arquitetura original, assinada por <strong>Myron Hunt<\/strong> e <strong>Elmer Grey<\/strong>, j\u00e1 era um espet\u00e1culo \u00e0 parte. E foi justamente essa base hist\u00f3rica que serviu como ponto de partida para a cria\u00e7\u00e3o de ambientes que misturam diferentes \u00e9pocas.<\/p>\n<p>O detalhe mais inusitado da casa<\/p>\n<p>Se tem um elemento que chama aten\u00e7\u00e3o imediatamente \u00e9 a sala de m\u00fasica. O espa\u00e7o, que originalmente funcionava como sal\u00e3o de dan\u00e7a, ganhou uma pe\u00e7a surpreendente: uma bola de discoteca do in\u00edcio do s\u00e9culo XX, vinda de um spa turco.<\/p>\n<p>O ambiente ainda conta com piano, m\u00f3veis sofisticados e \u00e1reas aconchegantes para receber amigos. &#8220;Este \u00e9 o cora\u00e7\u00e3o da casa&#8221;, revelou <strong>Anne Hathaway<\/strong>, destacando a import\u00e2ncia do espa\u00e7o para encontros e momentos especiais.<\/p>\n<p>Romance \u00e0 primeira vista<\/p>\n<p>O casal descreve a compra da casa como um verdadeiro caso de amor.\u00a0<\/p>\n<blockquote>\n<p>&#8220;Quando vimos a vista panor\u00e2mica pela primeira vez, ficamos completamente encantados&#8221;, lembrou <strong>Adam Shulman<\/strong>.<\/p>\n<\/blockquote>\n<p>Para a atriz, o im\u00f3vel representa mais do que est\u00e9tica.\u00a0<\/p>\n<blockquote>\n<p>&#8220;Era o equil\u00edbrio ideal entre romance e design. Eu conseguia imaginar nossa fam\u00edlia crescendo aqui&#8221;, afirmou.<\/p>\n<\/blockquote>\n<p>Outro destaque da decora\u00e7\u00e3o \u00e9 o uso ousado de cores. Tons de p\u00eassego, bord\u00f4 e rosa aparecem em diferentes ambientes, refletindo o gosto pessoal do casal. Segundo <strong>Pamela Shamshiri<\/strong>, refer\u00eancias da moda tamb\u00e9m foram incorporadas ao projeto, incluindo uma camisa da <strong>Gucci<\/strong> e at\u00e9 a ic\u00f4nica capa amarela usada por <strong>Rihanna<\/strong> no Met Gala de 2015, que inspirou tecidos e detalhes da casa.<\/p>\n<p>Um ref\u00fagio entre o sil\u00eancio e a celebra\u00e7\u00e3o<\/p>\n<p>Apesar do visual impactante, o verdadeiro diferencial da casa est\u00e1 na sua atmosfera. O espa\u00e7o consegue ser ao mesmo tempo acolhedor e expansivo.<\/p>\n<blockquote>\n<p>&#8220;Quando estamos s\u00f3 n\u00f3s, a casa parece silenciosa e contemplativa. Quando recebemos amigos, ela se transforma completamente&#8221;, explicou <strong>Adam Shulman<\/strong>.<\/p>\n<\/blockquote>\n<p>J\u00e1 <strong>Anne Hathaway<\/strong> resumiu a experi\u00eancia de forma sens\u00edvel: &#8220;\u00c9 um lugar que equilibra isolamento e conviv\u00eancia. Aqui, encontro inspira\u00e7\u00e3o tanto no sil\u00eancio quanto na energia das pessoas&#8221;.<\/p>\n<p>        <img decoding=\"async\" class=\"thumb-img-100 thumb-img\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/05\/6e88bca83723d2dd-320x180-1.jpg\" alt=\"Venda cancelada: mans\u00e3o de R$ 10 milh\u00f5es que Marina Ruy Barbosa deu aos pais \u00e9 colocada \u00e0 venda, mas reviravolta faz im\u00f3vel de luxo ficar indispon\u00edvel; entenda!\" width=\"320\" height=\"180\" loading=\"lazy\" role=\"presentation\"\/><\/p>\n<p>                                            Venda cancelada: mans\u00e3o de R$ 10 milh\u00f5es que Marina Ruy Barbosa deu aos pais \u00e9 colocada \u00e0 venda, mas reviravolta faz im\u00f3vel de luxo ficar indispon\u00edvel; entenda!<\/p>\n<p>        <img decoding=\"async\" class=\"thumb-img-100 thumb-img\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/05\/3d1b94967e8e56f1-320x180-1.jpg\" alt=\"Nem S\u00e3o Paulo, nem Goi\u00e2nia: Maiara e Maraisa trocaram a vida na cidade por uma nova mans\u00e3o no interior com heliponto, piscina de borda infinita e floresta ao redor. Fotos!\" width=\"320\" height=\"180\" loading=\"lazy\" role=\"presentation\"\/><\/p>\n<p>                                            Nem S\u00e3o Paulo, nem Goi\u00e2nia: Maiara e Maraisa trocaram a vida na cidade por uma nova mans\u00e3o no interior com heliponto, piscina de borda infinita e floresta ao redor. Fotos!<\/p>\n<p>        <img decoding=\"async\" class=\"thumb-img-100 thumb-img\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/05\/1efb1508467c86c9-320x180-1.png\" alt=\"Cinco su\u00edtes, campo de futebol e muito mais: Ronaldinho Ga\u00facho ofereceu R$ 20 milh\u00f5es por esta mans\u00e3o, mas dono preferiu transform\u00e1-la em cen\u00e1rio de uma novela hist\u00f3rica\" width=\"320\" height=\"180\" loading=\"lazy\" role=\"presentation\"\/><\/p>\n<p>                                            Cinco su\u00edtes, campo de futebol e muito mais: Ronaldinho Ga\u00facho ofereceu R$ 20 milh\u00f5es por esta mans\u00e3o, mas dono preferiu transform\u00e1-la em cen\u00e1rio de uma novela hist\u00f3rica<\/p>\n<p>                <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2025\/10\/0e9ccd35959d299d-35x35-2.jpg\" class=\"author-article-picture\" width=\"35\" height=\"35\"\/><\/p>\n<p>                    Por <\/p>\n<p>                                            Pedro Henrique Cabo<\/p>\n<p>                    |<\/p>\n<p>                                            Colaborador<\/p>\n<p>\n                Geek fashionista que canta &#8216;Let It Go&#8217; no chuveiro, trata &#8216;O Diabo Veste Prada&#8217; como religi\u00e3o e escolheu Piplup como seu inicial. Jornalista metido a designer, cin\u00e9filo de Letterboxd e amante das artes.\n            <\/p>\n","protected":false},"excerpt":{"rendered":"De volta com &#8220;O Diabo Veste Prada 2&#8221;, Anne Hathaway define seu ref\u00fagio com Adam Shulman como &#8216;o&hellip;\n","protected":false},"author":2,"featured_media":374638,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[144],"tags":[207,205,206,203,201,202,204,114,115,32,33],"class_list":{"0":"post-374637","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arte-e-design","8":"tag-arte","9":"tag-arte-e-design","10":"tag-artedesign","11":"tag-arts","12":"tag-arts-and-design","13":"tag-artsanddesign","14":"tag-design","15":"tag-entertainment","16":"tag-entretenimento","17":"tag-portugal","18":"tag-pt"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116543262184171633","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/374637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=374637"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/374637\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/374638"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=374637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=374637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=374637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}