{"id":374882,"date":"2026-05-09T12:31:11","date_gmt":"2026-05-09T12:31:11","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/374882\/"},"modified":"2026-05-09T12:31:11","modified_gmt":"2026-05-09T12:31:11","slug":"bruno-fernandes-conquista-inglaterra-imprensa-elege-o-o-melhor-da-epoca-futebol-internacional","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/374882\/","title":{"rendered":"Bruno Fernandes conquista Inglaterra: imprensa elege-o o melhor da \u00e9poca | Futebol internacional"},"content":{"rendered":"<p>Bruno Fernandes, capit\u00e3o do Manchester United, acaba de ser distinguido como melhor futebolista da Liga inglesa em 2025\/26 pela Associa\u00e7\u00e3o de Jornalistas Desportivos (FWA) local.<\/p>\n<p>Em comunicado divulgado neste s\u00e1bado, a associa\u00e7\u00e3o informou que o internacional portugu\u00eas foi o \u00fanico jogador dos \u201cred devils\u201d a ser nomeado e recebeu 45% das prefer\u00eancias dos mais de 900 eleitores, ficando \u00e0 frente do m\u00e9dio Declan Rice, do Arsenal, e do avan\u00e7ado noruegu\u00eas Erling Haaland, do Manchester City.<\/p>\n<p>Bruno Fernandes, de 31 anos, soma oito golos e 20 assist\u00eancias nos 34 encontros disputados nesta \u00e9poca nas diversas competi\u00e7\u00f5es pelo Manchester United, clube a que chegou em Janeiro de 2020, proveniente do Sporting.<\/p>\n<p>S\u00f3 nas 32 partidas na Premier League, o m\u00e9dio <a href=\"https:\/\/www.publico.pt\/2025\/04\/04\/desporto\/noticia\/bruno-fernandes-vence-jogador-mes-juntase-historicos-premier-league-2128557\" target=\"_self\" rel=\"nofollow noopener\">marcou por oito vezes e fez 19 passes para golo,<\/a> estando a uma assist\u00eancia de igualar o recorde numa edi\u00e7\u00e3o, fixado pelo avan\u00e7ado franc\u00eas Thierry Henry em 2002\/03, ao servi\u00e7o do Arsenal, e pelo m\u00e9dio belga Kevin De Bruyne em 2019\/20, com o Manchester City.<\/p>\n<p>\u201cEstou muito feliz pelo Bruno Fernandes, que merece muito. N\u00e3o acho que seja necessariamente focado em pr\u00e9mios individuais. \u00c9 um jogador de equipa e demonstra-o com a sua lideran\u00e7a\u201d, disse o treinador do Manchester United, Michael Carrick, que sucedeu ao portugu\u00eas Ruben Amorim em Janeiro, ap\u00f3s a transi\u00e7\u00e3o interina com o escoc\u00eas Darren Fletcher.<\/p>\n<p>Bruno Fernandes tornou-se o terceiro jogador portugu\u00eas a ser distinguido pela FWA, cujo galard\u00e3o \u00e9 atribu\u00eddo desde 1947\/48 e j\u00e1 foi recebido por <a href=\"https:\/\/www.publico.pt\/2007\/05\/04\/desporto\/noticia\/cristiano-ronaldo-eleito-melhor-futebolista-do-ano-pelos-jornalistas-ingleses-1292962\" target=\"_self\" rel=\"nofollow noopener\">Cristiano Ronaldo<\/a>, ent\u00e3o avan\u00e7ado do Manchester United, em 2006\/07 e 2007\/08, e <a href=\"https:\/\/www.publico.pt\/2021\/06\/05\/desporto\/noticia\/ruben-dias-eleito-melhor-jogador-premier-league-1965396\" target=\"_self\" rel=\"nofollow noopener\">R\u00faben Dias<\/a>, defesa central do Manchester City, em 2020\/21.<\/p>\n<p>Nono futebolista dos \u2018red devils\u2019 a ser premiado, e primeiro desde 2009\/10, quando Wayne Rooney arrebatou a elei\u00e7\u00e3o, Bruno Fernandes sucedeu ao eg\u00edpcio Mohamed Salah, campe\u00e3o ingl\u00eas pelo Liverpool na \u00e9poca passada.<\/p>\n<p>Nos \u00faltimos anos, o jogador portugu\u00eas foi agraciado com v\u00e1rias distin\u00e7\u00f5es: em Mar\u00e7o de 2025, foi eleito jogador do m\u00eas da Liga inglesa, pr\u00e9mio que obteve pela quinta vez e que deixou o m\u00e9dio entre os futebolistas hist\u00f3ricos da Premier League. Em 2023, o internacional portugu\u00eas foi o <a href=\"https:\/\/www.publico.pt\/2023\/12\/06\/desporto\/noticia\/bruno-fernandes-futebolista-europa-tempo-jogo-2023-2072781\" target=\"_self\" rel=\"nofollow noopener\">futebolista a actuar na Europa com mais tempo de jogo<\/a>, entre clube e selec\u00e7\u00e3o.<\/p>\n<p>Mais recentemente, Fernandes bateu o recorde de assist\u00eancias numa s\u00f3 \u00e9poca no Manchester United consagrado por David Beckham em 1999\/2000, ao fazer passes decisivos nos dois primeiros golos do triunfo sobre o Aston Villa (3-2), na 30.\u00aa jornada da Liga inglesa, <a href=\"https:\/\/www.publico.pt\/2026\/03\/15\/desporto\/noticia\/bruno-fernandes-bate-recorde-assistencias-man-united-ultrapassando-beckham-2167970\" target=\"_self\" rel=\"nofollow noopener\">em Mar\u00e7o deste ano<\/a>.<\/p>\n<p>A tr\u00eas jornadas do fim do campeonato, o Manchester United, que tamb\u00e9m integra o portugu\u00eas Diogo Dalot no plantel, ocupa o terceiro lugar e tem 64 pontos, estando qualificado para a fase de liga da Liga dos Campe\u00f5es, ap\u00f3s duas temporadas de aus\u00eancia da principal prova europeia de clubes.<\/p>\n<p>Os \u2018red devils\u2019 n\u00e3o estiveram nas competi\u00e7\u00f5es continentais em 2025\/26 e v\u00e3o terminar a \u00e9poca sem trof\u00e9us pela segunda vez consecutiva, uma vez que, al\u00e9m da impossibilidade de alcan\u00e7arem o l\u00edder isolado Arsenal na Premier League, perderam frente ao primodivision\u00e1rio Brighton na terceira ronda da Ta\u00e7a de Inglaterra e cederam com o Grimsby Town, do quarto escal\u00e3o, na segunda eliminat\u00f3ria da Ta\u00e7a da Liga, atrav\u00e9s do desempate por pen\u00e1ltis.<\/p>\n","protected":false},"excerpt":{"rendered":"Bruno Fernandes, capit\u00e3o do Manchester United, acaba de ser distinguido como melhor futebolista da Liga inglesa em 2025\/26&hellip;\n","protected":false},"author":2,"featured_media":374883,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87],"tags":[135,524,138,7972,663,32,666,33,134],"class_list":{"0":"post-374882","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-desporto","8":"tag-desporto","9":"tag-futebol","10":"tag-futebol-internacional","11":"tag-liga-inglesa","12":"tag-manchester-united","13":"tag-portugal","14":"tag-premier-league","15":"tag-pt","16":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116544634138736328","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/374882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=374882"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/374882\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/374883"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=374882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=374882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=374882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}