{"id":375087,"date":"2026-05-09T16:22:11","date_gmt":"2026-05-09T16:22:11","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/375087\/"},"modified":"2026-05-09T16:22:11","modified_gmt":"2026-05-09T16:22:11","slug":"documentario-explora-bem-faceta-niponica-do-idolo-zico-09-05-2026-ilustrissima","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/375087\/","title":{"rendered":"Document\u00e1rio explora bem faceta nip\u00f4nica do \u00eddolo Zico &#8211; 09\/05\/2026 &#8211; Ilustr\u00edssima"},"content":{"rendered":"<p><strong>[RESUMO]<\/strong> Entre acertos e op\u00e7\u00f5es discut\u00edveis, document\u00e1rio &#8220;Zico, o Samurai de Quintino&#8221; tenta ir al\u00e9m de ser um filme para torcedor ou apenas registro de grandes lances nas partidas, investigando aspectos pouco conhecidos da vida do grande jogador e sua decis\u00e3o enigm\u00e1tica de jogar em um obscuro time japon\u00eas no fim da carreira.<\/p>\n<p>A passagem mais do\u00edda do filme &#8220;Zico, o Samurai de Quintino&#8221;, de <a href=\"https:\/\/www1.folha.uol.com.br\/colunas\/joao-wainer\/\" rel=\"nofollow noopener\" target=\"\">Jo\u00e3o Wainer,<\/a> \u00e9 aquela em que ele reafirma seu arrependimento por ter aceitado a convoca\u00e7\u00e3o para a<a href=\"https:\/\/www1.folha.uol.com.br\/folha\/especial\/2002\/copa\/historia-1986.shtml\" rel=\"nofollow noopener\" target=\"\"> Copa do Mundo de 1986<\/a>, no M\u00e9xico. &#8220;Meu cora\u00e7\u00e3o dizia que n\u00e3o deveria ir&#8221;, declara, reconhecendo sua falta de condi\u00e7\u00f5es f\u00edsicas.<\/p>\n<p><a href=\"https:\/\/www1.folha.uol.com.br\/folha-topicos\/zico\/\" rel=\"nofollow noopener\" target=\"\">O maior \u00eddolo da hist\u00f3ria do Flamengo<\/a> e um dos grandes do <a href=\"https:\/\/www1.folha.uol.com.br\/folha-topicos\/futebol\/\" rel=\"nofollow noopener\" target=\"_blank\">futebol<\/a> brasileiro e internacional havia sido v\u00edtima de uma entrada criminosa do zagueiro M\u00e1rcio Nunes, do Bangu, em 29 de agosto de 1985, no Maracan\u00e3, durante um jogo do Campeonato Carioca.<\/p>\n<p>Ele tinha 32 anos e vinha de duas temporadas bem-sucedidas na Udinese, na It\u00e1lia, depois de ter participado da gl\u00f3ria m\u00e1xima de vencer o<a href=\"https:\/\/www1.folha.uol.com.br\/esporte\/2019\/12\/derrotado-pelo-flamengo-liverpool-chegou-bebado-ao-mundial-de-1981.shtml\" rel=\"nofollow noopener\" target=\"\"> Liverpool por 3 x 0, em dezembro de 81<\/a>, em T\u00f3quio, na disputa do que se considerava e considera o mundial de clubes.<\/p>\n<p>Naquela Copa de 1986, a dimens\u00e3o tr\u00e1gica da carreira do craque se apresentou por inteira. Ele perdeu um p\u00eanalti na partida em que o Brasil foi eliminado pela Fran\u00e7a, o que lhe valeu um injusto estigma. Paralelamente, <a href=\"https:\/\/www1.folha.uol.com.br\/esporte\/2020\/11\/diego-maradona-morre-aos-60-anos-diz-imprensa-argentina.shtml\" rel=\"nofollow noopener\" target=\"\">Diego Maradona, o maior rival na Am\u00e9rica do Sul, sa\u00eda endeusado do torneio, vencido pela Argentina.<\/a><\/p>\n<p>A grav\u00edssima les\u00e3o no joelho esquerdo levou Zico a um penoso e atribulado final de carreira, numa trajet\u00f3ria marcada por grandes vit\u00f3rias, mas n\u00e3o a que teria sido a maior. Esse signo tr\u00e1gico, a ecoar um pouco da vida que poderia ter sido mas n\u00e3o foi, do poeta Bandeira, talvez tenha levado o famoso Galinho de Quintino a buscar uma segunda grande rodada existencial.<\/p>\n<p>Sugestivamente ele iria busc\u00e1-la no Jap\u00e3o, o pa\u00eds onde levantou o inesquec\u00edvel t\u00edtulo de 81. Dez anos depois, em 1991, com 38 anos, desembarcava em Kashima contratado pelo obscuro<a href=\"https:\/\/www1.folha.uol.com.br\/fsp\/esporte\/fk2206200617.htm\" rel=\"nofollow noopener\" target=\"\"> Sumitomo Metals<\/a>, um time de f\u00e1brica que disputava a segunda divis\u00e3o da liga amadora. A cidade era pequena, isolada e polu\u00edda pela f\u00e1brica, que tentava mudar sua imagem.<\/p>\n<p>A principal quest\u00e3o do document\u00e1rio \u00e9 justamente essa decis\u00e3o enigm\u00e1tica que a todos surpreendeu, a come\u00e7ar por Sandra, sua mulher. O filme relata a saga que levou o time, posteriormente chamado de <a href=\"https:\/\/www1.folha.uol.com.br\/fsp\/esporte\/fk2206200617.htm\" rel=\"nofollow noopener\" target=\"\">Kashima Antlers<\/a>, a tornar-se, sob a lideran\u00e7a de Zico, uma pot\u00eancia do futebol profissional japon\u00eas, al\u00e7ado a um status impens\u00e1vel d\u00e9cadas atr\u00e1s.<\/p>\n<p>N\u00e3o se trata, portanto, de uma produ\u00e7\u00e3o voltada para os grandes lances do craque, uma esp\u00e9cie de colagem de dribles e gols incr\u00edveis, que certamente muitos f\u00e3s, especialmente os flamenguistas, talvez esperem. N\u00e3o ser um filme de torcedor, no sentido mais estrito, foi uma das premissas de Wainer \u2014que \u00e9 santista e em mat\u00e9ria de \u00eddolo tamb\u00e9m n\u00e3o tem do que se queixar.<\/p>\n<p>Sim, uma cole\u00e7\u00e3o de grandes lances est\u00e1 l\u00e1, como o lend\u00e1rio gol de Rondinelli contra o Vasco, na final carioca de 1978, em escanteio cobrado por Zico, o baile em T\u00f3quio, jogadas na Udinese e na sele\u00e7\u00e3o, para n\u00e3o mencionar uma espl\u00eandida sequ\u00eancia de obras-primas em gols de falta. H\u00e1 cenas emocionantes da torcida do <a href=\"https:\/\/www1.folha.uol.com.br\/folha-topicos\/flamengo\/\" rel=\"nofollow noopener\" target=\"_blank\">Flamengo<\/a>, essa religi\u00e3o popular brasileira que come\u00e7ou a ser mais internacional justamente por obra de Zico.<\/p>\n<p>O document\u00e1rio investe em colocar em cena a vida do menino de Quintino, sua forma\u00e7\u00e3o, suas rela\u00e7\u00f5es familiares e amizades. H\u00e1 uma tentativa de v\u00ea-lo por dentro por meio de filmetes desconhecidos de Super 8, fotografias e v\u00eddeos dom\u00e9sticos. Reconstitui-se a aventura em Kashima com depoimentos de personagens da \u00e9poca e jovens torcedores do time.<\/p>\n<p>H\u00e1 tamb\u00e9m um n\u00facleo de conversas sobre a carreira do 10 da G\u00e1vea que re\u00fane nomes como J\u00fanior, Paulo Cesar Carpegiani,<a href=\"https:\/\/www1.folha.uol.com.br\/folha-topicos\/ronaldo\/\" rel=\"nofollow noopener\" target=\"\"> Ronaldo Fen\u00f4meno<\/a> (que diz que Zico sempre foi seu \u00eddolo), al\u00e9m de <a href=\"https:\/\/www1.folha.uol.com.br\/webstories\/esporte\/2026\/02\/a-trajetoria-de-carlos-alberto-parreira\/\" rel=\"nofollow noopener\" target=\"\">Carlos Alberto Parreira<\/a>, em cenas gravadas entre os trof\u00e9us e lembran\u00e7as guardadas pelo jogador.<\/p>\n<p>O flamenguista raiz talvez n\u00e3o preferisse o paulista Mauro Beting como um dos destaques da m\u00eddia no filme, mesmo ao lado do narrador carioca Jos\u00e9 Carlos Araujo \u2014esquecendo-se talvez de que Mauro \u00e9 autor da biografia &#8220;Zico 70&#8221; e profundo conhecedor do personagem. \u00c9 um pre\u00e7o a ser pago pela ideia de fazer um document\u00e1rio que n\u00e3o quer se reivindicar como carioca e flamenguista, com a ambi\u00e7\u00e3o de desvendar, o que faz bem, a faceta nip\u00f4nica do Galinho de Quintino.<\/p>\n<p>Entre acertos e op\u00e7\u00f5es discut\u00edveis, o filme amplia o interesse pela vida de Zico e deixa sua marca no espectador \u2014pelo menos deixou no autor deste coment\u00e1rio, que \u00e9 Flamengo at\u00e9 morrer.<\/p>\n","protected":false},"excerpt":{"rendered":"[RESUMO] Entre acertos e op\u00e7\u00f5es discut\u00edveis, document\u00e1rio &#8220;Zico, o Samurai de Quintino&#8221; tenta ir al\u00e9m de ser um&hellip;\n","protected":false},"author":2,"featured_media":375088,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[140],"tags":[114,115,2089,147,148,2460,236,524,146,21998,32,33,54686],"class_list":{"0":"post-375087","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-filmes","8":"tag-entertainment","9":"tag-entretenimento","10":"tag-esporte","11":"tag-film","12":"tag-filmes","13":"tag-flamengo","14":"tag-folha","15":"tag-futebol","16":"tag-movies","17":"tag-mundial-de-clubes","18":"tag-portugal","19":"tag-pt","20":"tag-zico"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116545542306976554","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/375087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=375087"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/375087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/375088"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=375087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=375087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=375087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}