{"id":377918,"date":"2026-05-11T21:57:13","date_gmt":"2026-05-11T21:57:13","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/377918\/"},"modified":"2026-05-11T21:57:13","modified_gmt":"2026-05-11T21:57:13","slug":"dolorosa-solidao-nem-imagina-como-o-antigo-principe-andre-passa-os-seus-dias-na-quinta-decadente-de-sandringham-mundo","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/377918\/","title":{"rendered":"Dolorosa solid\u00e3o! Nem imagina como o antigo pr\u00edncipe Andr\u00e9 passa os seus dias na quinta decadente de Sandringham &#8211; Mundo"},"content":{"rendered":"<p class=\"\">&#13;<br \/>\n        Face \u00e0 liga\u00e7\u00e3o \u00f3bvia de <b>Andr\u00e9<\/b> ao esc\u00e2ndalo de pedofilia de <b>Jeffrey Epstein<\/b>, o irm\u00e3o, <b>Carlos III<\/b>, retirou-lhe n\u00e3o s\u00f3 os t\u00edtulos reais como todas as regalias, o que implicou que o monarca, de 66 anos, tivesse de se\u00a0despedir da sua imponente <b>mans\u00e3o em Windsor<\/b>, com mais de 30 dormit\u00f3rios, propriedade da Casa Real brit\u00e2nica, e fazer as malas para um novo e mais modesto lar.&#13;\n    <\/p>\n<p class=\"\">&#13;<br \/>\n        No in\u00edcio de abril,\u00a0ficou conclu\u00edda a sua mudan\u00e7a para <b>Marsh Farm<\/b>, na propriedade de Sandringham, uma habita\u00e7\u00e3o muito mais austera,\u00a0 sem luxos e que agora serve de resid\u00eancia permanente a <b>Andr\u00e9 Mountbatten-Windsor<\/b>. O filho preferido da <b>rainha Isabel II <\/b>vive agora uma esp\u00e9cie de ex\u00edlio.&#13;\n    <\/p>\n<p class=\"\">&#13;<br \/>\n        Neste seu isolamento for\u00e7ado, o antigo pr\u00edncipe passa muitas horas sozinho. Uma solid\u00e3o que d\u00f3i, que castiga, que oprime. Sem poder sair de casa (ou n\u00e3o querer sair), <b>Andr\u00e9 Mountbatten-Windsor viu-se a obrigado a encontrar uma forma de &#8220;queimar&#8221; os seus dias.<\/b>&#13;\n    <\/p>\n<p class=\"\">&#13;<br \/>\n        Os v\u00eddeosjogos tornaram-se a sua distra\u00e7\u00e3o di\u00e1ria. Quem o revelou foi\u00a0o especialista em assuntos da realeza Andrew Lownie, que estudou ao detalhe a vida do antigo duque. No podcast &#8216;<b>Palace Confidential<\/b>&#8216; e conforme <a href=\"https:\/\/www.mirror.co.uk\/news\/royals\/andrew-mountbatten-windsor-fascinated-one-37133614\" target=\"_self\" rel=\"tag nofollow noopener\">avan\u00e7ado pelo jornal brit\u00e2nico &#8216;Mirror&#8217;<\/a>, Lownie afirmou que, desde o fim das suas fun\u00e7\u00f5es oficiais, Andr\u00e9 tem sentido falta de uma rotina di\u00e1ria definida. &#8220;<b>Acho que ele precisa de disciplina<\/b>&#8220;, explicou o referido especialista.&#13;\n    <\/p>\n<p class=\"\">&#13;<br \/>\n        Ter\u00e1 encontrado essa disciplina em muitos v\u00eddeojogos de cariz militar: &#8220;<b>Ele \u00e9 absolutamente fascinado por simula\u00e7\u00f5es de aterragem de aeronaves \u2013 isto remonta ao seu treino como piloto<\/b>&#8220;, diz Lownie. A par dos simuladores de voo, o antigo pr\u00edncipe tem passado muitas horas a jogar &#8216;Call of Duty&#8217;. &#8220;Perdeu qualquer prop\u00f3sito na vida&#8221;, acrescenta o especailista que diz que os jogos s\u00e3o para Andr\u00e9 a forma de combater a solid\u00e3o.\u00a0&#13;\n    <\/p>\n<p>        &#13;<br \/>\n            Saber mais sobre&#13;<br \/>\n            &#13;<br \/>\n            &#13;<\/p>\n<p>    &#13;<br \/>\n        &#13;<br \/>\n        &#13;<br \/>\n&#13;<\/p>\n","protected":false},"excerpt":{"rendered":"&#13; Face \u00e0 liga\u00e7\u00e3o \u00f3bvia de Andr\u00e9 ao esc\u00e2ndalo de pedofilia de Jeffrey Epstein, o irm\u00e3o, Carlos III,&hellip;\n","protected":false},"author":2,"featured_media":377919,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[48834,51718,114,115,1874,32,18708,33,2013,43496,22821],"class_list":{"0":"post-377918","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-entretenimento","8":"tag-andre-mountbatten-windsor","9":"tag-andrew-lownie","10":"tag-entertainment","11":"tag-entretenimento","12":"tag-mansao","13":"tag-portugal","14":"tag-principe","15":"tag-pt","16":"tag-realeza","17":"tag-sandringham","18":"tag-solidao"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116558184214302091","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/377918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=377918"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/377918\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/377919"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=377918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=377918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=377918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}