{"id":379093,"date":"2026-05-12T20:02:11","date_gmt":"2026-05-12T20:02:11","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/379093\/"},"modified":"2026-05-12T20:02:11","modified_gmt":"2026-05-12T20:02:11","slug":"portugal-vai-conquistar-um-lugar-na-final-do-festival-da-eurovisao-acompanhe-aqui-a-primeira-semifinal","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/379093\/","title":{"rendered":"Portugal vai conquistar um lugar na final do festival da Eurovis\u00e3o? Acompanhe aqui a primeira semifinal"},"content":{"rendered":"<p class=\"text-paragraph\">Na semifinal de hoje, a primeira, al\u00e9m de Portugal, que atua em quinto lugar, estar\u00e3o em competi\u00e7\u00e3o Mold\u00e1via (com a can\u00e7\u00e3o \u201cViva, Moldova\u201d, interpretada por Satoshi), Su\u00e9cia (\u201cMy System\u201d\/Felicia), Cro\u00e1cia (\u201cAndromeda\u201d\/Lelek), Gr\u00e9cia (\u201cFerto\u201d\/Akylas), Ge\u00f3rgia (\u201cOn Replay\u201d\/Bzikebi), Finl\u00e2ndia (\u201cLiekinheitin\u201d\/ Linda Lampenius &amp; Pete Parkkonen), Montenegro (\u201cNova zora\u201d\/ Tamara \u017divkovi\u0107), Est\u00f3nia (\u201cToo epic to be true\u201d\/V.Ninja), Israel (\u201cMichelle\u201d\/Noam Betten), B\u00e9lgica (\u201cDancing on the ice\u201d\/Essyla), Litu\u00e2nia (\u201cS\u00f3lo quiero m\u00e1s\u201d\/Lion Ceccah), S\u00e3o Marino (\u201cSuperstar\u201d\/Senhit), Pol\u00f3nia (\u201cPray\u201d\/Alicja) e S\u00e9rvia (\u201cKraj mene\u201d\/Lavina).<\/p>\n<p class=\"text-paragraph\">A semifinal abriu com um filme intitulado \u201cBy Your Side for 70 Years\u201d, que assinalou o 70.\u00ba anivers\u00e1rio do festival. O v\u00eddeo recordou alguns momentos da hist\u00f3ria da Eurovis\u00e3o atrav\u00e9s dos olhos de um rapaz austr\u00edaco chamado Toni, que cresce a acompanhar o festival.<\/p>\n<p class=\"text-paragraph\">Dos 15 pa\u00edses apenas dez v\u00e3o passar \u00e0 final, marcada para s\u00e1bado, e, de acordo com a m\u00e9dia de v\u00e1rias casas de apostas, calculada pelo \u2018site\u2019 eurovisionworld.com, especializado no concurso, a passagem de Portugal n\u00e3o \u00e9 certa.<\/p>\n<p class=\"text-paragraph\">A realiza\u00e7\u00e3o de duas semifinais, para apurar os pa\u00edses em competi\u00e7\u00e3o na final, aconteceu pela primeira vez em 2008 e, desde ent\u00e3o, Portugal falhou cinco vezes a passagem: em 2011, 2012, 2014, 2015 e 2019.<\/p>\n<p class=\"text-paragraph\">Al\u00e9m dos pa\u00edses em competi\u00e7\u00e3o, hoje sobem tamb\u00e9m a palco os representantes de It\u00e1lia (\u201cPer sempre s\u00ec\u201d\/Sal Davinci) e Alemanha (\u201cFire\u201d\/Sarah Engels), pa\u00edses que t\u00eam a passagem garantida \u00e0 final, por fazerem parte do grupo dos \u2018Big5\u2019.<\/p>\n<p class=\"text-paragraph\">Na segunda semifinal, na quinta-feira, competem mais 16 pa\u00edses, por outros dez lugares na final: Bulg\u00e1ria, Azerbaij\u00e3o, Rom\u00e9nia, Luxemburgo, Rep\u00fablica Checa, Arm\u00e9nia, Su\u00ed\u00e7a, Chipre, Let\u00f3nia, Dinamarca, Austr\u00e1lia, Ucr\u00e2nia, Alb\u00e2nia, Malta e Noruega.<\/p>\n<p class=\"text-paragraph\">Al\u00e9m disso, ser\u00e3o apresentadas as can\u00e7\u00f5es de outros tr\u00eas pa\u00edses com entrada direta na final: Fran\u00e7a e Reino Unidos, dos \u2018Big5\u2019, e \u00c1ustria, pa\u00eds anfitri\u00e3o da edi\u00e7\u00e3o deste ano.<\/p>\n<p class=\"text-paragraph\">A 70.\u00aa edi\u00e7\u00e3o do Festival Eurovis\u00e3o da Can\u00e7\u00e3o volta a ficar marcada, \u00e0 semelhan\u00e7a das duas anteriores, pela contesta\u00e7\u00e3o \u00e0 participa\u00e7\u00e3o de Israel no concurso, que este ano levou cinco pa\u00edses a desistirem.<\/p>\n<p class=\"text-paragraph\">Este ano s\u00e3o 35 os pa\u00edses em competi\u00e7\u00e3o, ap\u00f3s desist\u00eancias de Espanha (o quinto pa\u00eds do grupo dos \u2018Big5\u2019), Irlanda, Pa\u00edses Baixos, Eslov\u00e9nia e Isl\u00e2ndia, devido \u00e0 participa\u00e7\u00e3o de Israel no concurso, e regressos \u00e0 competi\u00e7\u00e3o da Bulg\u00e1ria, da Rom\u00e9nia e da Mold\u00e1via, ao fim de tr\u00eas, dois e um ano de aus\u00eancia, respetivamente.<\/p>\n<p class=\"text-paragraph\">Os boicotes devem-se aos ataques militares de Israel no territ\u00f3rio palestiniano da Faixa de Gaza, desde outubro de 2023, que mataram pelo menos 72 mil pessoas e foram classificados como genoc\u00eddio por uma comiss\u00e3o internacional independente de investiga\u00e7\u00e3o da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas.<\/p>\n<p class=\"text-paragraph\">Entretanto, na segunda-feira ficou a saber-se que as esta\u00e7\u00f5es p\u00fablicas de Espanha, da Irlanda e da Eslov\u00e9nia decidiram n\u00e3o transmitir este ano o concurso.<\/p>\n<p class=\"text-paragraph\">O grupo esloveno, RTV, anunciou que, em vez do Festival Eurovis\u00e3o da Can\u00e7\u00e3o, ir\u00e1 exibir um programa dedicado ao povo palestiniano, o espanhol RTVE, um evento musical sem liga\u00e7\u00e3o \u00e0 Eurovis\u00e3o, e a cadeia p\u00fablica irlandesa, uma s\u00e9rie.<\/p>\n<p class=\"text-paragraph\">O concurso realiza-se anualmente desde 1956 e j\u00e1 houve pa\u00edses exclu\u00eddos, caso da Bielorr\u00fassia, em 2021, ap\u00f3s a reelei\u00e7\u00e3o do presidente Aleksandr Lukashenko, e da R\u00fassia, em 2022, ap\u00f3s a invas\u00e3o da Ucr\u00e2nia.<\/p>\n<p class=\"text-paragraph\">Israel foi o primeiro pa\u00eds n\u00e3o europeu a poder participar, em 1973, e ganhou quatro vezes.<\/p>\n<p class=\"text-paragraph\">Este ano, voltou a haver v\u00e1rios apelos ao boicote ao concurso devido \u00e0 participa\u00e7\u00e3o de Israel.<\/p>\n","protected":false},"excerpt":{"rendered":"Na semifinal de hoje, a primeira, al\u00e9m de Portugal, que atua em quinto lugar, estar\u00e3o em competi\u00e7\u00e3o Mold\u00e1via&hellip;\n","protected":false},"author":2,"featured_media":379094,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142],"tags":[114,115,32,33,151],"class_list":{"0":"post-379093","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-entertainment","9":"tag-entretenimento","10":"tag-portugal","11":"tag-pt","12":"tag-tv"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116563394269646490","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/379093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=379093"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/379093\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/379094"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=379093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=379093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=379093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}