{"id":379107,"date":"2026-05-12T20:12:25","date_gmt":"2026-05-12T20:12:25","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/379107\/"},"modified":"2026-05-12T20:12:25","modified_gmt":"2026-05-12T20:12:25","slug":"trabalhador-morre-soterrado-em-obra-em-almada","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/379107\/","title":{"rendered":"Trabalhador morre soterrado em obra em Almada"},"content":{"rendered":"<p class=\"category\"><a href=\"https:\/\/sicnoticias.pt\/pais\" rel=\"nofollow noopener\" target=\"_blank\">Pa\u00eds<\/a><\/p>\n<p>Um trabalhador de uma obra na Charneca da Caparica, no concelho de Almada, morreu esta ter\u00e7a-feira soterrado na sequ\u00eancia de um desabamento de terras, disse \u00e0 ag\u00eancia Lusa o Comando Sub-regional de Emerg\u00eancia e Prote\u00e7\u00e3o Civil da Pen\u00ednsula de Set\u00fabal.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/05\/1778616745_849_original.webp\" alt=\"Capacete de obras\"\/><\/p>\n<p>Capacete de obras<\/p>\n<p>Canva<\/p>\n<p>Segundo a mesma fonte, o alerta foi dado \u00e0s 13:23 e no local est\u00e3o 20 operacionais dos bombeiros de Cacilhas, Instituto Nacional de Emerg\u00eancia M\u00e9dica (INEM) e Guarda Nacional Republicana (GNR), apoiados por nove ve\u00edculos.<\/p>\n<p> O \u00f3bito foi declarado no local e o corpo da v\u00edtima ainda est\u00e1 a ser retirado pelas equipas de emerg\u00eancia.<\/p>\n<p> A mesma fonte adiantou que a obra \u00e9 num coletor de \u00e1guas, tendo havido o rebentamento de uma conduta que provocou o desmoronamento das terras.<\/p>\n","protected":false},"excerpt":{"rendered":"Pa\u00eds Um trabalhador de uma obra na Charneca da Caparica, no concelho de Almada, morreu esta ter\u00e7a-feira soterrado&hellip;\n","protected":false},"author":2,"featured_media":379108,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[27,28,15,16,14,25,26,21,22,12,13,19,20,32,23,24,33,17,18,29,30,31],"class_list":{"0":"post-379107","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-principais-noticias","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-featured-news","11":"tag-featurednews","12":"tag-headlines","13":"tag-latest-news","14":"tag-latestnews","15":"tag-main-news","16":"tag-mainnews","17":"tag-news","18":"tag-noticias","19":"tag-noticias-principais","20":"tag-noticiasprincipais","21":"tag-portugal","22":"tag-principais-noticias","23":"tag-principaisnoticias","24":"tag-pt","25":"tag-top-stories","26":"tag-topstories","27":"tag-ultimas","28":"tag-ultimas-noticias","29":"tag-ultimasnoticias"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116563433916062608","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/379107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=379107"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/379107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/379108"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=379107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=379107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=379107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}