{"id":379126,"date":"2026-05-12T20:32:16","date_gmt":"2026-05-12T20:32:16","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/379126\/"},"modified":"2026-05-12T20:32:16","modified_gmt":"2026-05-12T20:32:16","slug":"eurovisao-2026-o-video-da-atuacao-dos-bandidos-do-cante-com-rosa-na-primeira-semifinal-de-viena","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/379126\/","title":{"rendered":"Eurovis\u00e3o 2026: o v\u00eddeo da atua\u00e7\u00e3o dos Bandidos do Cante com \u2018Rosa\u2019 na primeira semifinal de Viena"},"content":{"rendered":"<p>Os bejenses Bandidos do Cante apresentaram-se esta ter\u00e7a-feira <a href=\"https:\/\/expresso.pt\/blitz\/noticias\/2026-05-11-eurovisao-2026-tudo-sobre-a-semifinal-em-que-portugal-concorre-com-israel-e-as-hipoteses-dos-bandidos-do-cante-7ab0f462?utm_source=expresso&amp;utm_medium=category&amp;utm_campaign=WEB&amp;utm_content=\/blitz\/noticias\/2026-05-11-eurovisao-2026-tudo-sobre-a-semifinal-em-que-portugal-concorre-com-israel-e-as-hipoteses-dos-bandidos-do-cante-7ab0f462\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">na primeira semifinal do festival da Eurovis\u00e3o<\/a>, no Wiener Stadthalle, em Viena, capital da \u00c1ustria.<\/p>\n<p>Com a can\u00e7\u00e3o \u2018Rosa\u2019, vencedora em mar\u00e7o do Festival RTP da Can\u00e7\u00e3o, Portugal luta por um lugar na final de s\u00e1bado, precisando de ficar entre as 10 primeiras classificadas das 15 concorrentes desta eliminat\u00f3ria. (It\u00e1lia e Alemanha tamb\u00e9m se apresentar\u00e3o, apresentando-se nesta semifinal 17 can\u00e7\u00f5es, mas j\u00e1 est\u00e3o apuradas para a final por se tratarem \u2018Big 5\u2019, pa\u00edses que mais contribuem financeiramente para o evento.)<\/p>\n<p>Veja a interpreta\u00e7\u00e3o da can\u00e7\u00e3o portuguesa nesta semifinal em v\u00eddeo e imagens (logo que dispon\u00edveis):<\/p>\n<p> Previous<img decoding=\"async\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/05\/2026-05-12-bandidos-do-cante-59e33801.webp\" alt=\"Bandidos do Cante na primeira semifinal do Festival da Eurovis\u00e3o, em Viena, 12 de maio de 2026\"\/><\/p>\n<p>Bandidos do Cante na primeira semifinal do Festival da Eurovis\u00e3o, em Viena, 12 de maio de 2026<\/p>\n<p>Getty Images<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/pt\/wp-content\/uploads\/2026\/05\/2026-05-12-bandidos-do-cante-59e33801.webp\" alt=\"Bandidos do Cante na primeira semifinal do Festival da Eurovis\u00e3o, em Viena, 12 de maio de 2026\"\/><\/p>\n<p>Bandidos do Cante na primeira semifinal do Festival da Eurovis\u00e3o, em Viena, 12 de maio de 2026<\/p>\n<p>Getty Images<\/p>\n<p> Next<\/p>\n<p>Se ficar entre as 10 primeiras, a can\u00e7\u00e3o portuguesa voltar\u00e1 a ouvir-se no mesmo palco no pr\u00f3ximo s\u00e1bado, dia 16, na final do certame, onde se juntar\u00e3o os temas apurados na segunda semifinal, a ter lugar quinta-feira, dia 14.<\/p>\n","protected":false},"excerpt":{"rendered":"Os bejenses Bandidos do Cante apresentaram-se esta ter\u00e7a-feira na primeira semifinal do festival da Eurovis\u00e3o, no Wiener Stadthalle,&hellip;\n","protected":false},"author":2,"featured_media":379127,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142],"tags":[114,115,32,33,151],"class_list":{"0":"post-379126","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-entertainment","9":"tag-entretenimento","10":"tag-portugal","11":"tag-pt","12":"tag-tv"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116563512588035885","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/379126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=379126"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/379126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/379127"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=379126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=379126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=379126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}