{"id":379297,"date":"2026-05-12T23:08:14","date_gmt":"2026-05-12T23:08:14","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/379297\/"},"modified":"2026-05-12T23:08:14","modified_gmt":"2026-05-12T23:08:14","slug":"nota-de-condolencias-site-oficial-do-sporting-clube-de-portugal-3","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/379297\/","title":{"rendered":"Nota de condol\u00eancias | Site oficial do Sporting Clube de Portugal"},"content":{"rendered":"<p class=\"lede content__lede\">\n\t\t\t\t\t\t\t\t\t\t\tPedro Feist\t\t\t\t\t\t\t\t\t\t<\/p>\n<p>O Sporting Clube de Portugal manifesta o seu profundo pesar pelo falecimento de Pedro Feist, que partiu esta ter\u00e7a-feira aos 90 anos de idade.<\/p>\n<p>Antigo atleta do emblema de Alvalade, onde chegou em 1960, foi um importante nome do andebol verde e branco. Representou os Le\u00f5es durante cerca de uma d\u00e9cada, tendo conquistado seis Campeonatos Nacionais e oito Regionais na variante de sete e ainda tr\u00eas Campeonatos Nacionais e cinco Regionais no andebol de 11.<\/p>\n<p>Em 1966\/1967, foi treinador-jogador e levou a equipa \u00e0 conquista do t\u00edtulo com dez vit\u00f3rias nos dez encontros realizados, o que o levou a ser distinguido com o Pr\u00e9mio Stromp na categoria T\u00e9cnico Amador em 1967. Vestiu, ainda, a camisola da Selec\u00e7\u00e3o Nacional de andebol.<\/p>\n<p>Aos familiares e amigos, o Sporting CP endere\u00e7a as mais sentidas condol\u00eancias, n\u00e3o deixando de enaltecer e agradecer os anos de esfor\u00e7o e dedica\u00e7\u00e3o ao Clube.<\/p>\n","protected":false},"excerpt":{"rendered":"Pedro Feist O Sporting Clube de Portugal manifesta o seu profundo pesar pelo falecimento de Pedro Feist, que&hellip;\n","protected":false},"author":2,"featured_media":379298,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[27,28,15,16,14,25,26,21,22,12,13,19,20,32,23,24,33,17,18,29,30,31],"class_list":{"0":"post-379297","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-portugal","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-featured-news","11":"tag-featurednews","12":"tag-headlines","13":"tag-latest-news","14":"tag-latestnews","15":"tag-main-news","16":"tag-mainnews","17":"tag-news","18":"tag-noticias","19":"tag-noticias-principais","20":"tag-noticiasprincipais","21":"tag-portugal","22":"tag-principais-noticias","23":"tag-principaisnoticias","24":"tag-pt","25":"tag-top-stories","26":"tag-topstories","27":"tag-ultimas","28":"tag-ultimas-noticias","29":"tag-ultimasnoticias"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116564125811498094","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/379297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=379297"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/379297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/379298"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=379297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=379297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=379297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}