{"id":379612,"date":"2026-05-13T09:12:13","date_gmt":"2026-05-13T09:12:13","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/379612\/"},"modified":"2026-05-13T09:12:13","modified_gmt":"2026-05-13T09:12:13","slug":"the-white-lotus-revela-3-novos-nomes-que-se-juntam-ao-elenco-da-quarta-temporada-nit","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/379612\/","title":{"rendered":"\u201cThe White Lotus\u201d revela 3 novos nomes que se juntam ao elenco da quarta temporada \u2014 NiT"},"content":{"rendered":"<p>A quarta temporada de \u201cThe White Lotus\u201d ainda est\u00e1 longe de estrear (possivelmente ser\u00e1 no in\u00edcio de 2027), mas a cada not\u00edcia que sai sobre a produ\u00e7\u00e3o, os f\u00e3s ficam mais entusiasmados. Depois de confirmar o cen\u00e1rio, a HBO Max tem vindo a revelar os nomes que v\u00e3o fazer parte do elenco, onde n\u00e3o faltam nomes de peso.\u00a0<\/p>\n<p><strong> Esta segunda-feira, 11 de maio, foram anunciados mais tr\u00eas refor\u00e7os: Ben Kingsley, Max Minghella e Pekka Strang juntam-se \u00e0 nova fase da s\u00e9rie, que desta vez se passa na Riviera Francesa.\u00a0<\/strong><\/p>\n<p>A plataforma de streaming revela tamb\u00e9m que este dever\u00e1 ser o \u00faltimo grande an\u00fancio de casting. A nova temporada vai decorrer durante o Festival de Cannes e acompanhar v\u00e1rios h\u00f3spedes e funcion\u00e1rios de hot\u00e9is de luxo ao longo de uma semana marcada por rivalidades, egos e muito caos. <\/p>\n<p>A narrativa da <a href=\"https:\/\/www.imdb.com\/title\/tt13406094\/?ref_=nv_sr_srsg_0_tt_8_nm_0_in_0_q_the%20white%20lotus\" target=\"_blank\" rel=\"nofollow noopener\">quarta<\/a> temporada dever\u00e1 centrar-se em duas equipas rivais da ind\u00fastria do cinema: uma instalada num hotel luxuoso junto \u00e0 Croisette, a avenida mais famosa de Cannes, e outra num ref\u00fagio exclusivo nas colinas da C\u00f4te d\u2019Azur. Os novos epis\u00f3dios tamb\u00e9m dever\u00e3o satirizar o servi\u00e7o ao cliente franc\u00eas, um dos elementos que Mike White, criador da s\u00e9rie, quer explorar nesta nova fase.<\/p>\n<p>Ben Kingsley, vencedor do \u00d3scar de Melhor Ator por \u201cGandhi\u201d (1982), Max Minghella, conhecido pela participa\u00e7\u00e3o em s\u00e9ries como \u201cThe Handmaid\u2019s Tale\u201d e \u201cIndustry\u201d e Pekka Strang, ator finland\u00eas de \u201cTom of Finland\u201d (2017), ter\u00e3o pap\u00e9is de destaque ao longo da nova temporada.<\/p>\n<p>Os tr\u00eas juntam-se a um elenco que j\u00e1 inclu\u00eda Vincent Cassel, Steve Coogan, Laura Dern, Kumail Nanjiani, Chris Messina, AJ Michalka, Nadia Tereszkiewicz e Alexander Ludwig, entre outros. O elenco secund\u00e1rio conta ainda com nomes como Chloe Bennet, Heather Graham, Rosie Perez, Sandra Bernhard e Max Greenfield.<\/p>\n<p>Como a NiT j\u00e1 lhe <a href=\"https:\/\/www.nit.pt\/cultura\/televisao\/ja-sabemos-quem-vai-substituir-helena-bonham-carter-em-the-white-lotus\" rel=\"nofollow noopener\" target=\"_blank\">contou<\/a>, Laura Dern entrou recentemente para a s\u00e9rie depois da sa\u00edda inesperada de Helena Bonham Carter, ap\u00f3s o in\u00edcio das grava\u00e7\u00f5es a 15 de abril. Segundo fontes ligadas \u00e0 produ\u00e7\u00e3o, citadas anteriormente pela HBO Max, a personagem atribu\u00edda \u00e0 atriz brit\u00e2nica \u201cn\u00e3o estava a resultar no contexto das grava\u00e7\u00f5es\u201d.<\/p>\n<p>A nova temporada vai ser filmada entre Cannes, Saint-Tropez, M\u00f3naco e Paris. Entre os cen\u00e1rios escolhidos est\u00e3o o H\u00f4tel Martinez, que ser\u00e1 transformado no fict\u00edcio White Lotus Cannes, e o Airelles Ch\u00e2teau de la Messardi\u00e8re, em Saint-Tropez.<\/p>\n<p>Carregue na galeria para conhecer algumas das s\u00e9ries e temporadas que chegam este m\u00eas ao streaming.<\/p>\n","protected":false},"excerpt":{"rendered":"A quarta temporada de \u201cThe White Lotus\u201d ainda est\u00e1 longe de estrear (possivelmente ser\u00e1 no in\u00edcio de 2027),&hellip;\n","protected":false},"author":2,"featured_media":379613,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142],"tags":[114,115,32,33,151],"class_list":{"0":"post-379612","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-entertainment","9":"tag-entretenimento","10":"tag-portugal","11":"tag-pt","12":"tag-tv"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116566500790523236","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/379612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=379612"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/379612\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/379613"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=379612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=379612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=379612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}