{"id":379620,"date":"2026-05-13T09:21:15","date_gmt":"2026-05-13T09:21:15","guid":{"rendered":"https:\/\/www.europesays.com\/pt\/379620\/"},"modified":"2026-05-13T09:21:15","modified_gmt":"2026-05-13T09:21:15","slug":"morreu-pedro-feist-antigo-vereador-em-lisboa-politica","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/pt\/379620\/","title":{"rendered":"Morreu Pedro Feist, antigo vereador em Lisboa &#8211; Pol\u00edtica"},"content":{"rendered":"<p>&#13;<br \/>\n                        O Correio da Manh\u00e3 oferece nos seus artigos um espa\u00e7o de coment\u00e1rio, que considera essencial para reflex\u00e3o, debate e livre veicula\u00e7\u00e3o de opini\u00f5es e ideias e apela aos Leitores que sigam as regras b\u00e1sicas de uma conviv\u00eancia s\u00e3 e de respeito pelos outros, promovendo um ambiente de respeito e fair-play.&#13;\n                    <\/p>\n<p>&#13;<br \/>\n                        S\u00f3 ap\u00f3s a atenta leitura das regras abaixo e posterior aceita\u00e7\u00e3o expressa ser\u00e1 poss\u00edvel efectuar coment\u00e1rios \u00e0s not\u00edcias publicados no Correio da Manh\u00e3.&#13;\n                    <\/p>\n<p>&#13;<br \/>\n                        A possibilidade de efetuar coment\u00e1rios neste espa\u00e7o est\u00e1 limitada a Leitores registados e Leitores assinantes do Correio da Manh\u00e3 Premium (\u201cLeitor\u201d).&#13;\n                    <\/p>\n<p>&#13;<br \/>\n                        Ao comentar, o Leitor est\u00e1 a declarar que \u00e9 o \u00fanico e exclusivo titular dos direitos associados a esse conte\u00fado, e como tal \u00e9 o \u00fanico e exclusivo respons\u00e1vel por esses mesmos conte\u00fados, e que autoriza o Correio da Manh\u00e3 a difundir o referido conte\u00fado, para todos e em quaisquer suportes dispon\u00edveis.&#13;\n                    <\/p>\n<p>&#13;<br \/>\n                        O Leitor permanecer\u00e1 o propriet\u00e1rio dos conte\u00fados que submeta ao Correio da Manh\u00e3 e ao enviar tais conte\u00fados concede ao Correio da Manh\u00e3 uma licen\u00e7a, gratuita, irrevog\u00e1vel, transmiss\u00edvel, exclusiva e perp\u00e9tua para a utiliza\u00e7\u00e3o dos referidos conte\u00fados, em qualquer suporte ou formato atualmente existente no mercado ou que venha a surgir.&#13;\n                    <\/p>\n<p>&#13;<br \/>\n                        O Leitor obriga-se a garantir que os conte\u00fados que submete nos espa\u00e7os de coment\u00e1rios do Correio da Manh\u00e3 n\u00e3o s\u00e3o obscenos, ofensivos ou geradores de responsabilidade civil ou criminal e n\u00e3o violam o direito de propriedade intelectual de terceiros. O Leitor compromete-se, nomeadamente, a n\u00e3o utilizar os espa\u00e7os de coment\u00e1rios do Correio da Manh\u00e3 para: (i) fins comerciais, nomeadamente, difundindo mensagens publicit\u00e1rias nos coment\u00e1rios ou em outros espa\u00e7os, fora daqueles especificamente destinados \u00e0 publicidade contratada nos termos adequados; (ii) difundir conte\u00fados de \u00f3dio, racismo, xenofobia ou discrimina\u00e7\u00e3o ou que, de um modo geral, incentivem a viol\u00eancia ou a pr\u00e1tica de atos il\u00edcitos; (iii) difundir conte\u00fados que, de forma direta ou indireta, expl\u00edcita ou impl\u00edcita, tenham como objetivo, finalidade, resultado, consequ\u00eancia ou inten\u00e7\u00e3o, humilhar, denegrir ou atingir o bom-nome e reputa\u00e7\u00e3o de terceiros.&#13;\n                    <\/p>\n<p>&#13;<br \/>\n                        O Leitor reconhece expressamente que \u00e9 exclusivamente respons\u00e1vel pelo pagamento de quaisquer coimas, custas, encargos, multas, penaliza\u00e7\u00f5es, indemniza\u00e7\u00f5es ou outros montantes que advenham da publica\u00e7\u00e3o dos seus coment\u00e1rios nos espa\u00e7os de coment\u00e1rios do Correio da Manh\u00e3.&#13;\n                    <\/p>\n<p>&#13;<br \/>\n                        O Leitor reconhece que o Correio da Manh\u00e3 n\u00e3o est\u00e1 obrigado a monitorizar, editar ou pr\u00e9-visualizar os conte\u00fados ou coment\u00e1rios que s\u00e3o partilhados pelos Leitores nos seus espa\u00e7os de coment\u00e1rio. No entanto, a reda\u00e7\u00e3o do Correio da Manh\u00e3, reserva-se o direito de fazer uma pr\u00e9-avalia\u00e7\u00e3o e n\u00e3o publicar coment\u00e1rios que n\u00e3o respeitem as presentes Regras.&#13;\n                    <\/p>\n<p>&#13;<br \/>\n                        Todos os coment\u00e1rios ou conte\u00fados que venham a ser partilhados pelo Leitor nos espa\u00e7os de coment\u00e1rios do Correio da Manh\u00e3 constituem a opini\u00e3o exclusiva e \u00fanica do seu autor, que s\u00f3 a este vincula e n\u00e3o refletem a opini\u00e3o ou posi\u00e7\u00e3o do Correio da Manh\u00e3 ou de terceiros. O facto de um conte\u00fado ter sido difundido por um Leitor nos espa\u00e7os de coment\u00e1rios do Correio da Manh\u00e3 n\u00e3o pressup\u00f5e, de forma direta ou indireta, expl\u00edcita ou impl\u00edcita, que o Correio da Manh\u00e3 teve qualquer conhecimento pr\u00e9vio do mesmo e muito menos que concorde, valide ou suporte o seu conte\u00fado.&#13;\n                    <\/p>\n<p>                    Comportamento<\/p>\n<p>&#13;<br \/>\n                        O Correio da Manh\u00e3 pode, em caso de viola\u00e7\u00e3o das presentes Regras, suspender por tempo determinado, indeterminado ou mesmo proibir permanentemente a possibilidade de comentar, independentemente de ser assinante do Correio da Manh\u00e3 Premium ou da sua classifica\u00e7\u00e3o.&#13;\n                    <\/p>\n<p>&#13;<br \/>\n                        O Correio da Manh\u00e3 reserva-se ao direito de apagar de imediato e sem qualquer aviso ou notifica\u00e7\u00e3o pr\u00e9via os coment\u00e1rios dos Leitores que n\u00e3o cumpram estas regras.&#13;\n                    <\/p>\n<p>&#13;<br \/>\n                        O Correio da Manh\u00e3 ocultar\u00e1 de forma autom\u00e1tica todos os coment\u00e1rios uma semana ap\u00f3s a publica\u00e7\u00e3o dos mesmos.&#13;\n                    <\/p>\n","protected":false},"excerpt":{"rendered":"&#13; O Correio da Manh\u00e3 oferece nos seus artigos um espa\u00e7o de coment\u00e1rio, que considera essencial para reflex\u00e3o,&hellip;\n","protected":false},"author":2,"featured_media":379621,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[27,28,42900,15,16,14,25,26,797,21,22,12,13,19,20,63681,32,14937,1963,23,24,33,17,18,29,30,31,10769,28332],"class_list":{"0":"post-379620","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-portugal","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-cds-partido-popular","11":"tag-featured-news","12":"tag-featurednews","13":"tag-headlines","14":"tag-latest-news","15":"tag-latestnews","16":"tag-lisboa","17":"tag-main-news","18":"tag-mainnews","19":"tag-news","20":"tag-noticias","21":"tag-noticias-principais","22":"tag-noticiasprincipais","23":"tag-pedro-feist","24":"tag-portugal","25":"tag-presidencia-da-republica","26":"tag-presidente-da-republica","27":"tag-principais-noticias","28":"tag-principaisnoticias","29":"tag-pt","30":"tag-top-stories","31":"tag-topstories","32":"tag-ultimas","33":"tag-ultimas-noticias","34":"tag-ultimasnoticias","35":"tag-vereador","36":"tag-vereadora"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@pt\/116566536207183307","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/379620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/comments?post=379620"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/posts\/379620\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media\/379621"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/media?parent=379620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/categories?post=379620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/pt\/wp-json\/wp\/v2\/tags?post=379620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}