{"id":6704,"date":"2025-09-29T13:27:07","date_gmt":"2025-09-29T13:27:07","guid":{"rendered":"https:\/\/www.europesays.com\/ro\/6704\/"},"modified":"2025-09-29T13:27:07","modified_gmt":"2025-09-29T13:27:07","slug":"google-a-lansat-oficial-in-romania-abonamentul-youtube-premium-lite-promite-mai-putine-reclame-si-cam-atat","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ro\/6704\/","title":{"rendered":"Google a lansat oficial \u00een Rom\u00e2nia abonamentul YouTube Premium Lite (promite mai pu\u0163ine reclame \u015fi cam at\u00e2t)"},"content":{"rendered":"<p>Google a lansat \u00een luna martie a acestui an abonamentul YouTube Premium Lite, unul care cost\u0103 destul de mult \u015fi nu ofer\u0103 mai nimic \u00een schimb.<\/p>\n<p>Conform informa\u0163iilor oficiale publicate de compania american\u0103, prin YouTube Premium Lite sunt scutite de reclame domenii precum jocuri, \u015ftiri, mod\u0103, frumuse\u0163e etc., \u00eens\u0103 categoriile care atrag grosul vizualiz\u0103rilor (clipurile muzicale, shorts-urile) vor continua s\u0103 primeasc\u0103 reclame (mai pu\u0163ine, este adev\u0103rat).<\/p>\n<p>\u00cen rest, YouTube Premium Lite nu ofer\u0103 acces la YouTube Music Premium, nu permite desc\u0103rcarea de con\u0163inut offline \u015fi nu permite redarea con\u0163inutului \u00een background. Pentru toate acestea exist\u0103 YouTube Premium cel clasic.<\/p>\n<p>Noul abonament YouTube Premium Lite a ajuns oficial \u015fi \u00een Rom\u00e2nia la un cost de 17 lei \/ lun\u0103, cu prima lun\u0103 de \u00eencercare gratuit\u0103. A\u015fa cum am spus \u015fi mai sus, categoriile Muzic\u0103 \u015fi Videoclipuri scurte NU sunt scutite de reclame, ci vor avea mai pu\u0163ine (ce \u00eenseamna asta, doar Google \u015ftie).<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" width=\"526\" height=\"514\" src=\"https:\/\/www.europesays.com\/ro\/wp-content\/uploads\/2025\/09\/YouTube-Premium-Lite.png\" alt=\"\" class=\"wp-image-366905\"  \/><\/p>\n<p>Altceva nu primi\u0163i \u00een rest. Merit\u0103 sau nu YouTube Premium Lite cei 17 lei \/ lun\u0103?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"816\" src=\"https:\/\/www.europesays.com\/ro\/wp-content\/uploads\/2025\/09\/youtube.png\" alt=\"\" class=\"wp-image-366906\"  \/><\/p>\n","protected":false},"excerpt":{"rendered":"Google a lansat \u00een luna martie a acestui an abonamentul YouTube Premium Lite, unul care cost\u0103 destul de&hellip;\n","protected":false},"author":2,"featured_media":6705,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[4207,85,4208,41,40,38,39,141,124,4209,4210,4211],"class_list":{"0":"post-6704","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tehnologie","8":"tag-abonament-youtube-premium-lite","9":"tag-google","10":"tag-pret-youtube-premium-lite","11":"tag-ro","12":"tag-romana","13":"tag-romania","14":"tag-romanian","15":"tag-technology","16":"tag-tehnologie","17":"tag-youtube","18":"tag-youtube-premium-lite","19":"tag-youtube-premium-lite-in-romania"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/posts\/6704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/comments?post=6704"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/posts\/6704\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/media\/6705"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/media?parent=6704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/categories?post=6704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/tags?post=6704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}