{"id":80399,"date":"2026-01-02T06:38:10","date_gmt":"2026-01-02T06:38:10","guid":{"rendered":"https:\/\/www.europesays.com\/ro\/80399\/"},"modified":"2026-01-02T06:38:10","modified_gmt":"2026-01-02T06:38:10","slug":"in-cap-unui-jucator-de-ai-lui-chivu-i-a-scazut-cota-de-la-40-de-milioane-la-22-de-milioane-de-euro","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ro\/80399\/","title":{"rendered":"\u00cen cap! Unui juc\u0103tor de-ai lui Chivu i-a sc\u0103zut cota de la 40 de milioane la 22 de milioane de euro"},"content":{"rendered":"\n<ul class=\"bullets\">\n<li>\n<p>Serie A: Cagliari &#8211; Milan, vineri, 21:45, DGS 1<\/p>\n<\/li>\n<li>\n<p>La Liga: Rayo &#8211; Getafe, vineri, 22:00, DGS 2<\/p>\n<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.digisport.ro\/fotbal\/serie-a\/inter-a-luat-decizia-ce-se-intampla-cu-jucatorul-aflat-pe-lista-neagra-a-lui-chivu-4007469\" target=\"_blank\" rel=\"noopener nofollow\" data-skip-linkfix=\"1\">Interul lui Cristi Chivu (45 de ani)<\/a> \u0219i Juventus domin\u0103 un clasament deloc onorant, \u00een timp ce AS Roma pl\u0103te\u0219te pentru lipsa de constan\u021b\u0103 a unor juc\u0103tori importan\u021bi.<\/p>\n<p>Lui Barella i-a sc\u0103zut cota de la 80 la 65 de milioane de euro, iar lui Akanji de la 40 la 22 de milioane de euro<\/p>\n<p>\u00cen topul juc\u0103torilor din Serie A care au pierdut cel mai mult din valoare \u00een 2025 se reg\u0103sesc doi fotbali\u0219ti de la Inter, un detaliu care nu poate fi trecut cu vederea prea u\u0219or de Cristi Chivu.<\/p>\n<p>Pe locul 3 se afl\u0103 Manuel Akanji, a c\u0103rui cot\u0103 a sc\u0103zut drastic, de la 40 la 22 de milioane de euro. Totu\u0219i, \u00een cazul funda\u0219ului, a contat \u00een special sezonul complicat avut la Manchester City, clubul care l-a \u00eemprumutat, cu evolu\u021bii sub a\u0219tept\u0103ri, care i-au afectat serios statutul pe pia\u021ba transferurilor.<\/p>\n<p>Tot de la Inter vine \u0219i Nicolo Barella, aflat pe pozi\u021bia a 5-a, cu o sc\u0103dere de 15 milioane de euro, de la 80 la 65 de milioane. De\u0219i mijloca\u0219ul italian a avut numeroase presta\u021bii de top, verdictul pie\u021bei a fost influen\u021bat decisiv de lipsa trofeelor \u00een Italia \u0219i de <a href=\"https:\/\/www.digisport.ro\/fotbal\/champions-league\/psg-inter-5-0-parizienii-i-au-facut-ko-pe-nerazzurri-si-au-castigat-primul-trofeu-champions-league-din-istorie-3617377\" target=\"_blank\" rel=\"noopener nofollow\" data-skip-linkfix=\"1\">finala de Champions League pierdut\u0103 categoric, scor 0-5 cu PSG<\/a>.<\/p>\n<ul>\n<li>20 de meciuri a jucat Manuel Akanji \u00een actualul sezon la \u201dNerazzurri\u201d.<\/li>\n<li>21 de apari\u021bii a avut Nicolo Barella pentru Inter \u00een stagiunea curent\u0103. A marcat un gol \u0219i a oferit 5 pase de gol.<\/li>\n<\/ul>\n<p>Juventus domin\u0103 \u00een clasamentul juc\u0103torilor care au pierdut cel mai mult din valoare <a href=\"https:\/\/www.digisport.ro\/special\/aboneaza-te-la-canalul-de-whatsapp-digi-sport-si-afla-primul-cele-mai-importante-stiri-ale-zilei-din-sport-2686297\" target=\"_blank\" rel=\"noopener nofollow\"> <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/ro\/wp-content\/uploads\/2025\/12\/1766681530_23_YXNoPTlmMDRmYWU3ZWMyYWQxMjEyMDczYWNmMWNkYTQ4ZDk5.jpg\"\/> <\/a><\/p>\n<p>Pe primele dou\u0103 pozi\u021bii se afl\u0103 doi juc\u0103tori de la Juventus. Dusan Vlahovic este lider negativ, cu o sc\u0103dere uria\u0219\u0103: de la 60 la 35 de milioane de euro. Sezonul modest, lipsa de constan\u021b\u0103 \u0219i o echip\u0103 Juventus f\u0103r\u0103 obiective majore au tras \u00een jos cota atacantului s\u00e2rb.<\/p>\n<p>Imediat dup\u0103 el vine Teun Koopmeiners, care a pierdut 20 de milioane \u0219i a ajuns de la 50 la 30 de milioane de euro. Tranzi\u021bia dificil\u0103 la Torino \u0219i rezultatele slabe ale echipei au afectat un juc\u0103tor considerat nu demult printre cei mai comple\u021bi mijloca\u0219i din Serie A.<\/p>\n<p>Pe locul 4 \u00een acest clasament se afl\u0103 Leon Bailey, acum la Roma, cu o sc\u0103dere de 16 milioane de euro, de la 38 la 22. Declinul extremei jamaicane a \u00eenceput \u00eenc\u0103 din perioada petrecut\u0103 la Aston Villa \u0219i s-a accentuat \u00een ultimul an.<\/p>\n<p>Dup\u0103 ce atinsese aproape 42 de milioane \u00een prim\u0103vara lui 2024, Bailey a cobor\u00e2t constant p\u00e2n\u0103 la valoarea actual\u0103.<\/p>\n<p>Cite\u0219te \u0219i:<\/p>\n<p>Clasamentul din Serie A  <img decoding=\"async\" data-skip-htmlfix=\"1\" src=\"https:\/\/www.europesays.com\/ro\/wp-content\/uploads\/2025\/12\/ZyZ3PTU5MCZoYXNoPTI2MDVhM2IxNTZlYTVlZjE3MjdkNjY3M2NjMTExZmM0.thumb.jpg\" alt=\"clasamentitaliaetapa17\"\/>   Clasamentul din Serie A \/ Foto: digisport.ro  VIDEO cu rezumatul meciului Atalanta &#8211; Inter 0-1. Manuel Akanji \u0219i Nicolo Barella au fost titulari   <\/p>\n<p>  Etichete:  <a href=\"https:\/\/www.digisport.ro\/eticheta\/inter\" rel=\"nofollow noopener\" target=\"_blank\">inter<\/a> , <a href=\"https:\/\/www.digisport.ro\/eticheta\/cristi-chivu\" rel=\"nofollow noopener\" target=\"_blank\">cristi chivu<\/a> , <a href=\"https:\/\/www.digisport.ro\/eticheta\/nicolo-barella\" rel=\"nofollow noopener\" target=\"_blank\">nicolo barella<\/a> , <a href=\"https:\/\/www.digisport.ro\/eticheta\/manuel-akanji\" rel=\"nofollow noopener\" target=\"_blank\">manuel akanji<\/a> , <a href=\"https:\/\/www.digisport.ro\/eticheta\/cote-jucatori-inter\" rel=\"nofollow noopener\" target=\"_blank\">cote jucatori inter<\/a>   <\/p>\n<p>Urm\u0103re\u0219te \u0219tirile digisport.ro \u0219i pe <a href=\"https:\/\/news.google.com\/publications\/CAAiENr1L9HFNMG5hpp5zTfVtpsqFAgKIhDa9S_RxTTBuYaaec031bab?ceid=RO:ro&amp;oc=3\" target=\"_blank\" rel=\"external nofollow noopener\">Google News<\/a><\/p>\n<p>   Noua Aplica\u0163ie Digi Sport poate fi desc\u0103rcat\u0103 din   <\/p>\n","protected":false},"excerpt":{"rendered":"Serie A: Cagliari &#8211; Milan, vineri, 21:45, DGS 1 La Liga: Rayo &#8211; Getafe, vineri, 22:00, DGS 2&hellip;\n","protected":false},"author":2,"featured_media":69438,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[32,33,31,27934,544,36,37,27,545,34,35,14778,25,27933,41,40,38,39,26,28,29,30],"class_list":{"0":"post-80399","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-titluri","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-cele-mai-populare-subiecte","11":"tag-cote-jucatori-inter","12":"tag-cristi-chivu","13":"tag-featured-news","14":"tag-featurednews","15":"tag-headlines","16":"tag-inter","17":"tag-latest-news","18":"tag-latestnews","19":"tag-manuel-akanji","20":"tag-news","21":"tag-nicolo-barella","22":"tag-ro","23":"tag-romana","24":"tag-romania","25":"tag-romanian","26":"tag-stiri","27":"tag-titluri","28":"tag-top-stories","29":"tag-topstories"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ro\/115824132513813226","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/posts\/80399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/comments?post=80399"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/posts\/80399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/media\/69438"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/media?parent=80399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/categories?post=80399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ro\/wp-json\/wp\/v2\/tags?post=80399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}