{"id":54563,"date":"2026-04-27T06:01:10","date_gmt":"2026-04-27T06:01:10","guid":{"rendered":"https:\/\/www.europesays.com\/sk\/54563\/"},"modified":"2026-04-27T06:01:10","modified_gmt":"2026-04-27T06:01:10","slug":"obrovska-bitka-na-oddeleni-padali-rany-bolo-aj-skrtenie","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/sk\/54563\/","title":{"rendered":"Obrovsk\u00e1 bitka na oddelen\u00ed! Padali rany, bolo aj \u0161krtenie"},"content":{"rendered":"<p>\tPoplach v nemocnici: Obrovsk\u00e1 bitka na oddelen\u00ed! Padali rany, bolo aj \u0161krtenie<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n<p>\t\t\t&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n<p>    &#13;<br \/>\n    &#13;<br \/>\n    wpDiscuz<\/p>\n<p>Insert<\/p>\n","protected":false},"excerpt":{"rendered":"Poplach v nemocnici: Obrovsk\u00e1 bitka na oddelen\u00ed! Padali rany, bolo aj \u0161krtenie &#13; &#13; &#13; &#13; &#13; &#13;&hellip;\n","protected":false},"author":2,"featured_media":54564,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[33,43,40,42,36,50,1492,49,48],"class_list":{"0":"post-54563","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-svet","8":"tag-news","9":"tag-sk","10":"tag-slovak","11":"tag-slovencina","12":"tag-spravy","13":"tag-svet","14":"tag-top2","15":"tag-world","16":"tag-world-news"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@sk\/116475152567834887","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/sk\/wp-json\/wp\/v2\/posts\/54563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/sk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/sk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/sk\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/sk\/wp-json\/wp\/v2\/comments?post=54563"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/sk\/wp-json\/wp\/v2\/posts\/54563\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/sk\/wp-json\/wp\/v2\/media\/54564"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/sk\/wp-json\/wp\/v2\/media?parent=54563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/sk\/wp-json\/wp\/v2\/categories?post=54563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/sk\/wp-json\/wp\/v2\/tags?post=54563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}