{"id":111822,"count":1,"description":"","link":"https:\/\/www.europesays.com\/uk\/tag\/nasser-hussain-ben-stokes-jofra-archer-relationship\/","name":"Nasser Hussain Ben Stokes Jofra Archer relationship","slug":"nasser-hussain-ben-stokes-jofra-archer-relationship","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/tags\/111822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/posts?tags=111822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}