{"id":118665,"count":1,"description":"","link":"https:\/\/www.europesays.com\/uk\/tag\/government-revenue\/","name":"government revenue","slug":"government-revenue","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/tags\/118665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/posts?tags=118665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}