{"id":144357,"count":1,"description":"","link":"https:\/\/www.europesays.com\/uk\/tag\/meghan-markle-engagement-ring\/","name":"meghan markle engagement ring","slug":"meghan-markle-engagement-ring","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/tags\/144357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/posts?tags=144357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}