{"id":183834,"count":1,"description":"","link":"https:\/\/www.europesays.com\/uk\/tag\/heart-rate-metrics\/","name":"heart rate metrics","slug":"heart-rate-metrics","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/tags\/183834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/posts?tags=183834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}