{"id":43425,"count":1,"description":"","link":"https:\/\/www.europesays.com\/uk\/tag\/bubbies-bagels\/","name":"bubbie\u2019s bagels","slug":"bubbies-bagels","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/tags\/43425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/uk\/wp-json\/wp\/v2\/posts?tags=43425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}