{"id":106211,"count":1,"description":"","link":"https:\/\/www.europesays.com\/us\/tag\/ustr-jamieson-greer\/","name":"USTR Jamieson Greer","slug":"ustr-jamieson-greer","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/us\/wp-json\/wp\/v2\/tags\/106211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/us\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/us\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/us\/wp-json\/wp\/v2\/posts?tags=106211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}