{"id":158370,"count":1,"description":"","link":"https:\/\/www.europesays.com\/us\/tag\/alabama-vs-tennessee-time\/","name":"Alabama vs. Tennessee time","slug":"alabama-vs-tennessee-time","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/us\/wp-json\/wp\/v2\/tags\/158370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/us\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/us\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/us\/wp-json\/wp\/v2\/posts?tags=158370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}